{"id":9999,"date":"2025-06-19T10:27:15","date_gmt":"2025-06-19T15:27:15","guid":{"rendered":"https:\/\/el-perico.com\/?p=9999"},"modified":"2025-06-19T10:30:23","modified_gmt":"2025-06-19T15:30:23","slug":"hola-nebraska-omaha-celebra-un-desfile-historico-de-juneteenth-con-su-primer-alcalde-afroamericano-electo","status":"publish","type":"post","link":"https:\/\/el-perico.com\/es\/hola-nebraska-omaha-celebra-un-desfile-historico-de-juneteenth-con-su-primer-alcalde-afroamericano-electo\/","title":{"rendered":"Hola Nebraska Omaha celebra un desfile hist\u00f3rico de Juneteenth con su primer alcalde afroamericano electo"},"content":{"rendered":"\n<p>Voluntarios prepararon la hist\u00f3rica calle 24 de Omaha, Nebraska, para el desfile de Juneteenth de este a\u00f1o. Frankie Jean Williams, presidenta del comit\u00e9 de celebraci\u00f3n de Juneteenth de la NAACP en Omaha, esperaba con especial entusiasmo ver al primer alcalde afroamericano electo de la ciudad entre los participantes. Ewing asumi\u00f3 el cargo diez d\u00edas antes del feriado.<\/p>\n\n\n\n<p>\u201cEs un motivo de orgullo\u201d, expres\u00f3. \u201cEstaba pensando en el orden del desfile, y normalmente incluimos primero a los funcionarios estatales, luego a los del condado y finalmente a los locales. Es una oportunidad maravillosa para mostrar a los j\u00f3venes el valor de su voto\u201d.<\/p>\n\n\n\n<p>Williams quer\u00eda que el reci\u00e9n electo alcalde John Ewing Jr. se sentara en un convertible durante el desfile del 14 de junio, que se llev\u00f3 a cabo antes del feriado del 19 de junio. Pero sab\u00eda que probablemente \u00e9l preferir\u00eda caminar para interactuar con los residentes.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/el-perico.com\/wp-content\/uploads\/2025\/06\/NAACP.min-1200x1200-1-edited-1024x768.jpg\" alt=\"\" class=\"wp-image-9992\" srcset=\"https:\/\/el-perico.com\/wp-content\/uploads\/2025\/06\/NAACP.min-1200x1200-1-edited-1024x768.jpg 1024w, https:\/\/el-perico.com\/wp-content\/uploads\/2025\/06\/NAACP.min-1200x1200-1-edited-300x225.jpg 300w, https:\/\/el-perico.com\/wp-content\/uploads\/2025\/06\/NAACP.min-1200x1200-1-edited-768x576.jpg 768w, https:\/\/el-perico.com\/wp-content\/uploads\/2025\/06\/NAACP.min-1200x1200-1-edited-1200x900.jpg 1200w, https:\/\/el-perico.com\/wp-content\/uploads\/2025\/06\/NAACP.min-1200x1200-1-edited-800x600.jpg 800w, https:\/\/el-perico.com\/wp-content\/uploads\/2025\/06\/NAACP.min-1200x1200-1-edited-600x450.jpg 600w, https:\/\/el-perico.com\/wp-content\/uploads\/2025\/06\/NAACP.min-1200x1200-1-edited-400x300.jpg 400w, https:\/\/el-perico.com\/wp-content\/uploads\/2025\/06\/NAACP.min-1200x1200-1-edited-200x150.jpg 200w, https:\/\/el-perico.com\/wp-content\/uploads\/2025\/06\/NAACP.min-1200x1200-1-edited-780x585.jpg 780w, https:\/\/el-perico.com\/wp-content\/uploads\/2025\/06\/NAACP.min-1200x1200-1-edited.jpg 1422w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Frankie Jean Williams (left) and T. Michael Williams (no relation) pose for a photo inside the Omaha NAACP branch. (Photo by Kassidy Arena\/Nebraska Public Media News)<\/figcaption><\/figure>\n\n\n\n<p>\u201cVerlo sentado ah\u00ed en ese momento, estoy segura de que para mi generaci\u00f3n ser\u00e1 algo que conmueva hasta las l\u00e1grimas, porque hace a\u00f1os mucha gente jam\u00e1s habr\u00eda cre\u00eddo que esto podr\u00eda pasar\u201d, coment\u00f3.<\/p>\n\n\n\n<p><a href=\"https:\/\/www.npr.org\/2025\/05\/14\/nx-s1-5398327\/a-democrat-wins-in-red-state-nebraska-and-becomes-first-elected-black-mayor-of-omaha\">El dem\u00f3crata Ewing gan\u00f3 la elecci\u00f3n para alcalde<\/a> de la ciudad m\u00e1s grande de Nebraska, al derrotar a la republicana Jean Stothert, quien hab\u00eda ocupado el cargo durante 12 a\u00f1os. El presidente de la NAACP en Omaha, T. Michael Williams, dijo que esta celebraci\u00f3n representa \u201cun momento hist\u00f3rico\u201d, y que toda la ciudad \u2014no solo la comunidad afroamericana\u2014 est\u00e1 entusiasmada con el nuevo alcalde.<\/p>\n\n\n\n<p>\u201cEl estado de Nebraska y la ciudad de Omaha, sinceramente, no siempre han sido lugares acogedores para los afroamericanos. El hecho de que hace unos 20 a\u00f1os estuvimos cerca de tener un alcalde negro, pero no lo logramos, y que ahora s\u00ed lo tenemos, representa una gran oportunidad para avanzar como ciudad de manera m\u00e1s inclusiva\u201d, dijo.<\/p>\n\n\n\n<p>Ewing expres\u00f3 su entusiasmo por representar este a\u00f1o a la ciudad donde naci\u00f3 y creci\u00f3. El ex tesorero del condado, ahora alcalde, proviene del norte de Omaha, una \u00e1rea con una importante poblaci\u00f3n afroamericana.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignleft size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/el-perico.com\/wp-content\/uploads\/2025\/06\/John_1.min-800x800-1-768x1024.jpg\" alt=\"\" class=\"wp-image-9994\" srcset=\"https:\/\/el-perico.com\/wp-content\/uploads\/2025\/06\/John_1.min-800x800-1-768x1024.jpg 768w, https:\/\/el-perico.com\/wp-content\/uploads\/2025\/06\/John_1.min-800x800-1-225x300.jpg 225w, https:\/\/el-perico.com\/wp-content\/uploads\/2025\/06\/John_1.min-800x800-1-600x800.jpg 600w, https:\/\/el-perico.com\/wp-content\/uploads\/2025\/06\/John_1.min-800x800-1-450x600.jpg 450w, https:\/\/el-perico.com\/wp-content\/uploads\/2025\/06\/John_1.min-800x800-1-300x400.jpg 300w, https:\/\/el-perico.com\/wp-content\/uploads\/2025\/06\/John_1.min-800x800-1-150x200.jpg 150w, https:\/\/el-perico.com\/wp-content\/uploads\/2025\/06\/John_1.min-800x800-1-780x1039.jpg 780w, https:\/\/el-perico.com\/wp-content\/uploads\/2025\/06\/John_1.min-800x800-1-400x533.jpg 400w, https:\/\/el-perico.com\/wp-content\/uploads\/2025\/06\/John_1.min-800x800-1.jpg 800w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><figcaption class=\"wp-element-caption\">Mayor John Ewing Jr. walks in the parade, taking pictures with attendees. (Photo courtesy Erin Grace\/Mayor&#8217;s Office)<\/figcaption><\/figure>\n<\/div>\n\n\n<p>\u201cSi analizamos el significado de Juneteenth desde esa perspectiva y lo relacionamos con el hecho de que soy el primer alcalde negro en la historia de Omaha, esa conexi\u00f3n es muy simb\u00f3lica\u201d, se\u00f1al\u00f3. \u201cRefleja un avance significativo en nuestro pa\u00eds, y en esta ciudad en particular\u201d.<\/p>\n\n\n\n<p>Ewing dijo que su elecci\u00f3n ha revitalizado la celebraci\u00f3n de Juneteenth en Omaha y que cree que la ciudad puede convertirse en un ejemplo nacional al reconocer la historia estadounidense y fomentar un sentido de pertenencia para todos.<\/p>\n\n\n\n<p>\u201cEn lugar de huir de nuestra historia, en lugar de intentar borrar lo que realmente ocurri\u00f3 en Estados Unidos, debemos aceptarlo y aprender las lecciones que nos deja\u201d, dijo Ewing.<\/p>\n\n\n\n<p>Agreg\u00f3 que espera no ser solo un modelo a seguir para los ni\u00f1os que se parecen a \u00e9l, sino tambi\u00e9n para aquellos que no se parecen a \u00e9l, demostrando que una ciudad puede ser liderada por un hombre negro.<\/p>\n\n\n\n<p>\u201cPodemos seguir el ejemplo de muchas otras partes del pa\u00eds y vivir con enfrentamientos y enojo, lo que resulta improductivo, o podemos enfocarnos en c\u00f3mo podemos ser grandes juntos. Y esa es la \u00fanica forma en que Omaha alcanzar\u00e1 todo su potencial: si todos estamos unidos en esto\u201d, a\u00f1adi\u00f3.<\/p>\n\n\n\n<p>Sin embargo, parte de las tensiones a nivel nacional tambi\u00e9n se han reflejado en la celebraci\u00f3n de Omaha. Frankie Jean Williams coment\u00f3 que algunos patrocinadores que hab\u00edan apoyado en a\u00f1os anteriores se retiraron debido a los retrocesos impulsados por la administraci\u00f3n Trump en los programas de diversidad, equidad e inclusi\u00f3n (DEI, por sus siglas en ingl\u00e9s).<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/el-perico.com\/wp-content\/uploads\/2025\/06\/Calvin.min-1200x1200-1-1024x768.jpg\" alt=\"\" class=\"wp-image-9996\" srcset=\"https:\/\/el-perico.com\/wp-content\/uploads\/2025\/06\/Calvin.min-1200x1200-1-1024x768.jpg 1024w, https:\/\/el-perico.com\/wp-content\/uploads\/2025\/06\/Calvin.min-1200x1200-1-300x225.jpg 300w, https:\/\/el-perico.com\/wp-content\/uploads\/2025\/06\/Calvin.min-1200x1200-1-768x576.jpg 768w, https:\/\/el-perico.com\/wp-content\/uploads\/2025\/06\/Calvin.min-1200x1200-1-1536x1152.jpg 1536w, https:\/\/el-perico.com\/wp-content\/uploads\/2025\/06\/Calvin.min-1200x1200-1-1200x900.jpg 1200w, https:\/\/el-perico.com\/wp-content\/uploads\/2025\/06\/Calvin.min-1200x1200-1-800x600.jpg 800w, https:\/\/el-perico.com\/wp-content\/uploads\/2025\/06\/Calvin.min-1200x1200-1-600x450.jpg 600w, https:\/\/el-perico.com\/wp-content\/uploads\/2025\/06\/Calvin.min-1200x1200-1-400x300.jpg 400w, https:\/\/el-perico.com\/wp-content\/uploads\/2025\/06\/Calvin.min-1200x1200-1-200x150.jpg 200w, https:\/\/el-perico.com\/wp-content\/uploads\/2025\/06\/Calvin.min-1200x1200-1-780x585.jpg 780w, https:\/\/el-perico.com\/wp-content\/uploads\/2025\/06\/Calvin.min-1200x1200-1.jpg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Calvin Williams poses for a photo in front of the Omaha Freedom Festival banner. (Photo by Kassidy Arena\/Nebraska Public Media News)<\/figcaption><\/figure>\n\n\n\n<p>\u201cNo fue una sorpresa\u201d, dijo. \u201cFue una excusa para salir. Estaban haciendo algo que no quer\u00edan hacer desde el principio, y eso deja ver sus verdaderos colores. Y definitivamente quiero que la gente sepa qui\u00e9n se retir\u00f3 y qui\u00e9n decidi\u00f3 quedarse\u201d.<\/p>\n\n\n\n<p>Aun as\u00ed, Frankie Jean Williams afirm\u00f3 que este fue el desfile m\u00e1s grande en cuanto a participaci\u00f3n. Los organizadores registraron 158 inscripciones, entre ellas funcionarios electos y patrocinadores. Un total de 5,600 personas formaron parte del desfile. Y no piensa detenerse. El presidente T. Michael Williams dijo que nunca hab\u00eda visto a tanta gente presenciar el evento.<\/p>\n\n\n\n<p>El desfile no fue el \u00fanico evento que perdi\u00f3 patrocinadores habituales. Calvin Williams, director de operaciones de la organizaci\u00f3n de eventos comunitarios <a href=\"https:\/\/www.freedomtainment.com\/\">Freedomtainment<\/a>, organiza el Omaha Freedom Festival, el evento que se celebra despu\u00e9s del desfile en la Malcolm X Memorial Foundation.<\/p>\n\n\n\n<p>\u201cCuando Trump asumi\u00f3 la presidencia, el financiamiento cambi\u00f3 de inmediato, y ahora estamos sintiendo las consecuencias\u201d, coment\u00f3.<\/p>\n\n\n\n<p>Calvin Williams aclar\u00f3 que har\u00eda este trabajo de forma voluntaria, pero sabe que no es realista. Tanto \u00e9l como su organizaci\u00f3n sin fines de lucro siguen necesitando fondos para ofrecer servicios esenciales como orientaci\u00f3n laboral, informaci\u00f3n sobre salud, recursos habitacionales y apoyo en salud mental.<\/p>\n\n\n\n<p>Freedomtainment organizar\u00e1 una feria de empleo y vivienda llamada <em>Level Up<\/em>, donde CeeLo Green se presentar\u00e1 el 30 de agosto. Todo eso, se\u00f1al\u00f3 Williams, requiere recursos econ\u00f3micos si se quiere ofrecer un evento gratuito que beneficie a la comunidad.<\/p>\n\n\n\n<p>La administraci\u00f3n Trump ha tomado medidas contra los programas de diversidad, equidad e inclusi\u00f3n, calific\u00e1ndolos como <a href=\"https:\/\/www.whitehouse.gov\/presidential-actions\/2025\/01\/ending-radical-and-wasteful-government-dei-programs-and-preferencing\/\">\u201cilegales\u201d y discriminatorios<\/a>.<\/p>\n\n\n\n<p>La presidenta del comit\u00e9, Frankie Jean Williams, dijo que prev\u00e9 un futuro en el que Juneteenth deje de ser considerado feriado federal, lo cual le da a\u00fan m\u00e1s valor a su labor.<\/p>\n\n\n\n<p>\u201cEstoy esperando que esta administraci\u00f3n diga que ya no es un feriado y he pensado mucho en qu\u00e9 haremos si eso sucede. No pueden quitarnos nuestra historia, sea o no un d\u00eda festivo\u201d, dijo.<\/p>\n\n\n\n<p>El 19 de junio fue <a href=\"https:\/\/www.npr.org\/2021\/06\/17\/1007602290\/biden-and-harris-will-speak-at-the-bill-signing-making-juneteenth-a-federal-holi\">declarado feriado federal<\/a> en 2021 bajo el gobierno del expresidente Joe Biden. Pero incluso antes de esa designaci\u00f3n, Omaha ya conmemoraba el d\u00eda en que los \u00faltimos esclavizados en los estados confederados fueron informados de su libertad. El presidente de la NAACP, T. Michael Williams, se\u00f1al\u00f3 que su organizaci\u00f3n organiza el desfile desde la d\u00e9cada de 1980, aunque la ciudad lo celebra desde la d\u00e9cada de 1890.<\/p>\n\n\n\n<p>Y los organizadores aseguraron que seguir\u00e1n haci\u00e9ndolo, especialmente ahora con el respaldo del nuevo alcalde.<\/p>\n\n\n\n<p><em>La traducci\u00f3n de<\/em> <a href=\"https:\/\/holaamericanews.com\/es\/omaha-celebrates-a-historic-juneteenth-parade-with-its-first-elected-black-mayor\/\"><strong><em>Hola Nebraska<\/em><\/strong><\/a><em>.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Voluntarios prepararon la hist\u00f3rica calle 24 de Omaha, Nebraska, para el desfile de Juneteenth de este a\u00f1o. Frankie Jean Williams, presidenta del comit\u00e9 de celebraci\u00f3n de Juneteenth de la NAACP en Omaha, esperaba con especial entusiasmo ver al primer alcalde afroamericano electo de la ciudad entre los participantes. Ewing asumi\u00f3 el cargo diez d\u00edas antes [&hellip;]<\/p>\n","protected":false},"author":53,"featured_media":9988,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"newspack_ads_suppress_ads":false,"_newspack_byline_active":false,"_newspack_byline":"","newspack_hide_updated_date":false,"newspack_show_updated_date":false,"newspack_content_restriction_is_exempt":false,"newspack_featured_image_position":"","newspack_post_subtitle":"","newspack_article_summary_title":"Overview:","newspack_article_summary":"","footnotes":""},"categories":[1843,1854,38],"tags":[],"newspack_spnsrs_tax":[],"coauthors":[1848],"class_list":["post-9999","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comunidad-es","category-cultura-es","category-eventos","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Hola Nebraska Omaha celebra un desfile hist\u00f3rico de Juneteenth con su primer alcalde afroamericano electo - el perico<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/el-perico.com\/es\/hola-nebraska-omaha-celebra-un-desfile-historico-de-juneteenth-con-su-primer-alcalde-afroamericano-electo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hola Nebraska Omaha celebra un desfile hist\u00f3rico de Juneteenth con su primer alcalde afroamericano electo - el perico\" \/>\n<meta property=\"og:description\" content=\"Voluntarios prepararon la hist\u00f3rica calle 24 de Omaha, Nebraska, para el desfile de Juneteenth de este a\u00f1o. Frankie Jean Williams, presidenta del comit\u00e9 de celebraci\u00f3n de Juneteenth de la NAACP en Omaha, esperaba con especial entusiasmo ver al primer alcalde afroamericano electo de la ciudad entre los participantes. Ewing asumi\u00f3 el cargo diez d\u00edas antes [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/el-perico.com\/es\/hola-nebraska-omaha-celebra-un-desfile-historico-de-juneteenth-con-su-primer-alcalde-afroamericano-electo\/\" \/>\n<meta property=\"og:site_name\" content=\"el perico\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/elpericoomaha\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-19T15:27:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-19T15:30:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/el-perico.com\/wp-content\/uploads\/2025\/06\/John_2.min-800x600-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"840\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Kassidy Arena\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Kassidy Arena\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n\t<meta name=\"twitter:label3\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data3\" content=\"Kassidy Arena\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/hola-nebraska-omaha-celebra-un-desfile-historico-de-juneteenth-con-su-primer-alcalde-afroamericano-electo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/hola-nebraska-omaha-celebra-un-desfile-historico-de-juneteenth-con-su-primer-alcalde-afroamericano-electo\\\/\"},\"author\":{\"name\":\"Kassidy Arena\",\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/#\\\/schema\\\/person\\\/f27993eba4b03c6b74d08db36c771ccb\"},\"headline\":\"Hola Nebraska Omaha celebra un desfile hist\u00f3rico de Juneteenth con su primer alcalde afroamericano electo\",\"datePublished\":\"2025-06-19T15:27:15+00:00\",\"dateModified\":\"2025-06-19T15:30:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/hola-nebraska-omaha-celebra-un-desfile-historico-de-juneteenth-con-su-primer-alcalde-afroamericano-electo\\\/\"},\"wordCount\":1159,\"publisher\":{\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/hola-nebraska-omaha-celebra-un-desfile-historico-de-juneteenth-con-su-primer-alcalde-afroamericano-electo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/el-perico.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/John_2.min-800x600-1.jpg\",\"articleSection\":[\"Comunidad\",\"Cultura\",\"Eventos\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/hola-nebraska-omaha-celebra-un-desfile-historico-de-juneteenth-con-su-primer-alcalde-afroamericano-electo\\\/\",\"url\":\"https:\\\/\\\/el-perico.com\\\/es\\\/hola-nebraska-omaha-celebra-un-desfile-historico-de-juneteenth-con-su-primer-alcalde-afroamericano-electo\\\/\",\"name\":\"Hola Nebraska Omaha celebra un desfile hist\u00f3rico de Juneteenth con su primer alcalde afroamericano electo - el perico\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/hola-nebraska-omaha-celebra-un-desfile-historico-de-juneteenth-con-su-primer-alcalde-afroamericano-electo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/hola-nebraska-omaha-celebra-un-desfile-historico-de-juneteenth-con-su-primer-alcalde-afroamericano-electo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/el-perico.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/John_2.min-800x600-1.jpg\",\"datePublished\":\"2025-06-19T15:27:15+00:00\",\"dateModified\":\"2025-06-19T15:30:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/hola-nebraska-omaha-celebra-un-desfile-historico-de-juneteenth-con-su-primer-alcalde-afroamericano-electo\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/el-perico.com\\\/es\\\/hola-nebraska-omaha-celebra-un-desfile-historico-de-juneteenth-con-su-primer-alcalde-afroamericano-electo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/hola-nebraska-omaha-celebra-un-desfile-historico-de-juneteenth-con-su-primer-alcalde-afroamericano-electo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/el-perico.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/John_2.min-800x600-1.jpg\",\"contentUrl\":\"https:\\\/\\\/el-perico.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/John_2.min-800x600-1.jpg\",\"width\":840,\"height\":600,\"caption\":\"Omaha Mayor John Ewing Jr. walked in the Juneteenth parade on Saturday, June 14, 2025. He is the city's first Black mayor. (Photo courtesy Erin Grace\\\/Mayor's Office)\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/hola-nebraska-omaha-celebra-un-desfile-historico-de-juneteenth-con-su-primer-alcalde-afroamericano-electo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/el-perico.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hola Nebraska Omaha celebra un desfile hist\u00f3rico de Juneteenth con su primer alcalde afroamericano electo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/el-perico.com\\\/es\\\/\",\"name\":\"el perico\",\"description\":\"La plataforma original de noticias e informaci\u00f3n para la comunidad hispana de Omaha\",\"publisher\":{\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/el-perico.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/#organization\",\"name\":\"el perico\",\"url\":\"https:\\\/\\\/el-perico.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/el-perico.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/ElPerico-Logo_NPM-1-e1717102187440.png\",\"contentUrl\":\"https:\\\/\\\/el-perico.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/ElPerico-Logo_NPM-1-e1717102187440.png\",\"width\":648,\"height\":216,\"caption\":\"el perico\"},\"image\":{\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/elpericoomaha\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/#\\\/schema\\\/person\\\/f27993eba4b03c6b74d08db36c771ccb\",\"name\":\"Kassidy Arena\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/56fe902807c4db396868614d1487f5e0af006997d13b304d912d550dff68305a?s=96&d=mm&r=g59d843837e06ed66a2ac6beefa284942\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/56fe902807c4db396868614d1487f5e0af006997d13b304d912d550dff68305a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/56fe902807c4db396868614d1487f5e0af006997d13b304d912d550dff68305a?s=96&d=mm&r=g\",\"caption\":\"Kassidy Arena\"},\"url\":\"https:\\\/\\\/el-perico.com\\\/es\\\/author\\\/karena\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hola Nebraska Omaha celebra un desfile hist\u00f3rico de Juneteenth con su primer alcalde afroamericano electo - el perico","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/el-perico.com\/es\/hola-nebraska-omaha-celebra-un-desfile-historico-de-juneteenth-con-su-primer-alcalde-afroamericano-electo\/","og_locale":"es_ES","og_type":"article","og_title":"Hola Nebraska Omaha celebra un desfile hist\u00f3rico de Juneteenth con su primer alcalde afroamericano electo - el perico","og_description":"Voluntarios prepararon la hist\u00f3rica calle 24 de Omaha, Nebraska, para el desfile de Juneteenth de este a\u00f1o. Frankie Jean Williams, presidenta del comit\u00e9 de celebraci\u00f3n de Juneteenth de la NAACP en Omaha, esperaba con especial entusiasmo ver al primer alcalde afroamericano electo de la ciudad entre los participantes. Ewing asumi\u00f3 el cargo diez d\u00edas antes [&hellip;]","og_url":"https:\/\/el-perico.com\/es\/hola-nebraska-omaha-celebra-un-desfile-historico-de-juneteenth-con-su-primer-alcalde-afroamericano-electo\/","og_site_name":"el perico","article_publisher":"https:\/\/www.facebook.com\/elpericoomaha","article_published_time":"2025-06-19T15:27:15+00:00","article_modified_time":"2025-06-19T15:30:23+00:00","og_image":[{"width":840,"height":600,"url":"https:\/\/el-perico.com\/wp-content\/uploads\/2025\/06\/John_2.min-800x600-1.jpg","type":"image\/jpeg"}],"author":"Kassidy Arena","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Kassidy Arena","Tiempo de lectura":"6 minutos","Written by":"Kassidy Arena"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/el-perico.com\/es\/hola-nebraska-omaha-celebra-un-desfile-historico-de-juneteenth-con-su-primer-alcalde-afroamericano-electo\/#article","isPartOf":{"@id":"https:\/\/el-perico.com\/es\/hola-nebraska-omaha-celebra-un-desfile-historico-de-juneteenth-con-su-primer-alcalde-afroamericano-electo\/"},"author":{"name":"Kassidy Arena","@id":"https:\/\/el-perico.com\/es\/#\/schema\/person\/f27993eba4b03c6b74d08db36c771ccb"},"headline":"Hola Nebraska Omaha celebra un desfile hist\u00f3rico de Juneteenth con su primer alcalde afroamericano electo","datePublished":"2025-06-19T15:27:15+00:00","dateModified":"2025-06-19T15:30:23+00:00","mainEntityOfPage":{"@id":"https:\/\/el-perico.com\/es\/hola-nebraska-omaha-celebra-un-desfile-historico-de-juneteenth-con-su-primer-alcalde-afroamericano-electo\/"},"wordCount":1159,"publisher":{"@id":"https:\/\/el-perico.com\/es\/#organization"},"image":{"@id":"https:\/\/el-perico.com\/es\/hola-nebraska-omaha-celebra-un-desfile-historico-de-juneteenth-con-su-primer-alcalde-afroamericano-electo\/#primaryimage"},"thumbnailUrl":"https:\/\/el-perico.com\/wp-content\/uploads\/2025\/06\/John_2.min-800x600-1.jpg","articleSection":["Comunidad","Cultura","Eventos"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/el-perico.com\/es\/hola-nebraska-omaha-celebra-un-desfile-historico-de-juneteenth-con-su-primer-alcalde-afroamericano-electo\/","url":"https:\/\/el-perico.com\/es\/hola-nebraska-omaha-celebra-un-desfile-historico-de-juneteenth-con-su-primer-alcalde-afroamericano-electo\/","name":"Hola Nebraska Omaha celebra un desfile hist\u00f3rico de Juneteenth con su primer alcalde afroamericano electo - el perico","isPartOf":{"@id":"https:\/\/el-perico.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/el-perico.com\/es\/hola-nebraska-omaha-celebra-un-desfile-historico-de-juneteenth-con-su-primer-alcalde-afroamericano-electo\/#primaryimage"},"image":{"@id":"https:\/\/el-perico.com\/es\/hola-nebraska-omaha-celebra-un-desfile-historico-de-juneteenth-con-su-primer-alcalde-afroamericano-electo\/#primaryimage"},"thumbnailUrl":"https:\/\/el-perico.com\/wp-content\/uploads\/2025\/06\/John_2.min-800x600-1.jpg","datePublished":"2025-06-19T15:27:15+00:00","dateModified":"2025-06-19T15:30:23+00:00","breadcrumb":{"@id":"https:\/\/el-perico.com\/es\/hola-nebraska-omaha-celebra-un-desfile-historico-de-juneteenth-con-su-primer-alcalde-afroamericano-electo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/el-perico.com\/es\/hola-nebraska-omaha-celebra-un-desfile-historico-de-juneteenth-con-su-primer-alcalde-afroamericano-electo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/el-perico.com\/es\/hola-nebraska-omaha-celebra-un-desfile-historico-de-juneteenth-con-su-primer-alcalde-afroamericano-electo\/#primaryimage","url":"https:\/\/el-perico.com\/wp-content\/uploads\/2025\/06\/John_2.min-800x600-1.jpg","contentUrl":"https:\/\/el-perico.com\/wp-content\/uploads\/2025\/06\/John_2.min-800x600-1.jpg","width":840,"height":600,"caption":"Omaha Mayor John Ewing Jr. walked in the Juneteenth parade on Saturday, June 14, 2025. He is the city's first Black mayor. (Photo courtesy Erin Grace\/Mayor's Office)"},{"@type":"BreadcrumbList","@id":"https:\/\/el-perico.com\/es\/hola-nebraska-omaha-celebra-un-desfile-historico-de-juneteenth-con-su-primer-alcalde-afroamericano-electo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/el-perico.com\/es\/"},{"@type":"ListItem","position":2,"name":"Hola Nebraska Omaha celebra un desfile hist\u00f3rico de Juneteenth con su primer alcalde afroamericano electo"}]},{"@type":"WebSite","@id":"https:\/\/el-perico.com\/es\/#website","url":"https:\/\/el-perico.com\/es\/","name":"el perico","description":"La plataforma original de noticias e informaci\u00f3n para la comunidad hispana de Omaha","publisher":{"@id":"https:\/\/el-perico.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/el-perico.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/el-perico.com\/es\/#organization","name":"el perico","url":"https:\/\/el-perico.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/el-perico.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/el-perico.com\/wp-content\/uploads\/2024\/05\/ElPerico-Logo_NPM-1-e1717102187440.png","contentUrl":"https:\/\/el-perico.com\/wp-content\/uploads\/2024\/05\/ElPerico-Logo_NPM-1-e1717102187440.png","width":648,"height":216,"caption":"el perico"},"image":{"@id":"https:\/\/el-perico.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/elpericoomaha"]},{"@type":"Person","@id":"https:\/\/el-perico.com\/es\/#\/schema\/person\/f27993eba4b03c6b74d08db36c771ccb","name":"Kassidy Arena","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/56fe902807c4db396868614d1487f5e0af006997d13b304d912d550dff68305a?s=96&d=mm&r=g59d843837e06ed66a2ac6beefa284942","url":"https:\/\/secure.gravatar.com\/avatar\/56fe902807c4db396868614d1487f5e0af006997d13b304d912d550dff68305a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/56fe902807c4db396868614d1487f5e0af006997d13b304d912d550dff68305a?s=96&d=mm&r=g","caption":"Kassidy Arena"},"url":"https:\/\/el-perico.com\/es\/author\/karena\/"}]}},"_links":{"self":[{"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/posts\/9999","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/users\/53"}],"replies":[{"embeddable":true,"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/comments?post=9999"}],"version-history":[{"count":1,"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/posts\/9999\/revisions"}],"predecessor-version":[{"id":10001,"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/posts\/9999\/revisions\/10001"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/media\/9988"}],"wp:attachment":[{"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/media?parent=9999"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/categories?post=9999"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/tags?post=9999"},{"taxonomy":"newspack_spnsrs_tax","embeddable":true,"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/newspack_spnsrs_tax?post=9999"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/coauthors?post=9999"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}