{"id":9913,"date":"2025-05-15T14:30:00","date_gmt":"2025-05-15T19:30:00","guid":{"rendered":"https:\/\/el-perico.com\/?p=9913"},"modified":"2025-05-15T14:32:30","modified_gmt":"2025-05-15T19:32:30","slug":"john-ewing-jr-elegido-alcalde-de-omaha","status":"publish","type":"post","link":"https:\/\/el-perico.com\/es\/john-ewing-jr-elegido-alcalde-de-omaha\/","title":{"rendered":"John Ewing Jr., elegido alcalde de Omaha"},"content":{"rendered":"\n<p>Ya se conocen los resultados de las elecciones a la alcald\u00eda de Omaha. El dem\u00f3crata John Ewing Jr. ha derrotado a la actual alcaldesa republicana Jean Stothert, con 45,336 votos frente a los 36,307 obtenidos por su contrincante, seg\u00fan los resultados no oficiales.<\/p>\n\n\n\n<p>Ewing coment\u00f3 que celebrar\u00eda el mi\u00e9rcoles y comenzar\u00eda a trabajar el jueves.<\/p>\n\n\n\n<p>\u201cLo primero que har\u00e9 ser\u00e1 empezar a hablar con personas interesadas en formar parte del equipo, para que podamos construir un gran equipo para la gente de esta comunidad\u201d, dijo Ewing. \u201cMe siento incre\u00edble. Me he preparado para esto pr\u00e1cticamente toda mi vida adulta, a trav\u00e9s del servicio p\u00fablico. Y espero que eso haya influido en los votantes, que hayan dicho: \u2018conocemos a este hombre, lo hemos visto crecer como l\u00edder en nuestra comunidad\u2019. Creo que eso marc\u00f3 una verdadera diferencia\u201d.<\/p>\n\n\n\n<p>Stothert reconoci\u00f3 la derrota alrededor de las 9:30 p.m., de acuerdo con los resultados no oficiales.<\/p>\n\n\n\n<p>Justo antes de su discurso, el gobernador Jim Pillen se dirigi\u00f3 a la multitud, afirmando que esta elecci\u00f3n \u201cdeber\u00eda haber sido un paseo\u201d para Stothert.<\/p>\n\n\n\n<p>\u201cEs un privilegio incre\u00edble estar aqu\u00ed con la alcaldesa\u201d, dijo Pillen. \u201cPero seamos claros: es un momento agridulce\u2026 Tuvimos oportunidades extraordinarias, desde arriba con el presidente Trump hasta el final de la boleta, y temas importantes. Entonces, \u00bfqu\u00e9 nos pasa a los conservadores? Volvemos al trabajo y olvidamos lo importantes que son las elecciones. Es fundamental que ninguno de nosotros lo olvide jam\u00e1s\u201d.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"771\" src=\"https:\/\/el-perico.com\/wp-content\/uploads\/2025\/05\/Ewing_talking.original-1024x771.jpg\" alt=\"\" class=\"wp-image-9911\" srcset=\"https:\/\/el-perico.com\/wp-content\/uploads\/2025\/05\/Ewing_talking.original-1024x771.jpg 1024w, https:\/\/el-perico.com\/wp-content\/uploads\/2025\/05\/Ewing_talking.original-300x226.jpg 300w, https:\/\/el-perico.com\/wp-content\/uploads\/2025\/05\/Ewing_talking.original-768x578.jpg 768w, https:\/\/el-perico.com\/wp-content\/uploads\/2025\/05\/Ewing_talking.original-1536x1157.jpg 1536w, https:\/\/el-perico.com\/wp-content\/uploads\/2025\/05\/Ewing_talking.original-2048x1542.jpg 2048w, https:\/\/el-perico.com\/wp-content\/uploads\/2025\/05\/Ewing_talking.original-400x301.jpg 400w, https:\/\/el-perico.com\/wp-content\/uploads\/2025\/05\/Ewing_talking.original-200x150.jpg 200w, https:\/\/el-perico.com\/wp-content\/uploads\/2025\/05\/Ewing_talking.original-1200x904.jpg 1200w, https:\/\/el-perico.com\/wp-content\/uploads\/2025\/05\/Ewing_talking.original-2000x1506.jpg 2000w, https:\/\/el-perico.com\/wp-content\/uploads\/2025\/05\/Ewing_talking.original-780x587.jpg 780w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Stothert habl\u00f3 tras el discurso de Pillen.<\/p>\n\n\n\n<p>\u201cMe siento muy orgullosa, agradecida y con esperanza\u201d, expres\u00f3 Stothert. \u201cTengo esperanza de que el impulso que hemos creado contin\u00fae\u2026 Me ha encantado cada minuto en el Ayuntamiento: cuatro a\u00f1os en el Concejo, 12 a\u00f1os como alcaldesa. No me arrepiento de nada\u201d.<\/p>\n\n\n\n<p>Stothert y Ewing<a href=\"https:\/\/nebraskapublicmedia.org\/en\/news\/news-articles\/early-voting-results-roll-in-for-omaha-city-primary-election\/\" rel=\"noreferrer noopener\" target=\"_blank\">&nbsp;avanzaron a las elecciones generales<\/a>&nbsp;luego de obtener 27,245 y 24,605 votos, respectivamente, en las primarias del 1 de abril. Otros tres candidatos quedaron fuera en esa contienda: Mike McDonnell, con 15,039 votos; Jasmine Harris, con 7,706; y Terry Brewer, con 563 votos.<\/p>\n\n\n\n<p>Stothert domin\u00f3 en los distritos del oeste de la ciudad, aunque la participaci\u00f3n en esa zona fue relativamente baja en comparaci\u00f3n con las elecciones de 2021.<\/p>\n\n\n\n<p>Ewing gan\u00f3 en los recintos del centro-este y norte de Omaha, dentro del \u00e1rea limitada al sur por la I-80 y al oeste por la I-680.<\/p>\n\n\n\n<p>Con 12 a\u00f1os en el cargo, Stothert empat\u00f3 el r\u00e9cord como la alcaldesa con m\u00e1s tiempo en funciones en Omaha. En su primera campa\u00f1a, derrot\u00f3 al entonces alcalde Jim Suttle con el 57 % de los votos.<\/p>\n\n\n\n<p>Ewing es tesorero del condado de Douglas desde 2007. Antes de eso, trabaj\u00f3 en el Departamento de Polic\u00eda de Omaha por aproximadamente 25 a\u00f1os. Ocup\u00f3 varios cargos dentro del departamento, concluyendo su carrera como subjefe, responsable del presupuesto y de otras operaciones clave, como el plan de mejoras de capital.<\/p>\n\n\n\n<p>James Loach, uno de los votantes anticipados, opin\u00f3 que lo m\u00e1s importante es que la ciudad resulte atractiva para empresas y nuevos residentes.<\/p>\n\n\n\n<p>\u201cCreo que necesitamos mejorar el liderazgo, especialmente en lo relacionado con la comunidad\u201d, dijo Loach. \u201cY de cara al futuro, necesitamos que la ciudad siga siendo un lugar donde la gente quiera vivir\u201d.<\/p>\n\n\n\n<p>David Hill, otro votante temprano, se\u00f1al\u00f3 que su principal preocupaci\u00f3n eran las calles de Omaha, y opin\u00f3 que Stothert ya hab\u00eda tenido suficiente tiempo.<\/p>\n\n\n\n<p>\u201c[Stothert ha] tenido unos 12 a\u00f1os para resolver las cosas, y siguen igual. As\u00ed que estoy dispuesto a darle una oportunidad a John Ewing esta vez\u201d, dijo Hill. \u201cSeamos realistas: ha sido tesorero por casi 20 a\u00f1os y tiene un buen historial. Creo que ya es hora de un cambio\u201d.<\/p>\n\n\n\n<p>En los \u00faltimos 12 d\u00edas de campa\u00f1a, Stothert recibi\u00f3 un impulso financiero de $167,000, incluyendo $10,000 del senador Pete Ricketts, $2,500 del congresista Don Bacon y $50,000 del comit\u00e9 We Are Nebraska PAC, creado por el gobernador Jim Pillen y dirigido por su familia.<\/p>\n\n\n\n<p>Tambi\u00e9n recibi\u00f3 $10,000 del Omaha Leadership Fund, un comit\u00e9 de acci\u00f3n pol\u00edtica creado en marzo. Common Sense Nebraska, un PAC financiado en gran parte por Marlene Ricketts, madre de Pete Ricketts, ha canalizado m\u00e1s de $210,000 a este fondo desde su creaci\u00f3n.<\/p>\n\n\n\n<p>El Omaha Leadership Fund estuvo detr\u00e1s de gran parte de la publicidad negativa contra Ewing en los d\u00edas finales de la campa\u00f1a, incluyendo un volante enviado por correo a los hogares de Omaha, en el que se afirmaba que Ewing apoyaba \u201ca hombres en los deportes femeninos\u201d y \u201ca hombres en los ba\u00f1os de mujeres\u201d. Desde el 28 de abril, el PAC gast\u00f3 m\u00e1s de $93,000 en campa\u00f1as de mensajes de texto y anuncios contra Ewing.<\/p>\n\n\n\n<p>Stothert&nbsp;<a href=\"https:\/\/omaha.com\/news\/local\/government-politics\/elections\/article_eb1b7c90-9db6-4c47-8234-78c13cf33832.html\" rel=\"noreferrer noopener\" target=\"_blank\">respald\u00f3 el mensaje de esos volantes<\/a>, y su equipo de campa\u00f1a tambi\u00e9n lanz\u00f3 un anuncio de televisi\u00f3n en el que calificaba a Ewing como un \u201cradical\u201d que apoya \u201ca hombres en los ba\u00f1os y deportes de mujeres\u201d. En una conferencia de prensa, Stothert afirm\u00f3 que hab\u00eda presentado el contenido del anuncio a la junta asesora LGBTQ+ de la ciudad antes de su emisi\u00f3n, pero al menos un miembro de la junta recurri\u00f3 a las&nbsp;<a href=\"https:\/\/www.facebook.com\/demi.kulper\/posts\/pfbid0xBJr5noeWWGKsWdmCivXX5KEAVuffLgamCGsZgV8X49n6FRufMAETtpcuC3QjSAQl?rdid=UFbiTzq1ut7fD2WB\" rel=\"noreferrer noopener\" target=\"_blank\">redes sociales<\/a>&nbsp;para decir que no se les consult\u00f3.<\/p>\n\n\n\n<p>Por su parte, Ewing recaud\u00f3 $45,000 en los \u00faltimos 12 d\u00edas de campa\u00f1a, provenientes principalmente de sindicatos y donantes filantr\u00f3picos.<\/p>\n\n\n\n<p>Los siete esca\u00f1os del Concejo Municipal de Omaha estuvieron en juego, cinco de ellos con contiendas disputadas. Estos son los resultados preliminares:<\/p>\n\n\n\n<p><strong>Distrito 1<\/strong><br>Pete Festersen \u2013 9,042<br>Mark Brannen \u2013 3,703<\/p>\n\n\n\n<p><strong>Distrito 2<\/strong><br>Lavonya Goodwin \u2013 4,018<br>Ben Gray \u2013 2,858<\/p>\n\n\n\n<p><strong>Distrito 3<\/strong><br>Danny Begley \u2013 6,853<br>Michael Pilypaitis \u2013 3,652<\/p>\n\n\n\n<p><strong>Distrito 4<\/strong><br>Ron Hug \u2013 3,777<br>Andrew Adams \u2013 2,306<\/p>\n\n\n\n<p><strong>Distrito 7<\/strong><br>Aimee Melton \u2013 7,547<br>Tim Carter \u2013 6,206<\/p>\n\n\n\n<p>Los candidatos del Distrito 5, Don Rowe, y del Distrito 6, Brinker Harding, se postularon sin oposici\u00f3n en las elecciones generales.<\/p>\n\n\n\n<p>El comisionado electoral del condado de Douglas, Brian Kruse, anticipaba una participaci\u00f3n de alrededor del 32 % antes del martes.<\/p>\n\n\n\n<p><em>La traducci\u00f3n de<\/em>&nbsp;<a href=\"https:\/\/holaamericanews.com\/es\/john-ewing-jr-elected-mayor-of-omaha\/\" rel=\"noreferrer noopener\" target=\"_blank\"><strong><em>Hola Nebraska<\/em><\/strong><\/a><em>.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ya se conocen los resultados de las elecciones a la alcald\u00eda de Omaha. El dem\u00f3crata John Ewing Jr. ha derrotado a la actual alcaldesa republicana Jean Stothert, con 45,336 votos frente a los 36,307 obtenidos por su contrincante, seg\u00fan los resultados no oficiales. Ewing coment\u00f3 que celebrar\u00eda el mi\u00e9rcoles y comenzar\u00eda a trabajar el jueves. [&hellip;]<\/p>\n","protected":false},"author":54,"featured_media":9909,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"newspack_ads_suppress_ads":false,"_newspack_byline_active":false,"_newspack_byline":"","newspack_hide_updated_date":false,"newspack_show_updated_date":false,"newspack_content_restriction_is_exempt":false,"newspack_featured_image_position":"","newspack_post_subtitle":"","newspack_article_summary_title":"Overview:","newspack_article_summary":"","footnotes":""},"categories":[1226],"tags":[],"newspack_spnsrs_tax":[],"coauthors":[1859],"class_list":["post-9913","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categorizar","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>John Ewing Jr., elegido alcalde de Omaha - el perico<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/el-perico.com\/es\/john-ewing-jr-elegido-alcalde-de-omaha\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"John Ewing Jr., elegido alcalde de Omaha - el perico\" \/>\n<meta property=\"og:description\" content=\"Ya se conocen los resultados de las elecciones a la alcald\u00eda de Omaha. El dem\u00f3crata John Ewing Jr. ha derrotado a la actual alcaldesa republicana Jean Stothert, con 45,336 votos frente a los 36,307 obtenidos por su contrincante, seg\u00fan los resultados no oficiales. Ewing coment\u00f3 que celebrar\u00eda el mi\u00e9rcoles y comenzar\u00eda a trabajar el jueves. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/el-perico.com\/es\/john-ewing-jr-elegido-alcalde-de-omaha\/\" \/>\n<meta property=\"og:site_name\" content=\"el perico\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/elpericoomaha\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-15T19:30:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-15T19:32:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/el-perico.com\/wp-content\/uploads\/2025\/05\/Ewing_for_Mayor_Sign.original-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1819\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Arthur Jones\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Arthur Jones\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n\t<meta name=\"twitter:label3\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data3\" content=\"Arthur Jones\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/john-ewing-jr-elegido-alcalde-de-omaha\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/john-ewing-jr-elegido-alcalde-de-omaha\\\/\"},\"author\":{\"name\":\"Arthur Jones\",\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/#\\\/schema\\\/person\\\/fe3aafb86332185d762dad98cdaa33e1\"},\"headline\":\"John Ewing Jr., elegido alcalde de Omaha\",\"datePublished\":\"2025-05-15T19:30:00+00:00\",\"dateModified\":\"2025-05-15T19:32:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/john-ewing-jr-elegido-alcalde-de-omaha\\\/\"},\"wordCount\":1002,\"publisher\":{\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/john-ewing-jr-elegido-alcalde-de-omaha\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/el-perico.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Ewing_for_Mayor_Sign.original-scaled.jpg\",\"articleSection\":[\"Sin categorizar\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/john-ewing-jr-elegido-alcalde-de-omaha\\\/\",\"url\":\"https:\\\/\\\/el-perico.com\\\/es\\\/john-ewing-jr-elegido-alcalde-de-omaha\\\/\",\"name\":\"John Ewing Jr., elegido alcalde de Omaha - el perico\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/john-ewing-jr-elegido-alcalde-de-omaha\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/john-ewing-jr-elegido-alcalde-de-omaha\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/el-perico.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Ewing_for_Mayor_Sign.original-scaled.jpg\",\"datePublished\":\"2025-05-15T19:30:00+00:00\",\"dateModified\":\"2025-05-15T19:32:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/john-ewing-jr-elegido-alcalde-de-omaha\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/el-perico.com\\\/es\\\/john-ewing-jr-elegido-alcalde-de-omaha\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/john-ewing-jr-elegido-alcalde-de-omaha\\\/#primaryimage\",\"url\":\"https:\\\/\\\/el-perico.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Ewing_for_Mayor_Sign.original-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/el-perico.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Ewing_for_Mayor_Sign.original-scaled.jpg\",\"width\":2560,\"height\":1819,\"caption\":\"The podium at John Ewing Jr.'s election watch party. (Arthur Jones\\\/Nebraska Public Media News)\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/john-ewing-jr-elegido-alcalde-de-omaha\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/el-perico.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"John Ewing Jr., elegido alcalde de Omaha\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/el-perico.com\\\/es\\\/\",\"name\":\"el perico\",\"description\":\"La plataforma original de noticias e informaci\u00f3n para la comunidad hispana de Omaha\",\"publisher\":{\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/el-perico.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/#organization\",\"name\":\"el perico\",\"url\":\"https:\\\/\\\/el-perico.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/el-perico.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/ElPerico-Logo_NPM-1-e1717102187440.png\",\"contentUrl\":\"https:\\\/\\\/el-perico.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/ElPerico-Logo_NPM-1-e1717102187440.png\",\"width\":648,\"height\":216,\"caption\":\"el perico\"},\"image\":{\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/elpericoomaha\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/#\\\/schema\\\/person\\\/fe3aafb86332185d762dad98cdaa33e1\",\"name\":\"Arthur Jones\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/11e18d1ad1f552bc5074a56aed2f345eae6e26da44c5c1a6e1fcb791219257fb?s=96&d=mm&r=gc72fa755492f4a96e4ba39fb37ba56d9\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/11e18d1ad1f552bc5074a56aed2f345eae6e26da44c5c1a6e1fcb791219257fb?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/11e18d1ad1f552bc5074a56aed2f345eae6e26da44c5c1a6e1fcb791219257fb?s=96&d=mm&r=g\",\"caption\":\"Arthur Jones\"},\"url\":\"https:\\\/\\\/el-perico.com\\\/es\\\/author\\\/ajones\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"John Ewing Jr., elegido alcalde de Omaha - el perico","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/el-perico.com\/es\/john-ewing-jr-elegido-alcalde-de-omaha\/","og_locale":"es_ES","og_type":"article","og_title":"John Ewing Jr., elegido alcalde de Omaha - el perico","og_description":"Ya se conocen los resultados de las elecciones a la alcald\u00eda de Omaha. El dem\u00f3crata John Ewing Jr. ha derrotado a la actual alcaldesa republicana Jean Stothert, con 45,336 votos frente a los 36,307 obtenidos por su contrincante, seg\u00fan los resultados no oficiales. Ewing coment\u00f3 que celebrar\u00eda el mi\u00e9rcoles y comenzar\u00eda a trabajar el jueves. [&hellip;]","og_url":"https:\/\/el-perico.com\/es\/john-ewing-jr-elegido-alcalde-de-omaha\/","og_site_name":"el perico","article_publisher":"https:\/\/www.facebook.com\/elpericoomaha","article_published_time":"2025-05-15T19:30:00+00:00","article_modified_time":"2025-05-15T19:32:30+00:00","og_image":[{"width":2560,"height":1819,"url":"https:\/\/el-perico.com\/wp-content\/uploads\/2025\/05\/Ewing_for_Mayor_Sign.original-scaled.jpg","type":"image\/jpeg"}],"author":"Arthur Jones","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Arthur Jones","Tiempo de lectura":"5 minutos","Written by":"Arthur Jones"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/el-perico.com\/es\/john-ewing-jr-elegido-alcalde-de-omaha\/#article","isPartOf":{"@id":"https:\/\/el-perico.com\/es\/john-ewing-jr-elegido-alcalde-de-omaha\/"},"author":{"name":"Arthur Jones","@id":"https:\/\/el-perico.com\/es\/#\/schema\/person\/fe3aafb86332185d762dad98cdaa33e1"},"headline":"John Ewing Jr., elegido alcalde de Omaha","datePublished":"2025-05-15T19:30:00+00:00","dateModified":"2025-05-15T19:32:30+00:00","mainEntityOfPage":{"@id":"https:\/\/el-perico.com\/es\/john-ewing-jr-elegido-alcalde-de-omaha\/"},"wordCount":1002,"publisher":{"@id":"https:\/\/el-perico.com\/es\/#organization"},"image":{"@id":"https:\/\/el-perico.com\/es\/john-ewing-jr-elegido-alcalde-de-omaha\/#primaryimage"},"thumbnailUrl":"https:\/\/el-perico.com\/wp-content\/uploads\/2025\/05\/Ewing_for_Mayor_Sign.original-scaled.jpg","articleSection":["Sin categorizar"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/el-perico.com\/es\/john-ewing-jr-elegido-alcalde-de-omaha\/","url":"https:\/\/el-perico.com\/es\/john-ewing-jr-elegido-alcalde-de-omaha\/","name":"John Ewing Jr., elegido alcalde de Omaha - el perico","isPartOf":{"@id":"https:\/\/el-perico.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/el-perico.com\/es\/john-ewing-jr-elegido-alcalde-de-omaha\/#primaryimage"},"image":{"@id":"https:\/\/el-perico.com\/es\/john-ewing-jr-elegido-alcalde-de-omaha\/#primaryimage"},"thumbnailUrl":"https:\/\/el-perico.com\/wp-content\/uploads\/2025\/05\/Ewing_for_Mayor_Sign.original-scaled.jpg","datePublished":"2025-05-15T19:30:00+00:00","dateModified":"2025-05-15T19:32:30+00:00","breadcrumb":{"@id":"https:\/\/el-perico.com\/es\/john-ewing-jr-elegido-alcalde-de-omaha\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/el-perico.com\/es\/john-ewing-jr-elegido-alcalde-de-omaha\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/el-perico.com\/es\/john-ewing-jr-elegido-alcalde-de-omaha\/#primaryimage","url":"https:\/\/el-perico.com\/wp-content\/uploads\/2025\/05\/Ewing_for_Mayor_Sign.original-scaled.jpg","contentUrl":"https:\/\/el-perico.com\/wp-content\/uploads\/2025\/05\/Ewing_for_Mayor_Sign.original-scaled.jpg","width":2560,"height":1819,"caption":"The podium at John Ewing Jr.'s election watch party. (Arthur Jones\/Nebraska Public Media News)"},{"@type":"BreadcrumbList","@id":"https:\/\/el-perico.com\/es\/john-ewing-jr-elegido-alcalde-de-omaha\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/el-perico.com\/es\/"},{"@type":"ListItem","position":2,"name":"John Ewing Jr., elegido alcalde de Omaha"}]},{"@type":"WebSite","@id":"https:\/\/el-perico.com\/es\/#website","url":"https:\/\/el-perico.com\/es\/","name":"el perico","description":"La plataforma original de noticias e informaci\u00f3n para la comunidad hispana de Omaha","publisher":{"@id":"https:\/\/el-perico.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/el-perico.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/el-perico.com\/es\/#organization","name":"el perico","url":"https:\/\/el-perico.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/el-perico.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/el-perico.com\/wp-content\/uploads\/2024\/05\/ElPerico-Logo_NPM-1-e1717102187440.png","contentUrl":"https:\/\/el-perico.com\/wp-content\/uploads\/2024\/05\/ElPerico-Logo_NPM-1-e1717102187440.png","width":648,"height":216,"caption":"el perico"},"image":{"@id":"https:\/\/el-perico.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/elpericoomaha"]},{"@type":"Person","@id":"https:\/\/el-perico.com\/es\/#\/schema\/person\/fe3aafb86332185d762dad98cdaa33e1","name":"Arthur Jones","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/11e18d1ad1f552bc5074a56aed2f345eae6e26da44c5c1a6e1fcb791219257fb?s=96&d=mm&r=gc72fa755492f4a96e4ba39fb37ba56d9","url":"https:\/\/secure.gravatar.com\/avatar\/11e18d1ad1f552bc5074a56aed2f345eae6e26da44c5c1a6e1fcb791219257fb?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/11e18d1ad1f552bc5074a56aed2f345eae6e26da44c5c1a6e1fcb791219257fb?s=96&d=mm&r=g","caption":"Arthur Jones"},"url":"https:\/\/el-perico.com\/es\/author\/ajones\/"}]}},"_links":{"self":[{"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/posts\/9913","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/users\/54"}],"replies":[{"embeddable":true,"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/comments?post=9913"}],"version-history":[{"count":1,"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/posts\/9913\/revisions"}],"predecessor-version":[{"id":9914,"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/posts\/9913\/revisions\/9914"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/media\/9909"}],"wp:attachment":[{"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/media?parent=9913"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/categories?post=9913"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/tags?post=9913"},{"taxonomy":"newspack_spnsrs_tax","embeddable":true,"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/newspack_spnsrs_tax?post=9913"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/coauthors?post=9913"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}