{"id":916,"date":"2017-11-03T23:15:41","date_gmt":"2017-11-03T23:15:41","guid":{"rendered":"https:\/\/el-perico.kaageg0-liquidwebsites.com\/?p=916"},"modified":"2017-11-03T23:15:41","modified_gmt":"2017-11-03T23:15:41","slug":"consejo-escolar-de-omaha-en-busqueda-de-un-nuevo-normal-despues-de-desacuerdo-parte-1","status":"publish","type":"post","link":"https:\/\/el-perico.com\/es\/consejo-escolar-de-omaha-en-busqueda-de-un-nuevo-normal-despues-de-desacuerdo-parte-1\/","title":{"rendered":"Consejo Escolar de Omaha en b\u00fasqueda de un nuevo normal despu\u00e9s de desacuerdo: Parte 1"},"content":{"rendered":"<p><b>Para leer la versi\u00f3n original en ingl\u00e9s visite http:\/\/thereader.com\/<\/b><br \/>\n&nbsp;<br \/>\nCuando el consejo de Omaha Public Schools no logr\u00f3 encontrar un nuevo superintendente durante la primavera pasada, marc\u00f3 la continuaci\u00f3n de conflictos internos y de cuestiones en el distrito que fueron hechas p\u00fablicas.<br \/>\nEntre la b\u00fasqueda suspendida y el comienzo de un nuevo a\u00f1o escolar, el actual superintendente Mark Evans, quien antes hab\u00eda anunciado su retiro, acept\u00f3 quedarse un a\u00f1o m\u00e1s. Algunos miembros del consejo le han apoyado, mientras que otros han tenido problemas con \u00e9l. Despu\u00e9s de toda la situaci\u00f3n, Evans y los miembros del consejo han dicho que est\u00e1n dejando atr\u00e1s el pasado.<br \/>\nUn punto importante por atender es reactivar la b\u00fasqueda y alcanzar un consenso sobre el sucesor de Evans. Esa decisi\u00f3n, junto con la implementaci\u00f3n de un nuevo plan de tareas para alnos, abrir escuelas y una cuesti\u00f3n pendiente sobre continuar con el enfoque de un plan estrat\u00e9gico iniciado por Evans, estar\u00e1n bajo el escrutinio de una comunidad en guardia.<br \/>\nLas cosas eran tan malas que durante el verano nueve miembros del consejo participaron en sesiones de capacitaci\u00f3n con Marj Plumb centradas en la comunicaci\u00f3n interpersonal y la construcci\u00f3n de relaciones. Tal vez se realicen m\u00e1s sesiones en fechas posteriores.<br \/>\nPor lo pronto se est\u00e1 formando un comit\u00e9 de Junta Gobernante para servir como un \u00f3rgano de supervisi\u00f3n del desarrollo profesional.<br \/>\nSe necesita de algo de historia para entender c\u00f3mo las cosas llegaron a este punto. En enero, el consejo recientemente constituido requer\u00eda de m\u00e1s de 100 votos para elegir a su Presidenta, Lacey Merica. Muchas decisiones 5-4 sobre cuestiones del distrito siguieron de tensas reuniones del consejo. Cuando la b\u00fasqueda continu\u00f3 en medio de una notoria divisi\u00f3n, los tres candidatos finales se retiraron del proceso, diciendo que hab\u00eda disfuncionamiento. El marcado criticismo de las partes interesadas lleg\u00f3 a su punto m\u00e1ximo cuando el <i>Omaha World-Herald<\/i> public\u00f3 los correos repletos de discusiones entre algunos miembros del consejo. Esto ocasion\u00f3 que algunos observadores cuestionaren el profesionalismo y enfoque de los miembros.<br \/>\nHa habido situaciones sobre los logros acad\u00e9micos de los estudiantes, en los que a pesar de lo ganado persisten las brechas, la respuesta a las suspensiones desproporcionadas de los estudiantes y problemas en el transporte de estudiantes.<br \/>\nEl liderazgo del distrito ha sido atacado por no buscar una suficiente aportaci\u00f3n de los educadores y el p\u00fablico sobre la instituci\u00f3n del d\u00eda escolar con horario extendido, la presentaci\u00f3n y aplicaci\u00f3n de un nuevo plan de estudios sobre educaci\u00f3n sexual y por detener la b\u00fasqueda de un superintendente.<br \/>\nBridget Donovan, Presidenta de la Omaha Education Association, dijo que ella quiere que el liderazgo invite a los directores, maestros y padres a que est\u00e9n m\u00e1s involucrados durante \u00a0la nueva b\u00fasqueda, \u201cpues yo considero que ayuda a sentar las bases para el \u00e9xito del siguiente superintendente\u201d. Sin m\u00e1s transparencia, nos dice, \u201cno sabemos, como p\u00fablico o como empleados, cu\u00e1les son los criterios que ellos (el consejo) est\u00e1n utilizando\u201d.<br \/>\nCon el nuevo a\u00f1o escolar ya en marcha, el tiempo corre y la comunidad est\u00e1 observando para ver c\u00f3mo son diferentes las cosas en esta ocasi\u00f3n.<br \/>\n\u00abYo siento algo de esperanza de que en esta ocasi\u00f3n nos abordar\u00e1n de forma significativa\u201d, dijo Donovan, cuya organizaci\u00f3n representa a los educadores de OPS. \u201cYo considero que el consejo est\u00e1 haciendo un esfuerzo para que as\u00ed sea\u201d, aunque ella se pregunta si han aprendido a estar en desacuerdo de forma constructiva.<br \/>\nEvans, Snow y Merica coinciden en que el desempe\u00f1o del consejo ser\u00e1 juzgado sobre c\u00f3mo procede el a\u00f1o escolar y por el tenor de las reuniones abiertas. Dicen que desde que se asisti\u00f3 a la capacitaci\u00f3n han notado una mejora perceptible en c\u00f3mo se relacionan entre ellos y con Evans.<br \/>\nA\u00fan con todo lo dem\u00e1s que llevar\u00e1 a cabo el consejo, la forma en que manejen sus miembros la nueva b\u00fasqueda ser\u00e1 la prueba m\u00e1s apreciable sobre a d\u00f3nde han llegado.<br \/>\n\u00abConsiderando el gran problema que era, yo creo que ellos (el consejo) en verdad tienen que hacerlo bien esta vez\u201d, dijo Donovan. \u201dVan a estar bajo mucha presi\u00f3n\u201d.<br \/>\nEn agosto, un subcomit\u00e9 encargado a la tarea vot\u00f3 por cortar todo lazo con la anterior firma de b\u00fasqueda y comisionar a una nueva. La meta es poder actuar r\u00e1pidamente y contratar a un nuevo superintendente para finales de diciembre.<br \/>\n\u00abHemos iniciado con el comit\u00e9 que presentar\u00e1 recomendaciones al consejo para lo que es el siguiente paso, la l\u00ednea cronol\u00f3gica \u00a0c\u00f3mo la comunidad tendr\u00e1 una participaci\u00f3n en ello\u201d, dijo Merica.<br \/>\nElla mencion\u00f3 que es clave \u201cque la comunidad est\u00e9 dentro de esto\u201d despu\u00e9s de las quejas sobre c\u00f3mo OPS no estaba siendo suficientemente transparente.<br \/>\nEvans y los dem\u00e1s minimizaron las preocupaciones sobre c\u00f3mo los eventos ca\u00f3ticos del pasado podr\u00edan disuadir a los candidatos calificados de entrar en la contienda.<br \/>\n\u00abYo considero que la nueva firma de b\u00fasqueda dir\u00e1 qui\u00e9nes son esos candidatos\u2026 lo que hemos aprendido de esa experiencia nos ha ayudado a crecer\u201d, comenta. \u201cEn realidad, es un gran momento para entrar pues terminamos encontrado una forma de trabajar juntos de forma colectiva\u201d.<br \/>\nLa capacitaci\u00f3n del consejo brind\u00f3 una perspectiva sobre las din\u00e1micas individuales e interpersonales que los miembros ahora aplican en la pr\u00e1ctica.<br \/>\n\u00abHablamos un poco sobre nosotros y nuestras personalidades\u201d, dijo Lacey Merica. \u00abFue muy \u00fatil para poder que todos estuvi\u00e9ramos juntos y en sinton\u00eda, para tambi\u00e9n ver a los dem\u00e1s miembros del consejo como seres humanos.<br \/>\nSi Snow ha aprendido algo de esto, comenta, es \u201cllegar a un compromiso y entender lo que gu\u00eda a las personas y que sin importar si no estamos de acuerdo con su decisi\u00f3n, les respetemos\u2026 Nuestro objetivo es tomar una decisi\u00f3n con un consejo unificado, no como individuos\u201d.<br \/>\nSnow coment\u00f3 que la capacitaci\u00f3n fue una lecci\u00f3n en humildad.<br \/>\n\u00abTodos primero tenemos que reconocer el hecho de que todos tenemos margen para mejorar. Y el hecho de que pudimos hacer que todos los miembros del consejo asistieron es prueba de ello. El problema en el pasado para el consejo y para la mayor\u00eda de los consejos escolares en el pa\u00eds es que ellos (los miembros) solamente se re\u00fanen en las reuniones del consejo. Solamente tienen la posibilidad de hablar sobre cuestiones durante las reuniones del consejo cuando se toma una decisi\u00f3n y, si yo no te conozco a nivel personal, tal vez tome esa decisi\u00f3n como algo personal\u201d.<br \/>\nMark Evans dijo que la capacitaci\u00f3n no fue un mandato sino algo que se acord\u00f3 que era necesario.<br \/>\n\u00abFue una discusi\u00f3n que todos tuvimos. Quer\u00edamos enviar un mensaje de que \u00edbamos a tratar vivir juntos y no tener las controversias y conflictos del pasado y tratar de encontrar las razones que hicieron que hubiere una ruptura en la comunicaci\u00f3n y la confianza. Fue un deseo por, por as\u00ed decirlo, dar la vuelta a la p\u00e1gina\u201d.<br \/>\n\u201cSer\u00e1 fundamental para empezar con la b\u00fasqueda del superintendente\u201d, nos dijo. \u201cEl plan de asignaciones para estudiantes es dif\u00edcil, la cuesti\u00f3n del transporte es dif\u00edcil. La cuesti\u00f3n de los bonos es algo en lo que tenemos miembros en el consejo que tienen opiniones encontradas sobre ello y eso es una cuesti\u00f3n trascendental. Hace tres a\u00f1os no creo que hubi\u00e9ramos podido llegar a un acuerdo sobre algunas de estas cosas. Hoy en d\u00eda, considero que si podemos. Creo que eso es parte de la evoluci\u00f3n del proceso\u201d.<br \/>\n&nbsp;<br \/>\n<i>Lea m\u00e1s del trabajo de Leo Adam Biga en <\/i><a href=\"http:\/\/leoadambiga.com\/\"><i>leoadambiga.com<\/i><\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Para leer la versi\u00f3n original en ingl\u00e9s visite http:\/\/thereader.com\/ &nbsp; Cuando el consejo de Omaha Public Schools no logr\u00f3 encontrar un nuevo superintendente durante la primavera pasada, marc\u00f3 la continuaci\u00f3n de conflictos internos y de cuestiones en el distrito que fueron hechas p\u00fablicas. Entre la b\u00fasqueda suspendida y el comienzo de un nuevo a\u00f1o escolar, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":917,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"newspack_ads_suppress_ads":false,"_newspack_byline_active":false,"_newspack_byline":"","newspack_hide_updated_date":false,"newspack_show_updated_date":false,"newspack_content_restriction_is_exempt":false,"newspack_featured_image_position":"","newspack_post_subtitle":"","newspack_article_summary_title":"Overview:","newspack_article_summary":"","footnotes":""},"categories":[1],"tags":[],"newspack_spnsrs_tax":[],"coauthors":[],"class_list":["post-916","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Consejo Escolar de Omaha en b\u00fasqueda de un nuevo normal despu\u00e9s de desacuerdo: Parte 1 - el perico<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/el-perico.com\/es\/consejo-escolar-de-omaha-en-busqueda-de-un-nuevo-normal-despues-de-desacuerdo-parte-1\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Consejo Escolar de Omaha en b\u00fasqueda de un nuevo normal despu\u00e9s de desacuerdo: Parte 1 - el perico\" \/>\n<meta property=\"og:description\" content=\"Para leer la versi\u00f3n original en ingl\u00e9s visite http:\/\/thereader.com\/ &nbsp; Cuando el consejo de Omaha Public Schools no logr\u00f3 encontrar un nuevo superintendente durante la primavera pasada, marc\u00f3 la continuaci\u00f3n de conflictos internos y de cuestiones en el distrito que fueron hechas p\u00fablicas. Entre la b\u00fasqueda suspendida y el comienzo de un nuevo a\u00f1o escolar, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/el-perico.com\/es\/consejo-escolar-de-omaha-en-busqueda-de-un-nuevo-normal-despues-de-desacuerdo-parte-1\/\" \/>\n<meta property=\"og:site_name\" content=\"el perico\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/elpericoomaha\" \/>\n<meta property=\"article:published_time\" content=\"2017-11-03T23:15:41+00:00\" \/>\n<meta name=\"author\" content=\"El Perico Staff\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"El Perico Staff\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n\t<meta name=\"twitter:label3\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data3\" content=\"El Perico Staff\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/consejo-escolar-de-omaha-en-busqueda-de-un-nuevo-normal-despues-de-desacuerdo-parte-1\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/consejo-escolar-de-omaha-en-busqueda-de-un-nuevo-normal-despues-de-desacuerdo-parte-1\\\/\"},\"author\":{\"name\":\"El Perico Staff\",\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/#\\\/schema\\\/person\\\/1956e5e63b94d4bd0daf30675bdf4a93\"},\"headline\":\"Consejo Escolar de Omaha en b\u00fasqueda de un nuevo normal despu\u00e9s de desacuerdo: Parte 1\",\"datePublished\":\"2017-11-03T23:15:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/consejo-escolar-de-omaha-en-busqueda-de-un-nuevo-normal-despues-de-desacuerdo-parte-1\\\/\"},\"wordCount\":1353,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/consejo-escolar-de-omaha-en-busqueda-de-un-nuevo-normal-despues-de-desacuerdo-parte-1\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"articleSection\":[\"Uncategorized\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/el-perico.com\\\/es\\\/consejo-escolar-de-omaha-en-busqueda-de-un-nuevo-normal-despues-de-desacuerdo-parte-1\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/consejo-escolar-de-omaha-en-busqueda-de-un-nuevo-normal-despues-de-desacuerdo-parte-1\\\/\",\"url\":\"https:\\\/\\\/el-perico.com\\\/es\\\/consejo-escolar-de-omaha-en-busqueda-de-un-nuevo-normal-despues-de-desacuerdo-parte-1\\\/\",\"name\":\"Consejo Escolar de Omaha en b\u00fasqueda de un nuevo normal despu\u00e9s de desacuerdo: Parte 1 - el perico\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/consejo-escolar-de-omaha-en-busqueda-de-un-nuevo-normal-despues-de-desacuerdo-parte-1\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/consejo-escolar-de-omaha-en-busqueda-de-un-nuevo-normal-despues-de-desacuerdo-parte-1\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2017-11-03T23:15:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/consejo-escolar-de-omaha-en-busqueda-de-un-nuevo-normal-despues-de-desacuerdo-parte-1\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/el-perico.com\\\/es\\\/consejo-escolar-de-omaha-en-busqueda-de-un-nuevo-normal-despues-de-desacuerdo-parte-1\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/consejo-escolar-de-omaha-en-busqueda-de-un-nuevo-normal-despues-de-desacuerdo-parte-1\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/consejo-escolar-de-omaha-en-busqueda-de-un-nuevo-normal-despues-de-desacuerdo-parte-1\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/el-perico.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Consejo Escolar de Omaha en b\u00fasqueda de un nuevo normal despu\u00e9s de desacuerdo: Parte 1\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/el-perico.com\\\/es\\\/\",\"name\":\"el perico\",\"description\":\"La plataforma original de noticias e informaci\u00f3n para la comunidad hispana de Omaha\",\"publisher\":{\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/el-perico.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/#organization\",\"name\":\"el perico\",\"url\":\"https:\\\/\\\/el-perico.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/el-perico.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/ElPerico-Logo_NPM-1-e1717102187440.png\",\"contentUrl\":\"https:\\\/\\\/el-perico.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/ElPerico-Logo_NPM-1-e1717102187440.png\",\"width\":648,\"height\":216,\"caption\":\"el perico\"},\"image\":{\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/elpericoomaha\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/#\\\/schema\\\/person\\\/1956e5e63b94d4bd0daf30675bdf4a93\",\"name\":\"El Perico Staff\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/701b23c665bfde9fd4d874d31feb4c16bf2ac173b2b0b7224dc39896d4cfc381?s=96&d=mm&r=g80b2efc5844e688a6ffb9340c789e4c4\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/701b23c665bfde9fd4d874d31feb4c16bf2ac173b2b0b7224dc39896d4cfc381?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/701b23c665bfde9fd4d874d31feb4c16bf2ac173b2b0b7224dc39896d4cfc381?s=96&d=mm&r=g\",\"caption\":\"El Perico Staff\"},\"sameAs\":[\"https:\\\/\\\/el-perico.com\"],\"url\":\"https:\\\/\\\/el-perico.com\\\/es\\\/author\\\/af6f1d62_admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Consejo Escolar de Omaha en b\u00fasqueda de un nuevo normal despu\u00e9s de desacuerdo: Parte 1 - el perico","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/el-perico.com\/es\/consejo-escolar-de-omaha-en-busqueda-de-un-nuevo-normal-despues-de-desacuerdo-parte-1\/","og_locale":"es_ES","og_type":"article","og_title":"Consejo Escolar de Omaha en b\u00fasqueda de un nuevo normal despu\u00e9s de desacuerdo: Parte 1 - el perico","og_description":"Para leer la versi\u00f3n original en ingl\u00e9s visite http:\/\/thereader.com\/ &nbsp; Cuando el consejo de Omaha Public Schools no logr\u00f3 encontrar un nuevo superintendente durante la primavera pasada, marc\u00f3 la continuaci\u00f3n de conflictos internos y de cuestiones en el distrito que fueron hechas p\u00fablicas. Entre la b\u00fasqueda suspendida y el comienzo de un nuevo a\u00f1o escolar, [&hellip;]","og_url":"https:\/\/el-perico.com\/es\/consejo-escolar-de-omaha-en-busqueda-de-un-nuevo-normal-despues-de-desacuerdo-parte-1\/","og_site_name":"el perico","article_publisher":"https:\/\/www.facebook.com\/elpericoomaha","article_published_time":"2017-11-03T23:15:41+00:00","author":"El Perico Staff","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"El Perico Staff","Tiempo de lectura":"7 minutos","Written by":"El Perico Staff"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/el-perico.com\/es\/consejo-escolar-de-omaha-en-busqueda-de-un-nuevo-normal-despues-de-desacuerdo-parte-1\/#article","isPartOf":{"@id":"https:\/\/el-perico.com\/es\/consejo-escolar-de-omaha-en-busqueda-de-un-nuevo-normal-despues-de-desacuerdo-parte-1\/"},"author":{"name":"El Perico Staff","@id":"https:\/\/el-perico.com\/es\/#\/schema\/person\/1956e5e63b94d4bd0daf30675bdf4a93"},"headline":"Consejo Escolar de Omaha en b\u00fasqueda de un nuevo normal despu\u00e9s de desacuerdo: Parte 1","datePublished":"2017-11-03T23:15:41+00:00","mainEntityOfPage":{"@id":"https:\/\/el-perico.com\/es\/consejo-escolar-de-omaha-en-busqueda-de-un-nuevo-normal-despues-de-desacuerdo-parte-1\/"},"wordCount":1353,"commentCount":0,"publisher":{"@id":"https:\/\/el-perico.com\/es\/#organization"},"image":{"@id":"https:\/\/el-perico.com\/es\/consejo-escolar-de-omaha-en-busqueda-de-un-nuevo-normal-despues-de-desacuerdo-parte-1\/#primaryimage"},"thumbnailUrl":"","articleSection":["Uncategorized"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/el-perico.com\/es\/consejo-escolar-de-omaha-en-busqueda-de-un-nuevo-normal-despues-de-desacuerdo-parte-1\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/el-perico.com\/es\/consejo-escolar-de-omaha-en-busqueda-de-un-nuevo-normal-despues-de-desacuerdo-parte-1\/","url":"https:\/\/el-perico.com\/es\/consejo-escolar-de-omaha-en-busqueda-de-un-nuevo-normal-despues-de-desacuerdo-parte-1\/","name":"Consejo Escolar de Omaha en b\u00fasqueda de un nuevo normal despu\u00e9s de desacuerdo: Parte 1 - el perico","isPartOf":{"@id":"https:\/\/el-perico.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/el-perico.com\/es\/consejo-escolar-de-omaha-en-busqueda-de-un-nuevo-normal-despues-de-desacuerdo-parte-1\/#primaryimage"},"image":{"@id":"https:\/\/el-perico.com\/es\/consejo-escolar-de-omaha-en-busqueda-de-un-nuevo-normal-despues-de-desacuerdo-parte-1\/#primaryimage"},"thumbnailUrl":"","datePublished":"2017-11-03T23:15:41+00:00","breadcrumb":{"@id":"https:\/\/el-perico.com\/es\/consejo-escolar-de-omaha-en-busqueda-de-un-nuevo-normal-despues-de-desacuerdo-parte-1\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/el-perico.com\/es\/consejo-escolar-de-omaha-en-busqueda-de-un-nuevo-normal-despues-de-desacuerdo-parte-1\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/el-perico.com\/es\/consejo-escolar-de-omaha-en-busqueda-de-un-nuevo-normal-despues-de-desacuerdo-parte-1\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/el-perico.com\/es\/consejo-escolar-de-omaha-en-busqueda-de-un-nuevo-normal-despues-de-desacuerdo-parte-1\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/el-perico.com\/es\/"},{"@type":"ListItem","position":2,"name":"Consejo Escolar de Omaha en b\u00fasqueda de un nuevo normal despu\u00e9s de desacuerdo: Parte 1"}]},{"@type":"WebSite","@id":"https:\/\/el-perico.com\/es\/#website","url":"https:\/\/el-perico.com\/es\/","name":"el perico","description":"La plataforma original de noticias e informaci\u00f3n para la comunidad hispana de Omaha","publisher":{"@id":"https:\/\/el-perico.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/el-perico.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/el-perico.com\/es\/#organization","name":"el perico","url":"https:\/\/el-perico.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/el-perico.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/el-perico.com\/wp-content\/uploads\/2024\/05\/ElPerico-Logo_NPM-1-e1717102187440.png","contentUrl":"https:\/\/el-perico.com\/wp-content\/uploads\/2024\/05\/ElPerico-Logo_NPM-1-e1717102187440.png","width":648,"height":216,"caption":"el perico"},"image":{"@id":"https:\/\/el-perico.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/elpericoomaha"]},{"@type":"Person","@id":"https:\/\/el-perico.com\/es\/#\/schema\/person\/1956e5e63b94d4bd0daf30675bdf4a93","name":"El Perico Staff","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/701b23c665bfde9fd4d874d31feb4c16bf2ac173b2b0b7224dc39896d4cfc381?s=96&d=mm&r=g80b2efc5844e688a6ffb9340c789e4c4","url":"https:\/\/secure.gravatar.com\/avatar\/701b23c665bfde9fd4d874d31feb4c16bf2ac173b2b0b7224dc39896d4cfc381?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/701b23c665bfde9fd4d874d31feb4c16bf2ac173b2b0b7224dc39896d4cfc381?s=96&d=mm&r=g","caption":"El Perico Staff"},"sameAs":["https:\/\/el-perico.com"],"url":"https:\/\/el-perico.com\/es\/author\/af6f1d62_admin\/"}]}},"_links":{"self":[{"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/posts\/916","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/comments?post=916"}],"version-history":[{"count":0,"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/posts\/916\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/el-perico.com\/es\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/media?parent=916"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/categories?post=916"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/tags?post=916"},{"taxonomy":"newspack_spnsrs_tax","embeddable":true,"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/newspack_spnsrs_tax?post=916"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/coauthors?post=916"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}