{"id":8908,"date":"2023-02-01T08:00:00","date_gmt":"2023-02-01T13:00:00","guid":{"rendered":"https:\/\/el-perico.com\/?p=8908"},"modified":"2023-02-01T11:55:17","modified_gmt":"2023-02-01T16:55:17","slug":"lo-que-necesitan-comprender-los-trabajadores-de-la-construccion-en-omaha-para-su-seguridad","status":"publish","type":"post","link":"https:\/\/el-perico.com\/es\/lo-que-necesitan-comprender-los-trabajadores-de-la-construccion-en-omaha-para-su-seguridad\/","title":{"rendered":"Lo que necesitan entender los trabajadores de la construcci\u00f3n en Omaha para su seguridad"},"content":{"rendered":"\n<p>Casi todos los d\u00edas laborales, Alonso Maldonado instala revestimientos en casas del \u00e1rea de Omaha con la empresa de sus padres, <a href=\"http:\/\/www.1ruizconstructionllc.com\/\">Ruiz Construction<\/a>.<\/p>\n\n\n\n<p>Despu\u00e9s de haber trabajado en la construcci\u00f3n durante tres a\u00f1os, Maldonado sabe que puede ser una profesi\u00f3n peligrosa. Es por eso que asisti\u00f3 a una clase de seguridad en la construcci\u00f3n de 10 horas organizada por el <a href=\"https:\/\/www.heartlandworkerscenter.org\/hsti?lang=es\">Instituto de Entrenamiento de Salud y Seguridad<\/a> (HSTI, por sus siglas en ingl\u00e9s) del Heartland Workers Center (HWC).<\/p>\n\n\n\n<p>En el transcurso de un fin de semana de enero, Maldonado y otros catorce trabajadores de la construcci\u00f3n y empleadores se sentaron en la oficina de la calle 24 sur de la organizaci\u00f3n sin fines de lucro, y actualizaron sus conocimientos sobre las normas de seguridad en el lugar de trabajo. Para Maldonado, la decisi\u00f3n de asistir al entrenamiento fue sencilla.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/el-perico.com\/wp-content\/uploads\/2023\/02\/3_Trabajadores-1-1024x768.jpg\" alt=\"\" class=\"wp-image-8916\" width=\"770\" height=\"577\" srcset=\"https:\/\/el-perico.com\/wp-content\/uploads\/2023\/02\/3_Trabajadores-1-1024x768.jpg 1024w, https:\/\/el-perico.com\/wp-content\/uploads\/2023\/02\/3_Trabajadores-1-300x225.jpg 300w, https:\/\/el-perico.com\/wp-content\/uploads\/2023\/02\/3_Trabajadores-1-768x576.jpg 768w, https:\/\/el-perico.com\/wp-content\/uploads\/2023\/02\/3_Trabajadores-1-1536x1152.jpg 1536w, https:\/\/el-perico.com\/wp-content\/uploads\/2023\/02\/3_Trabajadores-1-2048x1536.jpg 2048w, https:\/\/el-perico.com\/wp-content\/uploads\/2023\/02\/3_Trabajadores-1-1200x900.jpg 1200w, https:\/\/el-perico.com\/wp-content\/uploads\/2023\/02\/3_Trabajadores-1-800x600.jpg 800w, https:\/\/el-perico.com\/wp-content\/uploads\/2023\/02\/3_Trabajadores-1-400x300.jpg 400w, https:\/\/el-perico.com\/wp-content\/uploads\/2023\/02\/3_Trabajadores-1-200x150.jpg 200w, https:\/\/el-perico.com\/wp-content\/uploads\/2023\/02\/3_Trabajadores-1-1568x1176.jpg 1568w\" sizes=\"auto, (max-width: 770px) 100vw, 770px\" \/><figcaption class=\"wp-element-caption\">Alonso Maldonado, izquierda, sonr\u00ede con sus padres, los due\u00f1os de Ruiz Construction en el Heartland Workers Center el 15 de enero. Foto por Bridget Fogarty.<\/figcaption><\/figure>\n<\/div>\n\n\n<p>\u201cAnimar\u00eda a todos los trabajadores a tomar la decisi\u00f3n de tomar una clase\u201d, dijo Maldonado. \u201cNo espere a que ocurra un accidente\u201d.<\/p>\n\n\n\n<p>La construcci\u00f3n sigue siendo una de las industrias m\u00e1s letales en los EE. UU. Durante 2021, 986 trabajadores de construcci\u00f3n murieron en el trabajo, seg\u00fan la <a href=\"https:\/\/www.constructiondive.com\/news\/construction-remains-among-top-deadliest-industries\/639304\/\">Oficina de Estad\u00edsticas Laborales de los EE. UU.<\/a><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/el-perico.com\/wp-content\/uploads\/2023\/02\/2_Trabajadores-1-1024x773.jpg\" alt=\"\" class=\"wp-image-8914\" width=\"747\" height=\"564\" srcset=\"https:\/\/el-perico.com\/wp-content\/uploads\/2023\/02\/2_Trabajadores-1-1024x773.jpg 1024w, https:\/\/el-perico.com\/wp-content\/uploads\/2023\/02\/2_Trabajadores-1-300x227.jpg 300w, https:\/\/el-perico.com\/wp-content\/uploads\/2023\/02\/2_Trabajadores-1-768x580.jpg 768w, https:\/\/el-perico.com\/wp-content\/uploads\/2023\/02\/2_Trabajadores-1-1536x1160.jpg 1536w, https:\/\/el-perico.com\/wp-content\/uploads\/2023\/02\/2_Trabajadores-1-2048x1547.jpg 2048w, https:\/\/el-perico.com\/wp-content\/uploads\/2023\/02\/2_Trabajadores-1-200x150.jpg 200w, https:\/\/el-perico.com\/wp-content\/uploads\/2023\/02\/2_Trabajadores-1-1200x906.jpg 1200w, https:\/\/el-perico.com\/wp-content\/uploads\/2023\/02\/2_Trabajadores-1-1568x1184.jpg 1568w, https:\/\/el-perico.com\/wp-content\/uploads\/2023\/02\/2_Trabajadores-1-400x302.jpg 400w\" sizes=\"auto, (max-width: 747px) 100vw, 747px\" \/><figcaption class=\"wp-element-caption\">Pen\u00e9lope Le\u00f3n se presenta en una capacitaci\u00f3n de construcci\u00f3n el 15 de enero. Foto por Bridget Fogarty.<\/figcaption><\/figure>\n<\/div>\n\n\n<p>Pen\u00e9lope Le\u00f3n, quien imparte capacitaci\u00f3n con HSTI, dijo que es importante que tanto los trabajadores como los empleadores comprendan sus derechos y obligaciones para mantener a todos seguros en el trabajo. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Aqu\u00ed hay algunas cosas que debe saber para sentirse m\u00e1s seguro en el trabajo en Nebraska:<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Sepa si es un empleado o un subcontratista.<\/strong><\/h3>\n\n\n\n<p>Es importante entender si est\u00e1 clasificado como empleado o subcontratista cuando trabaja. Para los empleados, un empleador es responsable de retener y pagar los impuestos relacionados con el empleo. Los subcontratistas son responsables de mantener sus propios registros y pagar sus propios impuestos sobre la renta y el trabajo por cuenta propia.<\/p>\n\n\n\n<p>El seguro de compensaci\u00f3n laboral cubre el riesgo de que un empleado se lesione en el trabajo. No cubre a los subcontratistas.<\/p>\n\n\n\n<p>En Nebraska, la Ley de Clasificaci\u00f3n de Empleados protege a los trabajadores de los servicios de construcci\u00f3n y entrega de ser clasificados err\u00f3neamente como subcontratistas. Eso puede conducir a la retenci\u00f3n de impuestos, seguro de desempleo y beneficios de seguro de compensaci\u00f3n laboral.<\/p>\n\n\n\n<p>Puede llamar al Departamento de Trabajo si cree que usted o alguien m\u00e1s est\u00e1 mal clasificado como empleado o subcontratista al (800) 627 3611.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignright size-full is-resized\"><img decoding=\"async\" src=\"https:\/\/el-perico.com\/wp-content\/uploads\/2023\/01\/Screen-Shot-2023-01-27-at-12.58.19-PM.png\" alt=\"\" class=\"wp-image-8910\" width=\"-146\" height=\"-194\" srcset=\"https:\/\/el-perico.com\/wp-content\/uploads\/2023\/01\/Screen-Shot-2023-01-27-at-12.58.19-PM.png 426w, https:\/\/el-perico.com\/wp-content\/uploads\/2023\/01\/Screen-Shot-2023-01-27-at-12.58.19-PM-225x300.png 225w, https:\/\/el-perico.com\/wp-content\/uploads\/2023\/01\/Screen-Shot-2023-01-27-at-12.58.19-PM-300x400.png 300w, https:\/\/el-perico.com\/wp-content\/uploads\/2023\/01\/Screen-Shot-2023-01-27-at-12.58.19-PM-150x200.png 150w, https:\/\/el-perico.com\/wp-content\/uploads\/2023\/01\/Screen-Shot-2023-01-27-at-12.58.19-PM-400x532.png 400w\" sizes=\"(max-width: 426px) 100vw, 426px\" \/><figcaption class=\"wp-element-caption\">Pen\u00e9lope Le\u00f3n se presenta en una capacitaci\u00f3n de construcci\u00f3n el 15 de enero. Foto por Bridget Fogarty.<\/figcaption><\/figure>\n<\/div>\n\n\n<h3 class=\"wp-block-heading\"><strong>Conozca la informaci\u00f3n de su empleador.<\/strong><\/h3>\n\n\n\n<p>Le\u00f3n dijo que una de las cosas m\u00e1s importantes que puede hacer para mantenerse seguro en el trabajo es revisar su equipo con regularidad.<\/p>\n\n\n\n<p>\u201cDicen que los accidentes ocurren, pero la mayor\u00eda de los accidentes se pueden prevenir\u201d, afirm\u00f3 Le\u00f3n. Si algo anda mal con su equipo, docum\u00e9ntelo y aseg\u00farese de que su gerente lo sepa.<\/p>\n\n\n\n<p>Si se lastima en el trabajo, es fundamental que busque ayuda m\u00e9dica, dijo Le\u00f3n. El seguro de compensaci\u00f3n laboral cubre el riesgo de que un empleado, no un subcontratista, se lesione en el trabajo. Aseg\u00farese de saber el nombre y apellido de su empleador, el n\u00famero de tel\u00e9fono y el nombre oficial de la empresa para que su compensaci\u00f3n laboral cubra la lesi\u00f3n.<\/p>\n\n\n\n<p>Cuando un empleador se entera de una lesi\u00f3n en el trabajo, tiene la obligaci\u00f3n de notificar a su aseguradora de compensaci\u00f3n laboral y presentar un informe ante el tribunal de compensaci\u00f3n laboral dentro de los 10 d\u00edas posteriores a la fecha del aviso de la lesi\u00f3n.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Conozca sus derechos a salarios justos.<\/strong><\/h3>\n\n\n\n<p>Los empleadores deben llevar un registro de las horas que trabajan los empleados y pagarles con un recibo de n\u00f3mina, dijo Pen\u00e9lope Le\u00f3n. Un recibo de n\u00f3mina incluye el nombre de la empresa, la direcci\u00f3n y el nombre del trabajador.<\/p>\n\n\n\n<p>En enero, el salario m\u00ednimo de Nebraska cambi\u00f3 de $9.00 a $10.50 y aumentar\u00e1 $1.50 cada a\u00f1o hasta llegar a $15 en 2026. Si cree que puede haber alg\u00fan problema con su salario, guarde los documentos del problema y hable con alguien en el trabajo que pueda ayudar a hacer un cambio directo. Tambi\u00e9n puede presentar una queja salarial ante el Departamento Laboral de Nebraska.<\/p>\n\n\n\n<p>Puede comunicarse con el Heartland Workers Center al (402) 933 6095 o en hsti@OSHABilingualTraining.org para solicitar capacitaci\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Casi todos los d\u00edas laborales, Alonso Maldonado instala revestimientos en casas del \u00e1rea de Omaha con la empresa de sus padres, Ruiz Construction. Despu\u00e9s de haber trabajado en la construcci\u00f3n durante tres a\u00f1os, Maldonado sabe que puede ser una profesi\u00f3n peligrosa. Es por eso que asisti\u00f3 a una clase de seguridad en la construcci\u00f3n de [&hellip;]<\/p>\n","protected":false},"author":26,"featured_media":8899,"comment_status":"open","ping_status":"closed","sticky":true,"template":"","format":"standard","meta":{"newspack_ads_suppress_ads":false,"_newspack_byline_active":false,"_newspack_byline":"","newspack_hide_updated_date":false,"newspack_show_updated_date":false,"newspack_content_restriction_is_exempt":false,"newspack_featured_image_position":"","newspack_post_subtitle":"La construcci\u00f3n sigue siendo una de las industrias m\u00e1s letales en los EE. UU. El Instituto de Entrenamiento de Salud y Seguridad del Heartland Workers Center les da apoyo a los trabajadores de la construcci\u00f3n en Omaha.","newspack_article_summary_title":"Overview:","newspack_article_summary":"","footnotes":""},"categories":[38,40,44,46],"tags":[1673,1672,1671,1669,1335,1674,1675,1670,1668],"newspack_spnsrs_tax":[],"coauthors":[1297],"class_list":["post-8908","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventos","category-inmigracion","category-la-vida-americana","category-reportaje","tag-health-and-safety-training-institute-2","tag-heartland-workers-center-2","tag-instituto-de-entrenamiento-de-salud-y-seguridad","tag-oficina-de-estadisticas-laborales","tag-omaha","tag-omaha-construccion","tag-penelope-leon-2","tag-ruiz-construction-2","tag-trabajo-de-construccion","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lo que necesitan entender los trabajadores de la construcci\u00f3n en Omaha para su seguridad - el perico<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/el-perico.com\/es\/lo-que-necesitan-comprender-los-trabajadores-de-la-construccion-en-omaha-para-su-seguridad\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lo que necesitan entender los trabajadores de la construcci\u00f3n en Omaha para su seguridad - el perico\" \/>\n<meta property=\"og:description\" content=\"Casi todos los d\u00edas laborales, Alonso Maldonado instala revestimientos en casas del \u00e1rea de Omaha con la empresa de sus padres, Ruiz Construction. Despu\u00e9s de haber trabajado en la construcci\u00f3n durante tres a\u00f1os, Maldonado sabe que puede ser una profesi\u00f3n peligrosa. Es por eso que asisti\u00f3 a una clase de seguridad en la construcci\u00f3n de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/el-perico.com\/es\/lo-que-necesitan-comprender-los-trabajadores-de-la-construccion-en-omaha-para-su-seguridad\/\" \/>\n<meta property=\"og:site_name\" content=\"el perico\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/elpericoomaha\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-01T13:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-01T16:55:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/el-perico.com\/wp-content\/uploads\/2023\/02\/1_Trabajadores_PenelopeLeon-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Bridget Fogarty, Report for America Corps Member\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Bridget Fogarty, Report for America Corps Member\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n\t<meta name=\"twitter:label3\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data3\" content=\"Bridget Fogarty, Report for America Corps Member\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/lo-que-necesitan-comprender-los-trabajadores-de-la-construccion-en-omaha-para-su-seguridad\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/lo-que-necesitan-comprender-los-trabajadores-de-la-construccion-en-omaha-para-su-seguridad\\\/\"},\"author\":{\"name\":\"Bridget Fogarty, Report for America Corps Member\",\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/#\\\/schema\\\/person\\\/c3c9a4c7cd6206a5b46fb472eff94bba\"},\"headline\":\"Lo que necesitan entender los trabajadores de la construcci\u00f3n en Omaha para su seguridad\",\"datePublished\":\"2023-02-01T13:00:00+00:00\",\"dateModified\":\"2023-02-01T16:55:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/lo-que-necesitan-comprender-los-trabajadores-de-la-construccion-en-omaha-para-su-seguridad\\\/\"},\"wordCount\":816,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/lo-que-necesitan-comprender-los-trabajadores-de-la-construccion-en-omaha-para-su-seguridad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/el-perico.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/1_Trabajadores_PenelopeLeon-scaled.jpg\",\"keywords\":[\"Health and Safety Training Institute\",\"Heartland Workers Center\",\"Instituto de Entrenamiento de Salud y Seguridad\",\"Oficina de Estad\u00edsticas Laborales\",\"Omaha\",\"Omaha construcci\u00f3n\",\"Pen\u00e9lope Le\u00f3n\",\"Ruiz Construction\",\"trabajo de construcci\u00f3n\"],\"articleSection\":[\"Eventos\",\"Inmigracion\",\"La Vida Americana\",\"Reportaje\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/el-perico.com\\\/es\\\/lo-que-necesitan-comprender-los-trabajadores-de-la-construccion-en-omaha-para-su-seguridad\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/lo-que-necesitan-comprender-los-trabajadores-de-la-construccion-en-omaha-para-su-seguridad\\\/\",\"url\":\"https:\\\/\\\/el-perico.com\\\/es\\\/lo-que-necesitan-comprender-los-trabajadores-de-la-construccion-en-omaha-para-su-seguridad\\\/\",\"name\":\"Lo que necesitan entender los trabajadores de la construcci\u00f3n en Omaha para su seguridad - el perico\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/lo-que-necesitan-comprender-los-trabajadores-de-la-construccion-en-omaha-para-su-seguridad\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/lo-que-necesitan-comprender-los-trabajadores-de-la-construccion-en-omaha-para-su-seguridad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/el-perico.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/1_Trabajadores_PenelopeLeon-scaled.jpg\",\"datePublished\":\"2023-02-01T13:00:00+00:00\",\"dateModified\":\"2023-02-01T16:55:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/lo-que-necesitan-comprender-los-trabajadores-de-la-construccion-en-omaha-para-su-seguridad\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/el-perico.com\\\/es\\\/lo-que-necesitan-comprender-los-trabajadores-de-la-construccion-en-omaha-para-su-seguridad\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/lo-que-necesitan-comprender-los-trabajadores-de-la-construccion-en-omaha-para-su-seguridad\\\/#primaryimage\",\"url\":\"https:\\\/\\\/el-perico.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/1_Trabajadores_PenelopeLeon-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/el-perico.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/1_Trabajadores_PenelopeLeon-scaled.jpg\",\"width\":2560,\"height\":1920},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/lo-que-necesitan-comprender-los-trabajadores-de-la-construccion-en-omaha-para-su-seguridad\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/el-perico.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lo que necesitan entender los trabajadores de la construcci\u00f3n en Omaha para su seguridad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/el-perico.com\\\/es\\\/\",\"name\":\"el perico\",\"description\":\"La plataforma original de noticias e informaci\u00f3n para la comunidad hispana de Omaha\",\"publisher\":{\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/el-perico.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/#organization\",\"name\":\"el perico\",\"url\":\"https:\\\/\\\/el-perico.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/el-perico.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/ElPerico-Logo_NPM-1-e1717102187440.png\",\"contentUrl\":\"https:\\\/\\\/el-perico.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/ElPerico-Logo_NPM-1-e1717102187440.png\",\"width\":648,\"height\":216,\"caption\":\"el perico\"},\"image\":{\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/elpericoomaha\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/#\\\/schema\\\/person\\\/c3c9a4c7cd6206a5b46fb472eff94bba\",\"name\":\"Bridget Fogarty, Report for America Corps Member\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd24cc6ab228b710e2b4d7220545b2b721779200a44f3e80f3c94559fe9a16cb?s=96&d=mm&r=ged5896247ed259e9e7dbf3d4b3b2e52d\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd24cc6ab228b710e2b4d7220545b2b721779200a44f3e80f3c94559fe9a16cb?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd24cc6ab228b710e2b4d7220545b2b721779200a44f3e80f3c94559fe9a16cb?s=96&d=mm&r=g\",\"caption\":\"Bridget Fogarty, Report for America Corps Member\"},\"description\":\"Bridget Fogarty is a Report for America Corps member reporting with El Perico and its English sister publication The Reader.\",\"url\":\"https:\\\/\\\/el-perico.com\\\/es\\\/author\\\/bridget-fogarty\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lo que necesitan entender los trabajadores de la construcci\u00f3n en Omaha para su seguridad - el perico","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/el-perico.com\/es\/lo-que-necesitan-comprender-los-trabajadores-de-la-construccion-en-omaha-para-su-seguridad\/","og_locale":"es_ES","og_type":"article","og_title":"Lo que necesitan entender los trabajadores de la construcci\u00f3n en Omaha para su seguridad - el perico","og_description":"Casi todos los d\u00edas laborales, Alonso Maldonado instala revestimientos en casas del \u00e1rea de Omaha con la empresa de sus padres, Ruiz Construction. Despu\u00e9s de haber trabajado en la construcci\u00f3n durante tres a\u00f1os, Maldonado sabe que puede ser una profesi\u00f3n peligrosa. Es por eso que asisti\u00f3 a una clase de seguridad en la construcci\u00f3n de [&hellip;]","og_url":"https:\/\/el-perico.com\/es\/lo-que-necesitan-comprender-los-trabajadores-de-la-construccion-en-omaha-para-su-seguridad\/","og_site_name":"el perico","article_publisher":"https:\/\/www.facebook.com\/elpericoomaha","article_published_time":"2023-02-01T13:00:00+00:00","article_modified_time":"2023-02-01T16:55:17+00:00","og_image":[{"width":2560,"height":1920,"url":"https:\/\/el-perico.com\/wp-content\/uploads\/2023\/02\/1_Trabajadores_PenelopeLeon-scaled.jpg","type":"image\/jpeg"}],"author":"Bridget Fogarty, Report for America Corps Member","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Bridget Fogarty, Report for America Corps Member","Tiempo de lectura":"4 minutos","Written by":"Bridget Fogarty, Report for America Corps Member"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/el-perico.com\/es\/lo-que-necesitan-comprender-los-trabajadores-de-la-construccion-en-omaha-para-su-seguridad\/#article","isPartOf":{"@id":"https:\/\/el-perico.com\/es\/lo-que-necesitan-comprender-los-trabajadores-de-la-construccion-en-omaha-para-su-seguridad\/"},"author":{"name":"Bridget Fogarty, Report for America Corps Member","@id":"https:\/\/el-perico.com\/es\/#\/schema\/person\/c3c9a4c7cd6206a5b46fb472eff94bba"},"headline":"Lo que necesitan entender los trabajadores de la construcci\u00f3n en Omaha para su seguridad","datePublished":"2023-02-01T13:00:00+00:00","dateModified":"2023-02-01T16:55:17+00:00","mainEntityOfPage":{"@id":"https:\/\/el-perico.com\/es\/lo-que-necesitan-comprender-los-trabajadores-de-la-construccion-en-omaha-para-su-seguridad\/"},"wordCount":816,"commentCount":0,"publisher":{"@id":"https:\/\/el-perico.com\/es\/#organization"},"image":{"@id":"https:\/\/el-perico.com\/es\/lo-que-necesitan-comprender-los-trabajadores-de-la-construccion-en-omaha-para-su-seguridad\/#primaryimage"},"thumbnailUrl":"https:\/\/el-perico.com\/wp-content\/uploads\/2023\/02\/1_Trabajadores_PenelopeLeon-scaled.jpg","keywords":["Health and Safety Training Institute","Heartland Workers Center","Instituto de Entrenamiento de Salud y Seguridad","Oficina de Estad\u00edsticas Laborales","Omaha","Omaha construcci\u00f3n","Pen\u00e9lope Le\u00f3n","Ruiz Construction","trabajo de construcci\u00f3n"],"articleSection":["Eventos","Inmigracion","La Vida Americana","Reportaje"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/el-perico.com\/es\/lo-que-necesitan-comprender-los-trabajadores-de-la-construccion-en-omaha-para-su-seguridad\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/el-perico.com\/es\/lo-que-necesitan-comprender-los-trabajadores-de-la-construccion-en-omaha-para-su-seguridad\/","url":"https:\/\/el-perico.com\/es\/lo-que-necesitan-comprender-los-trabajadores-de-la-construccion-en-omaha-para-su-seguridad\/","name":"Lo que necesitan entender los trabajadores de la construcci\u00f3n en Omaha para su seguridad - el perico","isPartOf":{"@id":"https:\/\/el-perico.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/el-perico.com\/es\/lo-que-necesitan-comprender-los-trabajadores-de-la-construccion-en-omaha-para-su-seguridad\/#primaryimage"},"image":{"@id":"https:\/\/el-perico.com\/es\/lo-que-necesitan-comprender-los-trabajadores-de-la-construccion-en-omaha-para-su-seguridad\/#primaryimage"},"thumbnailUrl":"https:\/\/el-perico.com\/wp-content\/uploads\/2023\/02\/1_Trabajadores_PenelopeLeon-scaled.jpg","datePublished":"2023-02-01T13:00:00+00:00","dateModified":"2023-02-01T16:55:17+00:00","breadcrumb":{"@id":"https:\/\/el-perico.com\/es\/lo-que-necesitan-comprender-los-trabajadores-de-la-construccion-en-omaha-para-su-seguridad\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/el-perico.com\/es\/lo-que-necesitan-comprender-los-trabajadores-de-la-construccion-en-omaha-para-su-seguridad\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/el-perico.com\/es\/lo-que-necesitan-comprender-los-trabajadores-de-la-construccion-en-omaha-para-su-seguridad\/#primaryimage","url":"https:\/\/el-perico.com\/wp-content\/uploads\/2023\/02\/1_Trabajadores_PenelopeLeon-scaled.jpg","contentUrl":"https:\/\/el-perico.com\/wp-content\/uploads\/2023\/02\/1_Trabajadores_PenelopeLeon-scaled.jpg","width":2560,"height":1920},{"@type":"BreadcrumbList","@id":"https:\/\/el-perico.com\/es\/lo-que-necesitan-comprender-los-trabajadores-de-la-construccion-en-omaha-para-su-seguridad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/el-perico.com\/es\/"},{"@type":"ListItem","position":2,"name":"Lo que necesitan entender los trabajadores de la construcci\u00f3n en Omaha para su seguridad"}]},{"@type":"WebSite","@id":"https:\/\/el-perico.com\/es\/#website","url":"https:\/\/el-perico.com\/es\/","name":"el perico","description":"La plataforma original de noticias e informaci\u00f3n para la comunidad hispana de Omaha","publisher":{"@id":"https:\/\/el-perico.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/el-perico.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/el-perico.com\/es\/#organization","name":"el perico","url":"https:\/\/el-perico.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/el-perico.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/el-perico.com\/wp-content\/uploads\/2024\/05\/ElPerico-Logo_NPM-1-e1717102187440.png","contentUrl":"https:\/\/el-perico.com\/wp-content\/uploads\/2024\/05\/ElPerico-Logo_NPM-1-e1717102187440.png","width":648,"height":216,"caption":"el perico"},"image":{"@id":"https:\/\/el-perico.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/elpericoomaha"]},{"@type":"Person","@id":"https:\/\/el-perico.com\/es\/#\/schema\/person\/c3c9a4c7cd6206a5b46fb472eff94bba","name":"Bridget Fogarty, Report for America Corps Member","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/cd24cc6ab228b710e2b4d7220545b2b721779200a44f3e80f3c94559fe9a16cb?s=96&d=mm&r=ged5896247ed259e9e7dbf3d4b3b2e52d","url":"https:\/\/secure.gravatar.com\/avatar\/cd24cc6ab228b710e2b4d7220545b2b721779200a44f3e80f3c94559fe9a16cb?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cd24cc6ab228b710e2b4d7220545b2b721779200a44f3e80f3c94559fe9a16cb?s=96&d=mm&r=g","caption":"Bridget Fogarty, Report for America Corps Member"},"description":"Bridget Fogarty is a Report for America Corps member reporting with El Perico and its English sister publication The Reader.","url":"https:\/\/el-perico.com\/es\/author\/bridget-fogarty\/"}]}},"_links":{"self":[{"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/posts\/8908","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/comments?post=8908"}],"version-history":[{"count":4,"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/posts\/8908\/revisions"}],"predecessor-version":[{"id":8949,"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/posts\/8908\/revisions\/8949"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/media\/8899"}],"wp:attachment":[{"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/media?parent=8908"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/categories?post=8908"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/tags?post=8908"},{"taxonomy":"newspack_spnsrs_tax","embeddable":true,"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/newspack_spnsrs_tax?post=8908"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/coauthors?post=8908"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}