{"id":4304,"date":"2020-12-03T16:43:56","date_gmt":"2020-12-03T21:43:56","guid":{"rendered":"https:\/\/el-perico.com\/?p=4304"},"modified":"2022-03-03T21:08:12","modified_gmt":"2022-03-04T02:08:12","slug":"me-la-pongo-o-no-el-dilema-que-ahora-viven-los-latinos-de-omaha-sobre-la-vacuna-contra-el-covid-19","status":"publish","type":"post","link":"https:\/\/el-perico.com\/es\/me-la-pongo-o-no-el-dilema-que-ahora-viven-los-latinos-de-omaha-sobre-la-vacuna-contra-el-covid-19\/","title":{"rendered":"\u00bfMe la pongo o no? El dilema que ahora viven los latinos de Omaha sobre la vacuna contra el COVID-19"},"content":{"rendered":"<p data-header=\"0\" data-textformat=\"{&quot;ff&quot;:&quot;Carlito&quot;,&quot;fv&quot;:&quot;normal&quot;,&quot;td&quot;:&quot;none&quot;,&quot;cs&quot;:&quot;0pt&quot;,&quot;fw&quot;:&quot;bold&quot;,&quot;fgc&quot;:&quot;rgb(0, 0, 0)&quot;,&quot;size&quot;:&quot;16.00&quot;,&quot;va&quot;:&quot;baseline&quot;,&quot;type&quot;:&quot;text&quot;,&quot;fs&quot;:&quot;normal&quot;,&quot;bgc&quot;:&quot;rgba(0, 0, 0, 0)&quot;}\" data-margin-bottom=\"8pt\" data-hd-info=\"0\" data-doc-id=\"7706799000001220001\" data-doc-type=\"writer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-4305\" src=\"https:\/\/el-perico.com\/wp-content\/uploads\/2020\/12\/Doctores-SP-1-300x169.png\" alt=\"\" width=\"888\" height=\"500\"><\/p>\n<p class=\"zw-paragraph heading0\" data-header=\"0\" data-textformat=\"{&quot;ff&quot;:&quot;Roboto&quot;,&quot;fgc&quot;:&quot;rgb(0, 0, 0)&quot;,&quot;size&quot;:&quot;12&quot;,&quot;type&quot;:&quot;text&quot;}\" data-margin-bottom=\"8pt\" data-hd-info=\"0\">Uso del cubre bocas, la distancia f\u00edsica, el aislamiento y qu\u00e9date en casa han sido las frases comunes que han servido de campa\u00f1a para prevenir el contagio del COVID-19, virus que ha cobrado millones de vidas desde el primer trimestre del a\u00f1o y que tambi\u00e9n ha afectado en gran parte a la comunidad latina en Omaha.<\/p>\n<p class=\"zw-paragraph heading0\" data-header=\"0\" data-textformat=\"{&quot;ff&quot;:&quot;Roboto&quot;,&quot;fgc&quot;:&quot;rgb(0, 0, 0)&quot;,&quot;size&quot;:&quot;12&quot;,&quot;type&quot;:&quot;text&quot;}\" data-margin-bottom=\"8pt\" data-hd-info=\"0\">M\u00e1s all\u00e1 de las medidas de prevenci\u00f3n que ya se conocen y se han reiterado por varios medios de comunicaci\u00f3n, el pasado 18 de noviembre seis expertos de la salud en Omaha, cinco de ellos hispanohablantes, pusieron esta vez sobre el tapete el tema que ahora preocupa: la vacuna contra el nuevo coronavirus.<\/p>\n<p class=\"zw-paragraph heading0\" data-header=\"0\" data-textformat=\"{&quot;ff&quot;:&quot;Roboto&quot;,&quot;fgc&quot;:&quot;rgb(0, 0, 0)&quot;,&quot;size&quot;:&quot;12&quot;,&quot;type&quot;:&quot;text&quot;}\" data-margin-bottom=\"8pt\" data-hd-info=\"0\">En septiembre de este a\u00f1o las empresas Johnson &amp; Johnson y AstraZeneca, que estaban desarrollando una vacuna, tuvieron que suspender los ensayos porque los voluntarios sufrieron efectos secundarios graves y \u201cenfermedades inexplicables\u201d. No obstante, otras farmac\u00e9uticas continuaron con sus estudios y ahora van en su fase III. Todas est\u00e1n peleando por el \u00ab\u00a1Eureka!\u00bb a la vacuna.<\/p>\n<p class=\"zw-paragraph heading0\" data-header=\"0\" data-textformat=\"{&quot;ff&quot;:&quot;Roboto&quot;,&quot;fgc&quot;:&quot;rgb(0, 0, 0)&quot;,&quot;size&quot;:&quot;12&quot;,&quot;type&quot;:&quot;text&quot;}\" data-margin-bottom=\"8pt\" data-hd-info=\"0\">Este sentimiento de incertidumbre alert\u00f3 tambi\u00e9n a la comunidad latina a la que nos aproximamos para conocer sus impresiones sobre este tema.<\/p>\n<p class=\"zw-paragraph heading0\" data-header=\"0\" data-textformat=\"{&quot;ff&quot;:&quot;Roboto&quot;,&quot;fgc&quot;:&quot;rgb(0, 0, 0)&quot;,&quot;size&quot;:&quot;12&quot;,&quot;type&quot;:&quot;text&quot;}\" data-margin-bottom=\"8pt\" data-hd-info=\"0\"><strong>Opiniones encontradas<\/strong><\/p>\n<p class=\"zw-paragraph heading0\" data-header=\"0\" data-textformat=\"{&quot;ff&quot;:&quot;Roboto&quot;,&quot;fgc&quot;:&quot;rgb(0, 0, 0)&quot;,&quot;size&quot;:&quot;12&quot;,&quot;type&quot;:&quot;text&quot;}\" data-margin-bottom=\"8pt\" data-hd-info=\"0\">Por un lado, est\u00e1n quienes han padecido COVID-19 y consideran que esa es la soluci\u00f3n para evitar m\u00e1s contagios, entre tanto otros prefieren abstenerse y esperar a ver qu\u00e9 pasa.<\/p>\n<p class=\"zw-paragraph heading0\" data-header=\"0\" data-textformat=\"{&quot;ff&quot;:&quot;Roboto&quot;,&quot;fgc&quot;:&quot;rgb(0, 0, 0)&quot;,&quot;size&quot;:&quot;12&quot;,&quot;type&quot;:&quot;text&quot;}\" data-margin-bottom=\"8pt\" data-hd-info=\"0\">Giovanni B\u00e1rcenas tiene puestas las esperanzas en la vacuna y no dud\u00f3 en responder que s\u00ed se la pondr\u00eda porque lo considera necesario. \u201cEs una ayuda, sufr\u00ed de COVID, y qu\u00e9 bonito ser\u00eda que hubiera una vacuna para quitarnos ya esta peste\u201d, dijo.<\/p>\n<p class=\"zw-paragraph heading0\" data-header=\"0\" data-textformat=\"{&quot;ff&quot;:&quot;Roboto&quot;,&quot;fgc&quot;:&quot;rgb(0, 0, 0)&quot;,&quot;size&quot;:&quot;12&quot;,&quot;type&quot;:&quot;text&quot;}\" data-margin-bottom=\"8pt\" data-hd-info=\"0\">Por su parte Esmeralda Rodr\u00edguez quien tambi\u00e9n tuvo COVID-19, dijo que no quiere volver a vivir ese episodio y que tampoco quiere que ninguno de sus allegados lo viva por lo que dijo que se la pondr\u00eda, pero \u201cesperar\u00eda un poco para ver los efectos secundarios en otros, luego podr\u00eda vacunarme\u201d.<\/p>\n<p class=\"zw-paragraph heading0\" data-header=\"0\" data-textformat=\"{&quot;ff&quot;:&quot;Roboto&quot;,&quot;fgc&quot;:&quot;rgb(0, 0, 0)&quot;,&quot;size&quot;:&quot;12&quot;,&quot;type&quot;:&quot;text&quot;}\" data-margin-bottom=\"8pt\" data-hd-info=\"0\">Mar\u00eda Mendoza dijo que no tendr\u00eda problema en ponerse la vacuna de ser distribuida a todos. \u201cCon la vacuna todos nos beneficiar\u00edamos. La gente habla sobre los efectos secundarios de la vacuna, pero peores son los efectos del COVID-19 cuando lo tienes\u201d, asegur\u00f3.<\/p>\n<p class=\"zw-paragraph heading0\" data-header=\"0\" data-textformat=\"{&quot;ff&quot;:&quot;Roboto&quot;,&quot;fgc&quot;:&quot;rgb(0, 0, 0)&quot;,&quot;size&quot;:&quot;12&quot;,&quot;type&quot;:&quot;text&quot;}\" data-margin-bottom=\"8pt\" data-hd-info=\"0\">Entre tanto Salvador Alba consider\u00f3 que es importante informarse m\u00e1s sobre las vacunas. \u201cYo no me la pondr\u00eda porque no hay mucha informaci\u00f3n al respecto. Hay que saber qu\u00e9 contiene, en qu\u00e9 te beneficia y en qu\u00e9 te perjudica. He escuchado a especialistas que han afirmado que los pacientes tienen problemas. Te puede ayudar pero a la larga trae problemas de salud\u201d, dijo.<\/p>\n<p class=\"zw-paragraph heading0\" data-header=\"0\" data-textformat=\"{&quot;ff&quot;:&quot;Roboto&quot;,&quot;fgc&quot;:&quot;rgb(0, 0, 0)&quot;,&quot;size&quot;:&quot;12&quot;,&quot;type&quot;:&quot;text&quot;}\" data-margin-bottom=\"8pt\" data-hd-info=\"0\">Para Salvador la mejor vacuna es comer saludable y atenderse con productos naturales y seguir las reglas que ya se implementaron.<\/p>\n<p class=\"zw-paragraph heading0\" data-header=\"0\" data-textformat=\"{&quot;ff&quot;:&quot;Roboto&quot;,&quot;fgc&quot;:&quot;rgb(0, 0, 0)&quot;,&quot;size&quot;:&quot;12&quot;,&quot;type&quot;:&quot;text&quot;}\" data-margin-bottom=\"8pt\" data-hd-info=\"0\">Por \u00faltimo, Eleazar Moreno no conf\u00eda en que la vacuna sea una soluci\u00f3n para contrarrestar el COVID-19. \u201cNo me la pondr\u00eda a la primera. Necesito tener m\u00e1s informaci\u00f3n y los efectos que pueda tener. No tenemos mucha informaci\u00f3n y hay que ser cuidadoso. Pero, si no hay otra alternativa y lo piden, pues no queda de otra, pero no conocemos los efectos secundarios\u201d, dijo.<\/p>\n<p class=\"zw-paragraph heading0\" data-header=\"0\" data-textformat=\"{&quot;ff&quot;:&quot;Roboto&quot;,&quot;fgc&quot;:&quot;rgb(0, 0, 0)&quot;,&quot;size&quot;:&quot;12&quot;,&quot;type&quot;:&quot;text&quot;}\" data-margin-bottom=\"8pt\" data-hd-info=\"0\"><strong>M\u00e9dicos respondieron preguntas de la comunidad<\/strong><\/p>\n<p class=\"zw-paragraph heading0\" data-header=\"0\" data-textformat=\"{&quot;ff&quot;:&quot;Roboto&quot;,&quot;fgc&quot;:&quot;rgb(0, 0, 0)&quot;,&quot;size&quot;:&quot;12&quot;,&quot;type&quot;:&quot;text&quot;}\" data-margin-bottom=\"8pt\" data-hd-info=\"0\">La doctora Adi Pour, directora del Departamento de Salud del Condado de Douglas particip\u00f3 en una conferencia virtual dirigida a la comunidad hispana para tratar este tema junto con los m\u00e9dicos: Armando De Alba Rosales (Centro M\u00e9dico de la Universidad de Nebraska), Sara Hurtado Bares (Centro M\u00e9dico de la Universidad de Nebraska ), Shirley F.Delair (Pediatra de Enfermedades Infecciosas del Hospital Infantil y Centro M\u00e9dico), Alhel\u00ed Gastelum (internista Creighton Medical University) y Eduardo Herrera Lirio (ginec\u00f3logo y obstetra en CHI Health Clinic).<\/p>\n<p class=\"zw-paragraph heading0\" data-header=\"0\" data-textformat=\"{&quot;ff&quot;:&quot;Roboto&quot;,&quot;fgc&quot;:&quot;rgb(0, 0, 0)&quot;,&quot;size&quot;:&quot;12&quot;,&quot;type&quot;:&quot;text&quot;}\" data-margin-bottom=\"8pt\" data-hd-info=\"0\">La conferencia se hizo el 18 de noviembre a las 12 del mediod\u00eda a trav\u00e9s de la plataforma zoom y transmitida por las redes sociales. All\u00ed la doctora Pour record\u00f3 que el primer caso de COVID-19 conocido en Omaha se debi\u00f3 a una persona que hab\u00eda viajado a Gran Breta\u00f1a, donde el ya el virus estaba esparcido.<\/p>\n<p class=\"zw-paragraph heading0\" data-header=\"0\" data-textformat=\"{&quot;ff&quot;:&quot;Roboto&quot;,&quot;fgc&quot;:&quot;rgb(0, 0, 0)&quot;,&quot;size&quot;:&quot;12&quot;,&quot;type&quot;:&quot;text&quot;}\" data-margin-bottom=\"8pt\" data-hd-info=\"0\">Luego se conocieron brotes en las industrias de procesamiento de alimento en Nebraska, especialmente en el sur de Omaha. \u201cEl entorno en estas industrias hizo que fuera muy f\u00e1cil la transmisi\u00f3n del virus, muchas personas trabajando hombro con hombro en un espacio cerrado con poco o ning\u00fan equipo de protecci\u00f3n y sin buenas medidas de control de infecciones\u201d, agreg\u00f3.<\/p>\n<p class=\"zw-paragraph heading0\" data-header=\"0\" data-textformat=\"{&quot;ff&quot;:&quot;Roboto&quot;,&quot;fgc&quot;:&quot;rgb(0, 0, 0)&quot;,&quot;size&quot;:&quot;12&quot;,&quot;type&quot;:&quot;text&quot;}\" data-margin-bottom=\"8pt\" data-hd-info=\"0\">Ante las alertas y las recomendaciones de la Organizaci\u00f3n Mundial de la Salud (OMS), aunado a un clima de tensi\u00f3n pol\u00edtica, se tomat\u00f3n medidas estrictas para evitar m\u00e1s contagios.<\/p>\n<p class=\"zw-paragraph heading0\" data-header=\"0\" data-textformat=\"{&quot;ff&quot;:&quot;Roboto&quot;,&quot;fgc&quot;:&quot;rgb(0, 0, 0)&quot;,&quot;size&quot;:&quot;12&quot;,&quot;type&quot;:&quot;text&quot;}\" data-margin-bottom=\"8pt\" data-hd-info=\"0\">\u201cLa efectividad de esas medidas result\u00f3 en una disminuci\u00f3n significativa de casos en el sur de Omaha. Hubo varias semanas en el mes de junio en las que la carga de la infecci\u00f3n afect\u00f3 desproporcionadamente a la comunidad hispana y 54% de todos los casos en el condado de Douglas fueron hispanos. Por supuesto, la poblaci\u00f3n hispana constituye el 13% de la poblaci\u00f3n de este condado. Fue en ese momento que intentamos asegurarnos de que hubiera suficiente disponibilidad de pruebas en el Sur de Omaha\u201d, asegur\u00f3 Pour al inicio de la conferencia.<\/p>\n<p class=\"zw-paragraph heading0\" data-header=\"0\" data-textformat=\"{&quot;ff&quot;:&quot;Roboto&quot;,&quot;fgc&quot;:&quot;rgb(0, 0, 0)&quot;,&quot;size&quot;:&quot;12&quot;,&quot;type&quot;:&quot;text&quot;}\" data-margin-bottom=\"8pt\" data-hd-info=\"0\">Adem\u00e1s, dijo que durante las \u00faltimas 2 semanas de noviembre 16,9% de todos los casos de COVID-19 se encuentran en la poblaci\u00f3n hispana.<\/p>\n<p data-header=\"0\" data-textformat=\"{&quot;ff&quot;:&quot;Roboto&quot;,&quot;fgc&quot;:&quot;rgb(0, 0, 0)&quot;,&quot;size&quot;:&quot;12&quot;,&quot;type&quot;:&quot;text&quot;}\" data-margin-bottom=\"8pt\" data-hd-info=\"0\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-4306\" src=\"https:\/\/el-perico.com\/wp-content\/uploads\/2020\/12\/omaha-vacine-covid-1-300x190.png\" alt=\"\" width=\"744\" height=\"471\"><\/p>\n<p class=\"zw-paragraph heading0\" data-header=\"0\" data-textformat=\"{&quot;ff&quot;:&quot;Roboto&quot;,&quot;fgc&quot;:&quot;rgb(0, 0, 0)&quot;,&quot;size&quot;:&quot;12&quot;,&quot;type&quot;:&quot;text&quot;}\" data-margin-bottom=\"8pt\" data-hd-info=\"0\"><strong>La vacuna no es un suiche<\/strong><\/p>\n<p class=\"zw-paragraph heading0\" data-header=\"0\" data-textformat=\"{&quot;ff&quot;:&quot;Roboto&quot;,&quot;fgc&quot;:&quot;rgb(0, 0, 0)&quot;,&quot;size&quot;:&quot;12&quot;,&quot;type&quot;:&quot;text&quot;}\" data-margin-bottom=\"8pt\" data-hd-info=\"0\">Durante su intervenci\u00f3n doctor Armando De Alba Rosales vio con optimismo la llevada de la vacuna. Sin embargo, advirti\u00f3 que la vacuna no es una especie de interruptor que hace que todo desaparezca: \u201cHay que mantener las mismas medidas de prevenci\u00f3n hasta que se han tomado para seguir evitando contagios\u201d, dijo.<\/p>\n<p class=\"zw-paragraph heading0\" data-header=\"0\" data-textformat=\"{&quot;ff&quot;:&quot;Roboto&quot;,&quot;fgc&quot;:&quot;rgb(0, 0, 0)&quot;,&quot;size&quot;:&quot;12&quot;,&quot;type&quot;:&quot;text&quot;}\" data-margin-bottom=\"8pt\" data-hd-info=\"0\">Por su parte la doctora Pour dijo que las empresas Pfizer y Moderna est\u00e1n desarrollando para Estados Unidos estos inmunizadores contra el COVID-19 y afirm\u00f3 que ya han sido probadas en cuanto a seguridad y eficacia: \u201cambas son muy prometedoras con 95% y 94,5% de efectividad\u201d, opin\u00f3.<\/p>\n<p class=\"zw-paragraph heading0\" data-header=\"0\" data-textformat=\"{&quot;ff&quot;:&quot;Roboto&quot;,&quot;fgc&quot;:&quot;rgb(0, 0, 0)&quot;,&quot;size&quot;:&quot;12&quot;,&quot;type&quot;:&quot;text&quot;}\" data-margin-bottom=\"8pt\" data-hd-info=\"0\">Adem\u00e1s, inform\u00f3 que para finales de diciembre estar\u00eda lista para ser distribuida y esto se har\u00eda en dos fases. \u201cEsta primera etapa definir\u00e1 otras dos fases: 1A y 1B. La 1A estar\u00e1 destinada a los trabajadores de la salud que est\u00e9n en alto riesgo dado su contacto directo con pacientes con COVID en los hospitales\u201d, dijo.<\/p>\n<p class=\"zw-paragraph heading0\" data-header=\"0\" data-textformat=\"{&quot;ff&quot;:&quot;Roboto&quot;,&quot;fgc&quot;:&quot;rgb(0, 0, 0)&quot;,&quot;size&quot;:&quot;12&quot;,&quot;type&quot;:&quot;text&quot;}\" data-margin-bottom=\"8pt\" data-hd-info=\"0\">Agreg\u00f3 que la fase 1B se extender\u00eda a personas con alguna condici\u00f3n subyacente como la diabetes, c\u00e1ncer, enfermedades renales y tambi\u00e9n a personas mayores de 65 a\u00f1os. Adem\u00e1s, se agregar\u00eda a este grupo los trabajadores esenciales como bomberos, primeros auxilios, maestros y personal correccional.<\/p>\n<p class=\"zw-paragraph heading0\" data-header=\"0\" data-textformat=\"{&quot;ff&quot;:&quot;Roboto&quot;,&quot;fgc&quot;:&quot;rgb(0, 0, 0)&quot;,&quot;size&quot;:&quot;12&quot;,&quot;type&quot;:&quot;text&quot;}\" data-margin-bottom=\"8pt\" data-hd-info=\"0\">En este grupo entrar\u00edan los trabajadores de procesamiento de alimentos, los nativos estadounidenses y la comunidad de color (negros y latinos). Mientras, la fase 2 ser\u00eda dirigida y extendida a la poblaci\u00f3n en general.<\/p>\n<p class=\"zw-paragraph heading0\" data-header=\"0\" data-textformat=\"{&quot;ff&quot;:&quot;Roboto&quot;,&quot;fgc&quot;:&quot;rgb(0, 0, 0)&quot;,&quot;size&quot;:&quot;12&quot;,&quot;type&quot;:&quot;text&quot;}\" data-margin-bottom=\"8pt\" data-hd-info=\"0\">Por su parte, la especialista Shirley F.Delair aclar\u00f3 que para que las empresas Pfizer y Moderna puedan distribuir la vacuna deber\u00e1n tener el visto bueno de la Administraci\u00f3n de Medicamentos y Alimentos (Food and Drug Administration, FDA). Ambas farmac\u00e9uticas tendr\u00e1n que presentar las documentaciones necesarias ante la FDA para poder introducir la vacuna en determinado estado del pa\u00eds.<\/p>\n<p class=\"zw-paragraph heading0\" data-header=\"0\" data-textformat=\"{&quot;ff&quot;:&quot;Roboto&quot;,&quot;fgc&quot;:&quot;rgb(0, 0, 0)&quot;,&quot;size&quot;:&quot;12&quot;,&quot;type&quot;:&quot;text&quot;}\" data-margin-bottom=\"8pt\" data-hd-info=\"0\">Entre tanto, Sara Hurtado Bares, especialista de la UMNC, refiri\u00f3 la importancia de que la poblaci\u00f3n tenga en cuenta que en Estados Unidos se llevan controles muy estrictos para que una vacuna sea aprobada y distribuida a la poblaci\u00f3n: \u201cno se han saltado ninguno de los pasos ni controles\u201d, dijo.<\/p>\n<p class=\"zw-paragraph heading0\" data-header=\"0\" data-textformat=\"{&quot;ff&quot;:&quot;Roboto&quot;,&quot;fgc&quot;:&quot;rgb(0, 0, 0)&quot;,&quot;size&quot;:&quot;12&quot;,&quot;type&quot;:&quot;text&quot;}\" data-margin-bottom=\"8pt\" data-hd-info=\"0\"><strong>Costo de la vacuna<\/strong><\/p>\n<p class=\"zw-paragraph heading0\" data-header=\"0\" data-textformat=\"{&quot;ff&quot;:&quot;Roboto&quot;,&quot;fgc&quot;:&quot;rgb(0, 0, 0)&quot;,&quot;size&quot;:&quot;12&quot;,&quot;type&quot;:&quot;text&quot;}\" data-margin-bottom=\"8pt\" data-hd-info=\"0\">Las transaccionales farmac\u00e9uticas han afirmado que las vacunas van por la fase III, es decir, la \u00faltima de las etapas de ensayos que se han hecho en algunos estados del pa\u00eds como Rhode Island, Texas, Nuevo M\u00e9xico y Tennessee. Luego de esta fase vendr\u00eda un proceso de distribuci\u00f3n a otros estados en la cual a\u00fan no est\u00e1 especificado c\u00f3mo ser\u00e1.<\/p>\n<p class=\"zw-paragraph heading0\" data-header=\"0\" data-textformat=\"{&quot;ff&quot;:&quot;Roboto&quot;,&quot;fgc&quot;:&quot;rgb(0, 0, 0)&quot;,&quot;size&quot;:&quot;12&quot;,&quot;type&quot;:&quot;text&quot;}\" data-margin-bottom=\"8pt\" data-hd-info=\"0\">Vale destacar que la vacuna de Pfizer requiere ser transportada y almacenada a una temperatura de -70 grados cent\u00edgrados (-94\u00b0F), muy por debajo del promedio est\u00e1ndar de 2 a 8 grados cent\u00edgrados (36-46\u00b0F) de otras vacunas. Mientras que Moderna espera que la distribuci\u00f3n sea estable a temperaturas est\u00e1ndar del refrigerador de 2\u00ba a 8\u00ba durante 30 d\u00edas y se puede almacenar hasta 6 meses a -20\u00ba.<\/p>\n<p class=\"zw-paragraph heading0\" data-header=\"0\" data-textformat=\"{&quot;ff&quot;:&quot;Roboto&quot;,&quot;fgc&quot;:&quot;rgb(0, 0, 0)&quot;,&quot;size&quot;:&quot;12&quot;,&quot;type&quot;:&quot;text&quot;}\" data-margin-bottom=\"8pt\" data-hd-info=\"0\">En conferencia telef\u00f3nica para CNN el presidente ejecutivo de Moderna, St\u00e9phane Bancel, dijo que se est\u00e1 acordando con los gobiernos del mundo y ser\u00e1n responsable de los precios, agreg\u00f3 que el precio en peque\u00f1as cantidades de la vacuna hasta ahora han costado entre US$ 32 y US$ 37 por dosis y que Moderna cobrar\u00eda precios m\u00e1s bajos por vol\u00famenes m\u00e1s altos de la vacuna ARNm-1273.<\/p>\n<p>Mientras los estudios van avanzando nuestra situaci\u00f3n de pandemia puede pasar a ser endemia, pues la OMS advirti\u00f3 que el SARS-CoV-2, causante del COVID-19, podr\u00eda convertirse en un virus end\u00e9mico. Esto quiere decir el COVID-19 pasar\u00eda a ser parte de nuestro d\u00eda a d\u00eda como puede ser la gripe com\u00fan, catarro, VIH, varicela y muchas. Cada una de estas endemias tiene una vacuna salvo el caso del VIH que a\u00fan se est\u00e1 desarrollando.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Uso del cubre bocas, la distancia f\u00edsica, el aislamiento y qu\u00e9date en casa han sido las frases comunes que han servido de campa\u00f1a para prevenir el contagio del COVID-19, virus que ha cobrado millones de vidas desde el primer trimestre del a\u00f1o y que tambi\u00e9n ha afectado en gran parte a la comunidad latina en [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4305,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"newspack_ads_suppress_ads":false,"_newspack_byline_active":false,"_newspack_byline":"","newspack_hide_updated_date":false,"newspack_show_updated_date":false,"newspack_content_restriction_is_exempt":false,"newspack_featured_image_position":"","newspack_post_subtitle":"","newspack_article_summary_title":"Overview:","newspack_article_summary":"","footnotes":""},"categories":[44,46,45],"tags":[],"newspack_spnsrs_tax":[],"coauthors":[1233],"class_list":["post-4304","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-la-vida-americana","category-reportaje","category-salud","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00bfMe la pongo o no? El dilema que ahora viven los latinos de Omaha sobre la vacuna contra el COVID-19 - el perico<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/el-perico.com\/es\/me-la-pongo-o-no-el-dilema-que-ahora-viven-los-latinos-de-omaha-sobre-la-vacuna-contra-el-covid-19\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfMe la pongo o no? El dilema que ahora viven los latinos de Omaha sobre la vacuna contra el COVID-19 - el perico\" \/>\n<meta property=\"og:description\" content=\"Uso del cubre bocas, la distancia f\u00edsica, el aislamiento y qu\u00e9date en casa han sido las frases comunes que han servido de campa\u00f1a para prevenir el contagio del COVID-19, virus que ha cobrado millones de vidas desde el primer trimestre del a\u00f1o y que tambi\u00e9n ha afectado en gran parte a la comunidad latina en [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/el-perico.com\/es\/me-la-pongo-o-no-el-dilema-que-ahora-viven-los-latinos-de-omaha-sobre-la-vacuna-contra-el-covid-19\/\" \/>\n<meta property=\"og:site_name\" content=\"el perico\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/elpericoomaha\" \/>\n<meta property=\"article:published_time\" content=\"2020-12-03T21:43:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-03-04T02:08:12+00:00\" \/>\n<meta name=\"author\" content=\"El Perico Staff\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"El Perico Staff\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n\t<meta name=\"twitter:label3\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data3\" content=\"El Perico Staff\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/me-la-pongo-o-no-el-dilema-que-ahora-viven-los-latinos-de-omaha-sobre-la-vacuna-contra-el-covid-19\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/me-la-pongo-o-no-el-dilema-que-ahora-viven-los-latinos-de-omaha-sobre-la-vacuna-contra-el-covid-19\\\/\"},\"author\":{\"name\":\"El Perico Staff\",\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/#\\\/schema\\\/person\\\/1956e5e63b94d4bd0daf30675bdf4a93\"},\"headline\":\"\u00bfMe la pongo o no? El dilema que ahora viven los latinos de Omaha sobre la vacuna contra el COVID-19\",\"datePublished\":\"2020-12-03T21:43:56+00:00\",\"dateModified\":\"2022-03-04T02:08:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/me-la-pongo-o-no-el-dilema-que-ahora-viven-los-latinos-de-omaha-sobre-la-vacuna-contra-el-covid-19\\\/\"},\"wordCount\":1583,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/me-la-pongo-o-no-el-dilema-que-ahora-viven-los-latinos-de-omaha-sobre-la-vacuna-contra-el-covid-19\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"articleSection\":[\"La Vida Americana\",\"Reportaje\",\"Salud\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/el-perico.com\\\/es\\\/me-la-pongo-o-no-el-dilema-que-ahora-viven-los-latinos-de-omaha-sobre-la-vacuna-contra-el-covid-19\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/me-la-pongo-o-no-el-dilema-que-ahora-viven-los-latinos-de-omaha-sobre-la-vacuna-contra-el-covid-19\\\/\",\"url\":\"https:\\\/\\\/el-perico.com\\\/es\\\/me-la-pongo-o-no-el-dilema-que-ahora-viven-los-latinos-de-omaha-sobre-la-vacuna-contra-el-covid-19\\\/\",\"name\":\"\u00bfMe la pongo o no? El dilema que ahora viven los latinos de Omaha sobre la vacuna contra el COVID-19 - el perico\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/me-la-pongo-o-no-el-dilema-que-ahora-viven-los-latinos-de-omaha-sobre-la-vacuna-contra-el-covid-19\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/me-la-pongo-o-no-el-dilema-que-ahora-viven-los-latinos-de-omaha-sobre-la-vacuna-contra-el-covid-19\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2020-12-03T21:43:56+00:00\",\"dateModified\":\"2022-03-04T02:08:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/me-la-pongo-o-no-el-dilema-que-ahora-viven-los-latinos-de-omaha-sobre-la-vacuna-contra-el-covid-19\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/el-perico.com\\\/es\\\/me-la-pongo-o-no-el-dilema-que-ahora-viven-los-latinos-de-omaha-sobre-la-vacuna-contra-el-covid-19\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/me-la-pongo-o-no-el-dilema-que-ahora-viven-los-latinos-de-omaha-sobre-la-vacuna-contra-el-covid-19\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/me-la-pongo-o-no-el-dilema-que-ahora-viven-los-latinos-de-omaha-sobre-la-vacuna-contra-el-covid-19\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/el-perico.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfMe la pongo o no? El dilema que ahora viven los latinos de Omaha sobre la vacuna contra el COVID-19\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/el-perico.com\\\/es\\\/\",\"name\":\"el perico\",\"description\":\"La plataforma original de noticias e informaci\u00f3n para la comunidad hispana de Omaha\",\"publisher\":{\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/el-perico.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/#organization\",\"name\":\"el perico\",\"url\":\"https:\\\/\\\/el-perico.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/el-perico.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/ElPerico-Logo_NPM-1-e1717102187440.png\",\"contentUrl\":\"https:\\\/\\\/el-perico.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/ElPerico-Logo_NPM-1-e1717102187440.png\",\"width\":648,\"height\":216,\"caption\":\"el perico\"},\"image\":{\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/elpericoomaha\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/#\\\/schema\\\/person\\\/1956e5e63b94d4bd0daf30675bdf4a93\",\"name\":\"El Perico Staff\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/701b23c665bfde9fd4d874d31feb4c16bf2ac173b2b0b7224dc39896d4cfc381?s=96&d=mm&r=g80b2efc5844e688a6ffb9340c789e4c4\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/701b23c665bfde9fd4d874d31feb4c16bf2ac173b2b0b7224dc39896d4cfc381?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/701b23c665bfde9fd4d874d31feb4c16bf2ac173b2b0b7224dc39896d4cfc381?s=96&d=mm&r=g\",\"caption\":\"El Perico Staff\"},\"sameAs\":[\"https:\\\/\\\/el-perico.com\"],\"url\":\"https:\\\/\\\/el-perico.com\\\/es\\\/author\\\/af6f1d62_admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfMe la pongo o no? El dilema que ahora viven los latinos de Omaha sobre la vacuna contra el COVID-19 - el perico","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/el-perico.com\/es\/me-la-pongo-o-no-el-dilema-que-ahora-viven-los-latinos-de-omaha-sobre-la-vacuna-contra-el-covid-19\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfMe la pongo o no? El dilema que ahora viven los latinos de Omaha sobre la vacuna contra el COVID-19 - el perico","og_description":"Uso del cubre bocas, la distancia f\u00edsica, el aislamiento y qu\u00e9date en casa han sido las frases comunes que han servido de campa\u00f1a para prevenir el contagio del COVID-19, virus que ha cobrado millones de vidas desde el primer trimestre del a\u00f1o y que tambi\u00e9n ha afectado en gran parte a la comunidad latina en [&hellip;]","og_url":"https:\/\/el-perico.com\/es\/me-la-pongo-o-no-el-dilema-que-ahora-viven-los-latinos-de-omaha-sobre-la-vacuna-contra-el-covid-19\/","og_site_name":"el perico","article_publisher":"https:\/\/www.facebook.com\/elpericoomaha","article_published_time":"2020-12-03T21:43:56+00:00","article_modified_time":"2022-03-04T02:08:12+00:00","author":"El Perico Staff","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"El Perico Staff","Tiempo de lectura":"7 minutos","Written by":"El Perico Staff"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/el-perico.com\/es\/me-la-pongo-o-no-el-dilema-que-ahora-viven-los-latinos-de-omaha-sobre-la-vacuna-contra-el-covid-19\/#article","isPartOf":{"@id":"https:\/\/el-perico.com\/es\/me-la-pongo-o-no-el-dilema-que-ahora-viven-los-latinos-de-omaha-sobre-la-vacuna-contra-el-covid-19\/"},"author":{"name":"El Perico Staff","@id":"https:\/\/el-perico.com\/es\/#\/schema\/person\/1956e5e63b94d4bd0daf30675bdf4a93"},"headline":"\u00bfMe la pongo o no? El dilema que ahora viven los latinos de Omaha sobre la vacuna contra el COVID-19","datePublished":"2020-12-03T21:43:56+00:00","dateModified":"2022-03-04T02:08:12+00:00","mainEntityOfPage":{"@id":"https:\/\/el-perico.com\/es\/me-la-pongo-o-no-el-dilema-que-ahora-viven-los-latinos-de-omaha-sobre-la-vacuna-contra-el-covid-19\/"},"wordCount":1583,"commentCount":0,"publisher":{"@id":"https:\/\/el-perico.com\/es\/#organization"},"image":{"@id":"https:\/\/el-perico.com\/es\/me-la-pongo-o-no-el-dilema-que-ahora-viven-los-latinos-de-omaha-sobre-la-vacuna-contra-el-covid-19\/#primaryimage"},"thumbnailUrl":"","articleSection":["La Vida Americana","Reportaje","Salud"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/el-perico.com\/es\/me-la-pongo-o-no-el-dilema-que-ahora-viven-los-latinos-de-omaha-sobre-la-vacuna-contra-el-covid-19\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/el-perico.com\/es\/me-la-pongo-o-no-el-dilema-que-ahora-viven-los-latinos-de-omaha-sobre-la-vacuna-contra-el-covid-19\/","url":"https:\/\/el-perico.com\/es\/me-la-pongo-o-no-el-dilema-que-ahora-viven-los-latinos-de-omaha-sobre-la-vacuna-contra-el-covid-19\/","name":"\u00bfMe la pongo o no? El dilema que ahora viven los latinos de Omaha sobre la vacuna contra el COVID-19 - el perico","isPartOf":{"@id":"https:\/\/el-perico.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/el-perico.com\/es\/me-la-pongo-o-no-el-dilema-que-ahora-viven-los-latinos-de-omaha-sobre-la-vacuna-contra-el-covid-19\/#primaryimage"},"image":{"@id":"https:\/\/el-perico.com\/es\/me-la-pongo-o-no-el-dilema-que-ahora-viven-los-latinos-de-omaha-sobre-la-vacuna-contra-el-covid-19\/#primaryimage"},"thumbnailUrl":"","datePublished":"2020-12-03T21:43:56+00:00","dateModified":"2022-03-04T02:08:12+00:00","breadcrumb":{"@id":"https:\/\/el-perico.com\/es\/me-la-pongo-o-no-el-dilema-que-ahora-viven-los-latinos-de-omaha-sobre-la-vacuna-contra-el-covid-19\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/el-perico.com\/es\/me-la-pongo-o-no-el-dilema-que-ahora-viven-los-latinos-de-omaha-sobre-la-vacuna-contra-el-covid-19\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/el-perico.com\/es\/me-la-pongo-o-no-el-dilema-que-ahora-viven-los-latinos-de-omaha-sobre-la-vacuna-contra-el-covid-19\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/el-perico.com\/es\/me-la-pongo-o-no-el-dilema-que-ahora-viven-los-latinos-de-omaha-sobre-la-vacuna-contra-el-covid-19\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/el-perico.com\/es\/"},{"@type":"ListItem","position":2,"name":"\u00bfMe la pongo o no? El dilema que ahora viven los latinos de Omaha sobre la vacuna contra el COVID-19"}]},{"@type":"WebSite","@id":"https:\/\/el-perico.com\/es\/#website","url":"https:\/\/el-perico.com\/es\/","name":"el perico","description":"La plataforma original de noticias e informaci\u00f3n para la comunidad hispana de Omaha","publisher":{"@id":"https:\/\/el-perico.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/el-perico.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/el-perico.com\/es\/#organization","name":"el perico","url":"https:\/\/el-perico.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/el-perico.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/el-perico.com\/wp-content\/uploads\/2024\/05\/ElPerico-Logo_NPM-1-e1717102187440.png","contentUrl":"https:\/\/el-perico.com\/wp-content\/uploads\/2024\/05\/ElPerico-Logo_NPM-1-e1717102187440.png","width":648,"height":216,"caption":"el perico"},"image":{"@id":"https:\/\/el-perico.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/elpericoomaha"]},{"@type":"Person","@id":"https:\/\/el-perico.com\/es\/#\/schema\/person\/1956e5e63b94d4bd0daf30675bdf4a93","name":"El Perico Staff","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/701b23c665bfde9fd4d874d31feb4c16bf2ac173b2b0b7224dc39896d4cfc381?s=96&d=mm&r=g80b2efc5844e688a6ffb9340c789e4c4","url":"https:\/\/secure.gravatar.com\/avatar\/701b23c665bfde9fd4d874d31feb4c16bf2ac173b2b0b7224dc39896d4cfc381?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/701b23c665bfde9fd4d874d31feb4c16bf2ac173b2b0b7224dc39896d4cfc381?s=96&d=mm&r=g","caption":"El Perico Staff"},"sameAs":["https:\/\/el-perico.com"],"url":"https:\/\/el-perico.com\/es\/author\/af6f1d62_admin\/"}]}},"_links":{"self":[{"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/posts\/4304","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/comments?post=4304"}],"version-history":[{"count":1,"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/posts\/4304\/revisions"}],"predecessor-version":[{"id":5970,"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/posts\/4304\/revisions\/5970"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/el-perico.com\/es\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/media?parent=4304"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/categories?post=4304"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/tags?post=4304"},{"taxonomy":"newspack_spnsrs_tax","embeddable":true,"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/newspack_spnsrs_tax?post=4304"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/coauthors?post=4304"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}