{"id":3728,"date":"2020-05-24T18:56:53","date_gmt":"2020-05-24T23:56:53","guid":{"rendered":"https:\/\/el-perico.com\/?p=3728"},"modified":"2022-03-08T18:21:02","modified_gmt":"2022-03-08T23:21:02","slug":"cercan-la-lucha-diaria-en-la-plaza-de-la-raza","status":"publish","type":"post","link":"https:\/\/el-perico.com\/es\/cercan-la-lucha-diaria-en-la-plaza-de-la-raza\/","title":{"rendered":"Cercan la lucha diaria en la Plaza de la Raza"},"content":{"rendered":"<p data-header=\"0\" data-textformat=\"{&quot;fgc&quot;:&quot;rgb(0, 0, 0)&quot;}\" data-margin-bottom=\"0pt\" data-hd-info=\"0\" data-doc-id=\"7706799000000549005\" data-doc-type=\"writer\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-3729 alignleft\" src=\"https:\/\/el-perico.com\/wp-content\/uploads\/2020\/05\/SPANISH-VErsion-300x200.jpg\" alt=\"\" width=\"414\" height=\"276\"><\/p>\n<p class=\"zw-paragraph heading0\" data-header=\"0\" data-textformat=\"{&quot;fgc&quot;:&quot;rgb(0, 0, 0)&quot;}\" data-margin-bottom=\"0pt\" data-hd-info=\"0\" data-doc-id=\"7706799000000549005\" data-doc-type=\"writer\"><em><strong>Por Bernardo Montoya<\/strong><\/em><\/p>\n<p class=\"zw-paragraph heading0\" data-header=\"0\" data-textformat=\"{&quot;fgc&quot;:&quot;rgb(0, 0, 0)&quot;}\" data-margin-bottom=\"0pt\" data-hd-info=\"0\">Isidoro de Jes\u00fas Cortez lleg\u00f3, como todas las ma\u00f1anas,&nbsp;a sentarse y a esperar en una de las jardiner\u00edas de la conocida Plaza de la Raza, ubicada en pleno coraz\u00f3n del sur de Omaha.<\/p>\n<p class=\"zw-paragraph heading0\" data-header=\"0\" data-textformat=\"{&quot;fgc&quot;:&quot;rgb(0, 0, 0)&quot;}\" data-margin-bottom=\"0pt\" data-hd-info=\"0\">Desde hace siete a\u00f1os, el hombre de 62 a\u00f1os, y con mucha vitalidad por delante, acude puntualmente como muchos otros, para ver lo que la suerte le depara en la b\u00fasqueda de alg\u00fan trabajo en dicho lugar.<\/p>\n<p class=\"zw-paragraph heading0\" data-header=\"0\" data-textformat=\"{&quot;fgc&quot;:&quot;rgb(0, 0, 0)&quot;}\" data-margin-bottom=\"0pt\" data-hd-info=\"0\">Su espera puede tomar largas horas o d\u00edas, hasta que alguien se acerca para ofrecerle unas migajas de horas o quiz\u00e1s d\u00edas de trabajo, si corre con suerte.<\/p>\n<p class=\"zw-paragraph heading0\" data-header=\"0\" data-textformat=\"{&quot;fgc&quot;:&quot;rgb(0, 0, 0)&quot;}\" data-margin-bottom=\"0pt\" data-hd-info=\"0\">\u201cLa primera vez llegue por que mi hijo me trajo. Pero \u00e9l se mud\u00f3 a California con su nueva esposa y yo prefer\u00ed quedarme\u2026\u201d, dijo Cortez en frente de otros 3 conocidos m\u00e1s, que estaban all\u00ed por el mismo objetivo: trabajar.<\/p>\n<p class=\"zw-paragraph heading0\" data-header=\"0\" data-textformat=\"{&quot;fgc&quot;:&quot;rgb(0, 0, 0)&quot;}\" data-margin-bottom=\"0pt\" data-hd-info=\"0\">El sol del medio d\u00eda fue intenso ese d\u00eda y transcurrieron las horas como si fueran eternas, pero solo lleg\u00f3 la oportunidad para una \u00abchamba\u00bb: cargar unos muebles para una mudanza.<\/p>\n<p class=\"zw-paragraph heading0\" data-header=\"0\" data-textformat=\"{&quot;fgc&quot;:&quot;rgb(0, 0, 0)&quot;}\" data-margin-bottom=\"0pt\" data-hd-info=\"0\">La \u00abvuelta\u00bb se hizo r\u00e1pido y efectivo. Todos regresaron para esperar por algo m\u00e1s. Pero de pronto, una patrulla del Departamento de Policia de Omaha se detuvo frente a ellos. La&nbsp;oficial Ruteena Alcantara se acerco con pasos tranquilos y les dijo que no pueden estar m\u00e1s ah\u00ed por medidas de prevenci\u00f3n para evitar contagios de COVID-19 y por \u00f3rdenes de la autoridades de Omaha.<\/p>\n<p class=\"zw-paragraph heading0\" data-header=\"0\" data-textformat=\"{&quot;fgc&quot;:&quot;rgb(0, 0, 0)&quot;}\" data-margin-bottom=\"0pt\" data-hd-info=\"0\">Sac\u00f3 una cinta amarilla y acordon\u00f3 con ella las jardiner\u00edas, bancos y las bicicletas en la adyacencias de la placita, ya que todo all\u00ed es considerado como un parque p\u00fablico y esta prohibido que las personas lo usen como lugar de reuni\u00f3n.<\/p>\n<p class=\"zw-paragraph heading0\" data-header=\"0\" data-textformat=\"{&quot;fgc&quot;:&quot;rgb(0, 0, 0)&quot;}\" data-margin-bottom=\"0pt\" data-hd-info=\"0\">\u201c\u00a1Nos acaba de dar en toda la torre!\u201d, dijo Isidoro con una profunda consternaci\u00f3n. \u201cNos dicen que ya no podemos estar aqu\u00ed buscando trabajo\u201d, agreg\u00f3.<\/p>\n<p class=\"zw-paragraph heading0\" data-header=\"0\" data-textformat=\"{&quot;fv&quot;:&quot;normal&quot;,&quot;td&quot;:&quot;none&quot;,&quot;cs&quot;:&quot;0pt&quot;,&quot;fw&quot;:&quot;none&quot;,&quot;fgc&quot;:&quot;rgb(0, 0, 0)&quot;,&quot;size&quot;:&quot;8.25&quot;,&quot;va&quot;:&quot;baseline&quot;,&quot;fw_i&quot;:400,&quot;type&quot;:&quot;text&quot;,&quot;fs&quot;:&quot;normal&quot;,&quot;bgc&quot;:&quot;rgba(0, 0, 0, 0)&quot;}\" data-margin-bottom=\"0pt\" data-hd-info=\"0\">La mayor\u00eda que se ve en la plaza son hombres hispanos inmigrantes. La plaza ha sido el punto de concentraci\u00f3n para aquellos que luchan diariamente para tener unos centavos en su bolsillo y que ven en eso la v\u00eda r\u00e1pida y digna de obtenerlo. Y m\u00e1s durante esta \u00e9poca de pandemia, en donde el \u00edndice de desempleo se dispar\u00f3 en todo el estado, Omaha no queda excento.<\/p>\n<p class=\"zw-paragraph heading0\" data-header=\"0\" data-textformat=\"{&quot;fgc&quot;:&quot;rgb(0, 0, 0)&quot;}\" data-margin-bottom=\"0pt\" data-hd-info=\"0\">A pesar de todo eso la oficial Ruteena cumpli\u00f3 con una ordenanza.<\/p>\n<p class=\"zw-paragraph heading0\" data-header=\"0\" data-textformat=\"{&quot;fgc&quot;:&quot;rgb(0, 0, 0)&quot;}\" data-margin-bottom=\"0pt\" data-hd-info=\"0\">El viento hab\u00eda rompi\u00f3 las cintas, como si fuera una se\u00f1al de injusticia ante la situaci\u00f3n, pero fue simplemente eso, el viento. La oficial reforz\u00f3 con m\u00e1s cinta pl\u00e1stica el per\u00edmetro de la plaza que estaba restringido. Se qued\u00f3 as\u00ed.<\/p>\n<p>\u201cNo s\u00e9 qu\u00e9 voy ha hacer. No hay trabajo y ahora no hay placita para buscar unos centavos. \u00a1Qu\u00e9 Dios nos ampare! y haber por cu\u00e1nto aguantamos\u2026\u201d, dijo cabizbajo Isidoro, mientras se alejaba del lugar.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Bernardo Montoya Isidoro de Jes\u00fas Cortez lleg\u00f3, como todas las ma\u00f1anas,&nbsp;a sentarse y a esperar en una de las jardiner\u00edas de la conocida Plaza de la Raza, ubicada en pleno coraz\u00f3n del sur de Omaha. Desde hace siete a\u00f1os, el hombre de 62 a\u00f1os, y con mucha vitalidad por delante, acude puntualmente como muchos [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3729,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"newspack_ads_suppress_ads":false,"_newspack_byline_active":false,"_newspack_byline":"","newspack_hide_updated_date":false,"newspack_show_updated_date":false,"newspack_content_restriction_is_exempt":false,"newspack_featured_image_position":"","newspack_post_subtitle":"","newspack_article_summary_title":"Overview:","newspack_article_summary":"","footnotes":""},"categories":[46],"tags":[],"newspack_spnsrs_tax":[],"coauthors":[1233],"class_list":["post-3728","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-reportaje","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cercan la lucha diaria en la Plaza de la Raza - el perico<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/el-perico.com\/es\/cercan-la-lucha-diaria-en-la-plaza-de-la-raza\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cercan la lucha diaria en la Plaza de la Raza - el perico\" \/>\n<meta property=\"og:description\" content=\"Por Bernardo Montoya Isidoro de Jes\u00fas Cortez lleg\u00f3, como todas las ma\u00f1anas,&nbsp;a sentarse y a esperar en una de las jardiner\u00edas de la conocida Plaza de la Raza, ubicada en pleno coraz\u00f3n del sur de Omaha. Desde hace siete a\u00f1os, el hombre de 62 a\u00f1os, y con mucha vitalidad por delante, acude puntualmente como muchos [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/el-perico.com\/es\/cercan-la-lucha-diaria-en-la-plaza-de-la-raza\/\" \/>\n<meta property=\"og:site_name\" content=\"el perico\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/elpericoomaha\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-24T23:56:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-03-08T23:21:02+00:00\" \/>\n<meta name=\"author\" content=\"El Perico Staff\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"El Perico Staff\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n\t<meta name=\"twitter:label3\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data3\" content=\"El Perico Staff\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/cercan-la-lucha-diaria-en-la-plaza-de-la-raza\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/cercan-la-lucha-diaria-en-la-plaza-de-la-raza\\\/\"},\"author\":{\"name\":\"El Perico Staff\",\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/#\\\/schema\\\/person\\\/1956e5e63b94d4bd0daf30675bdf4a93\"},\"headline\":\"Cercan la lucha diaria en la Plaza de la Raza\",\"datePublished\":\"2020-05-24T23:56:53+00:00\",\"dateModified\":\"2022-03-08T23:21:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/cercan-la-lucha-diaria-en-la-plaza-de-la-raza\\\/\"},\"wordCount\":504,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/cercan-la-lucha-diaria-en-la-plaza-de-la-raza\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"articleSection\":[\"Reportaje\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/el-perico.com\\\/es\\\/cercan-la-lucha-diaria-en-la-plaza-de-la-raza\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/cercan-la-lucha-diaria-en-la-plaza-de-la-raza\\\/\",\"url\":\"https:\\\/\\\/el-perico.com\\\/es\\\/cercan-la-lucha-diaria-en-la-plaza-de-la-raza\\\/\",\"name\":\"Cercan la lucha diaria en la Plaza de la Raza - el perico\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/cercan-la-lucha-diaria-en-la-plaza-de-la-raza\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/cercan-la-lucha-diaria-en-la-plaza-de-la-raza\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2020-05-24T23:56:53+00:00\",\"dateModified\":\"2022-03-08T23:21:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/cercan-la-lucha-diaria-en-la-plaza-de-la-raza\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/el-perico.com\\\/es\\\/cercan-la-lucha-diaria-en-la-plaza-de-la-raza\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/cercan-la-lucha-diaria-en-la-plaza-de-la-raza\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/cercan-la-lucha-diaria-en-la-plaza-de-la-raza\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/el-perico.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cercan la lucha diaria en la Plaza de la Raza\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/el-perico.com\\\/es\\\/\",\"name\":\"el perico\",\"description\":\"La plataforma original de noticias e informaci\u00f3n para la comunidad hispana de Omaha\",\"publisher\":{\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/el-perico.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/#organization\",\"name\":\"el perico\",\"url\":\"https:\\\/\\\/el-perico.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/el-perico.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/ElPerico-Logo_NPM-1-e1717102187440.png\",\"contentUrl\":\"https:\\\/\\\/el-perico.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/ElPerico-Logo_NPM-1-e1717102187440.png\",\"width\":648,\"height\":216,\"caption\":\"el perico\"},\"image\":{\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/elpericoomaha\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/#\\\/schema\\\/person\\\/1956e5e63b94d4bd0daf30675bdf4a93\",\"name\":\"El Perico Staff\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/701b23c665bfde9fd4d874d31feb4c16bf2ac173b2b0b7224dc39896d4cfc381?s=96&d=mm&r=g80b2efc5844e688a6ffb9340c789e4c4\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/701b23c665bfde9fd4d874d31feb4c16bf2ac173b2b0b7224dc39896d4cfc381?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/701b23c665bfde9fd4d874d31feb4c16bf2ac173b2b0b7224dc39896d4cfc381?s=96&d=mm&r=g\",\"caption\":\"El Perico Staff\"},\"sameAs\":[\"https:\\\/\\\/el-perico.com\"],\"url\":\"https:\\\/\\\/el-perico.com\\\/es\\\/author\\\/af6f1d62_admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cercan la lucha diaria en la Plaza de la Raza - el perico","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/el-perico.com\/es\/cercan-la-lucha-diaria-en-la-plaza-de-la-raza\/","og_locale":"es_ES","og_type":"article","og_title":"Cercan la lucha diaria en la Plaza de la Raza - el perico","og_description":"Por Bernardo Montoya Isidoro de Jes\u00fas Cortez lleg\u00f3, como todas las ma\u00f1anas,&nbsp;a sentarse y a esperar en una de las jardiner\u00edas de la conocida Plaza de la Raza, ubicada en pleno coraz\u00f3n del sur de Omaha. Desde hace siete a\u00f1os, el hombre de 62 a\u00f1os, y con mucha vitalidad por delante, acude puntualmente como muchos [&hellip;]","og_url":"https:\/\/el-perico.com\/es\/cercan-la-lucha-diaria-en-la-plaza-de-la-raza\/","og_site_name":"el perico","article_publisher":"https:\/\/www.facebook.com\/elpericoomaha","article_published_time":"2020-05-24T23:56:53+00:00","article_modified_time":"2022-03-08T23:21:02+00:00","author":"El Perico Staff","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"El Perico Staff","Tiempo de lectura":"2 minutos","Written by":"El Perico Staff"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/el-perico.com\/es\/cercan-la-lucha-diaria-en-la-plaza-de-la-raza\/#article","isPartOf":{"@id":"https:\/\/el-perico.com\/es\/cercan-la-lucha-diaria-en-la-plaza-de-la-raza\/"},"author":{"name":"El Perico Staff","@id":"https:\/\/el-perico.com\/es\/#\/schema\/person\/1956e5e63b94d4bd0daf30675bdf4a93"},"headline":"Cercan la lucha diaria en la Plaza de la Raza","datePublished":"2020-05-24T23:56:53+00:00","dateModified":"2022-03-08T23:21:02+00:00","mainEntityOfPage":{"@id":"https:\/\/el-perico.com\/es\/cercan-la-lucha-diaria-en-la-plaza-de-la-raza\/"},"wordCount":504,"commentCount":0,"publisher":{"@id":"https:\/\/el-perico.com\/es\/#organization"},"image":{"@id":"https:\/\/el-perico.com\/es\/cercan-la-lucha-diaria-en-la-plaza-de-la-raza\/#primaryimage"},"thumbnailUrl":"","articleSection":["Reportaje"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/el-perico.com\/es\/cercan-la-lucha-diaria-en-la-plaza-de-la-raza\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/el-perico.com\/es\/cercan-la-lucha-diaria-en-la-plaza-de-la-raza\/","url":"https:\/\/el-perico.com\/es\/cercan-la-lucha-diaria-en-la-plaza-de-la-raza\/","name":"Cercan la lucha diaria en la Plaza de la Raza - el perico","isPartOf":{"@id":"https:\/\/el-perico.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/el-perico.com\/es\/cercan-la-lucha-diaria-en-la-plaza-de-la-raza\/#primaryimage"},"image":{"@id":"https:\/\/el-perico.com\/es\/cercan-la-lucha-diaria-en-la-plaza-de-la-raza\/#primaryimage"},"thumbnailUrl":"","datePublished":"2020-05-24T23:56:53+00:00","dateModified":"2022-03-08T23:21:02+00:00","breadcrumb":{"@id":"https:\/\/el-perico.com\/es\/cercan-la-lucha-diaria-en-la-plaza-de-la-raza\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/el-perico.com\/es\/cercan-la-lucha-diaria-en-la-plaza-de-la-raza\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/el-perico.com\/es\/cercan-la-lucha-diaria-en-la-plaza-de-la-raza\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/el-perico.com\/es\/cercan-la-lucha-diaria-en-la-plaza-de-la-raza\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/el-perico.com\/es\/"},{"@type":"ListItem","position":2,"name":"Cercan la lucha diaria en la Plaza de la Raza"}]},{"@type":"WebSite","@id":"https:\/\/el-perico.com\/es\/#website","url":"https:\/\/el-perico.com\/es\/","name":"el perico","description":"La plataforma original de noticias e informaci\u00f3n para la comunidad hispana de Omaha","publisher":{"@id":"https:\/\/el-perico.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/el-perico.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/el-perico.com\/es\/#organization","name":"el perico","url":"https:\/\/el-perico.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/el-perico.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/el-perico.com\/wp-content\/uploads\/2024\/05\/ElPerico-Logo_NPM-1-e1717102187440.png","contentUrl":"https:\/\/el-perico.com\/wp-content\/uploads\/2024\/05\/ElPerico-Logo_NPM-1-e1717102187440.png","width":648,"height":216,"caption":"el perico"},"image":{"@id":"https:\/\/el-perico.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/elpericoomaha"]},{"@type":"Person","@id":"https:\/\/el-perico.com\/es\/#\/schema\/person\/1956e5e63b94d4bd0daf30675bdf4a93","name":"El Perico Staff","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/701b23c665bfde9fd4d874d31feb4c16bf2ac173b2b0b7224dc39896d4cfc381?s=96&d=mm&r=g80b2efc5844e688a6ffb9340c789e4c4","url":"https:\/\/secure.gravatar.com\/avatar\/701b23c665bfde9fd4d874d31feb4c16bf2ac173b2b0b7224dc39896d4cfc381?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/701b23c665bfde9fd4d874d31feb4c16bf2ac173b2b0b7224dc39896d4cfc381?s=96&d=mm&r=g","caption":"El Perico Staff"},"sameAs":["https:\/\/el-perico.com"],"url":"https:\/\/el-perico.com\/es\/author\/af6f1d62_admin\/"}]}},"_links":{"self":[{"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/posts\/3728","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/comments?post=3728"}],"version-history":[{"count":1,"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/posts\/3728\/revisions"}],"predecessor-version":[{"id":6136,"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/posts\/3728\/revisions\/6136"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/el-perico.com\/es\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/media?parent=3728"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/categories?post=3728"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/tags?post=3728"},{"taxonomy":"newspack_spnsrs_tax","embeddable":true,"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/newspack_spnsrs_tax?post=3728"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/coauthors?post=3728"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}