{"id":3583,"date":"2020-04-28T20:24:05","date_gmt":"2020-04-29T01:24:05","guid":{"rendered":"https:\/\/el-perico.com\/?p=3583"},"modified":"2022-03-08T18:47:06","modified_gmt":"2022-03-08T23:47:06","slug":"las-escuelas-publicas-de-omaha-continuan-sirviendo-a-estudiantes-y-familias","status":"publish","type":"post","link":"https:\/\/el-perico.com\/es\/las-escuelas-publicas-de-omaha-continuan-sirviendo-a-estudiantes-y-familias\/","title":{"rendered":"Las Escuelas P\u00fablicas de Omaha contin\u00faan sirviendo a estudiantes y familias"},"content":{"rendered":"<p data-header=\"0\" data-margin-bottom=\"0pt\" data-hd-info=\"0\" data-doc-id=\"7706799000000539027\" data-doc-type=\"writer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone  wp-image-3584\" src=\"https:\/\/el-perico.com\/wp-content\/uploads\/2020\/04\/Vicky-Florian-nutrition-services-supervisor-organizing-meals-at-a-recent-distribution-outside-Gateway-Elementary-300x225.jpg\" alt=\"\" width=\"709\" height=\"532\"><\/p>\n<p data-header=\"0\" data-margin-bottom=\"0pt\" data-hd-info=\"0\" data-doc-id=\"7706799000000539027\" data-doc-type=\"writer\"><strong>By Johana Le Flores, activista comunitaria de artes<\/strong><\/p>\n<p class=\"zw-paragraph heading0\" data-header=\"0\" data-margin-bottom=\"0pt\" data-hd-info=\"0\" data-doc-id=\"7706799000000539027\" data-doc-type=\"writer\">Desde que se pas\u00f3 al aprendizaje a distancia en todos los distritos escolares del \u00e1rea, las Escuelas P\u00fablicas de Omaha (OPS) han trabajado para ayudar y mantener a flote esta vez a sus 53.552 estudiantes. Las principales prioridades son involucrar a los estudiantes y dirigirlos a tener alimentos. Si bien las escuelas est\u00e1n f\u00edsicamente cerradas, los esfuerzos continuos se centran en terminar el a\u00f1o acad\u00e9mico con buena cara mientras se preparan para un comienzo seguro y productivo para el pr\u00f3ximo a\u00f1o escolar.<\/p>\n<p class=\"zw-paragraph heading0\" data-header=\"0\" data-margin-bottom=\"0pt\" data-hd-info=\"0\">Durante la primera reuni\u00f3n virtual de la Junta de Educaci\u00f3n de OPS celebrada el 15 de abril, la Superintendente Dra. Cheryl Logan detall\u00f3 estos esfuerzos.<\/p>\n<p class=\"zw-paragraph heading0\" data-header=\"0\" data-textformat=\"{&quot;fw&quot;:&quot;bold&quot;,&quot;type&quot;:&quot;text&quot;}\" data-margin-bottom=\"0pt\" data-hd-info=\"0\"><strong>Oportunidades de aprendizaje virtual<\/strong><\/p>\n<p class=\"zw-paragraph heading0\" data-header=\"0\" data-margin-bottom=\"0pt\" data-hd-info=\"0\">\u00abNuestros maestros, directores y equipos de tecnolog\u00eda han dedicado innumerables horas a la migraci\u00f3n de lecciones en l\u00ednea para que nuestros estudiantes contin\u00faen aprendiendo en casa durante este tiempo sin precedentes cuando ellos mismos tambi\u00e9n est\u00e1n bajo estr\u00e9s y preocupaci\u00f3n por sus seres queridos y sus familias\u00bb, dijo el Dr. Logan .<\/p>\n<p class=\"zw-paragraph heading0\" data-header=\"0\" data-margin-bottom=\"0pt\" data-hd-info=\"0\">Desde el cierre de las escuelas, los maestros han proporcionado actividades semanales en l\u00ednea para los estudiantes. El distrito imprimi\u00f3<a href=\"https:\/\/district.ops.org\/DEPARTMENTS\/GeneralFinanceandAdministrativeServices\/DistrictCommunications\/AcademicResources.aspx\"> ocho semanas de paquetes de aprendizaje<\/a> de primaria espec\u00edficos para cada grado y materias como matem\u00e1ticas, lectura y escritura. Si bien no es necesario entregar f\u00edsicamente las tareas y las actividades, se recomienda que las familias traten asistir a los estudiantes para hacer las actividades durante el d\u00eda. Adem\u00e1s, se han proporcionado una serie de herramientas virtuales en una p\u00e1gina de recursos de aprendizaje a distancia de las Escuelas P\u00fablicas de Omaha.<\/p>\n<p class=\"zw-paragraph heading0\" data-header=\"0\" data-margin-bottom=\"0pt\" data-hd-info=\"0\">\u00abComo parte de nuestro trabajo inmediato para apoyar el aprendizaje de los estudiantes, estamos en el proceso de comprar 2.000 iPads adicionales para que los estudiantes los usen durante la escuela de verano\u00bb, comparti\u00f3 el Dr. Logan durante la \u00faltima reuni\u00f3n especial para la Junta de Educaci\u00f3n el 20 de abril 2020. \u201cAdem\u00e1s, estamos trabajando para eliminar algunos obst\u00e1culos que sabemos que algunas familias est\u00e1n experimentando actualmente en t\u00e9rminos de dispositivos y conectividad. Estamos planeando proporcionar a nuestro distrito escolar apoyos a nuestras familias lo mejor que podamos para minimizar la interrupci\u00f3n de la educaci\u00f3n de nuestros estudiantes \u00ab.<\/p>\n<p class=\"zw-paragraph heading0\" data-header=\"0\" data-textformat=\"{&quot;fw&quot;:&quot;bold&quot;,&quot;type&quot;:&quot;text&quot;}\" data-margin-bottom=\"0pt\" data-hd-info=\"0\"><strong>Lucha contra la inseguridad alimentaria<\/strong><\/p>\n<p class=\"zw-paragraph heading0\" data-header=\"0\" data-margin-bottom=\"0pt\" data-hd-info=\"0\">\u00abHemos servido m\u00e1s de 30.000 comidas a la semana a las familias de nuestra comunidad en las \u00faltimas semanas\u00bb, dijo el Dr. Logan, y agreg\u00f3 que otras distribuciones de comidas \u00abcontin\u00faan operando a trav\u00e9s de nuestra asociaci\u00f3n con Food Bank for the Heartland\u00bb.<\/p>\n<p class=\"zw-paragraph heading0\" data-header=\"0\" data-margin-bottom=\"0pt\" data-hd-info=\"0\">Actualmente, OPS Nutrition Services ofrece comidas para llevar todas las semanas a los ni\u00f1os que lo necesitan. Los lunes a las 11 a.m., las OPS ofrecen un paquete para llevar con una semana de desayunos y almuerzos para los estudiantes. Aqu\u00ed ocho lugares donde participan:<\/p>\n<p class=\"zw-list zw-paragraph heading0\" data-header=\"0\" data-textformat=\"{&quot;fgc&quot;:&quot;rgb(0, 0, 0)&quot;}\" data-margin-left=\"0.5in\" data-text-indent=\"-0.25in\" data-margin-bottom=\"0pt\" data-hd-info=\"0\" data-list-id=\"14869679\" data-list-info=\"{&quot;id&quot;:&quot;14869679&quot;,&quot;l&quot;:0}\"><!--Zoho writer list char starts--><span class=\"zw-list-char\">1.&nbsp;<\/span><!--Zoho writer list char starts ends-->Benson High<\/p>\n<p class=\"zw-list zw-paragraph heading0\" data-header=\"0\" data-textformat=\"{&quot;fgc&quot;:&quot;rgb(0, 0, 0)&quot;}\" data-margin-left=\"0.5in\" data-text-indent=\"-0.25in\" data-margin-bottom=\"0pt\" data-hd-info=\"0\" data-list-id=\"14869679\" data-list-info=\"{&quot;id&quot;:&quot;14869679&quot;,&quot;l&quot;:0}\"><!--Zoho writer list char starts--><span class=\"zw-list-char\">2.&nbsp;<\/span><!--Zoho writer list char starts ends-->Beveridge Middle<\/p>\n<p class=\"zw-list zw-paragraph heading0\" data-header=\"0\" data-textformat=\"{&quot;fgc&quot;:&quot;rgb(0, 0, 0)&quot;}\" data-margin-left=\"0.5in\" data-text-indent=\"-0.25in\" data-margin-bottom=\"0pt\" data-hd-info=\"0\" data-list-id=\"14869679\" data-list-info=\"{&quot;id&quot;:&quot;14869679&quot;,&quot;l&quot;:0}\"><!--Zoho writer list char starts--><span class=\"zw-list-char\">3.&nbsp;<\/span><!--Zoho writer list char starts ends-->Bryan Middle<\/p>\n<p class=\"zw-list zw-paragraph heading0\" data-header=\"0\" data-textformat=\"{&quot;fgc&quot;:&quot;rgb(0, 0, 0)&quot;}\" data-margin-left=\"0.5in\" data-text-indent=\"-0.25in\" data-margin-bottom=\"0pt\" data-hd-info=\"0\" data-list-id=\"14869679\" data-list-info=\"{&quot;id&quot;:&quot;14869679&quot;,&quot;l&quot;:0}\"><!--Zoho writer list char starts--><span class=\"zw-list-char\">4.&nbsp;<\/span><!--Zoho writer list char starts ends-->Gateway Elementary<\/p>\n<p class=\"zw-list zw-paragraph heading0\" data-header=\"0\" data-textformat=\"{&quot;fgc&quot;:&quot;rgb(0, 0, 0)&quot;}\" data-margin-left=\"0.5in\" data-text-indent=\"-0.25in\" data-margin-bottom=\"0pt\" data-hd-info=\"0\" data-list-id=\"14869679\" data-list-info=\"{&quot;id&quot;:&quot;14869679&quot;,&quot;l&quot;:0}\"><!--Zoho writer list char starts--><span class=\"zw-list-char\">5.&nbsp;<\/span><!--Zoho writer list char starts ends-->Nathan Hale Middle<\/p>\n<p class=\"zw-list zw-paragraph heading0\" data-header=\"0\" data-textformat=\"{&quot;fgc&quot;:&quot;rgb(0, 0, 0)&quot;}\" data-margin-left=\"0.5in\" data-text-indent=\"-0.25in\" data-margin-bottom=\"0pt\" data-hd-info=\"0\" data-list-id=\"14869679\" data-list-info=\"{&quot;id&quot;:&quot;14869679&quot;,&quot;l&quot;:0}\"><!--Zoho writer list char starts--><span class=\"zw-list-char\">6.&nbsp;<\/span><!--Zoho writer list char starts ends-->Norris Middle<\/p>\n<p class=\"zw-list zw-paragraph heading0\" data-header=\"0\" data-textformat=\"{&quot;fgc&quot;:&quot;rgb(0, 0, 0)&quot;}\" data-margin-left=\"0.5in\" data-text-indent=\"-0.25in\" data-margin-bottom=\"0pt\" data-hd-info=\"0\" data-list-id=\"14869679\" data-list-info=\"{&quot;id&quot;:&quot;14869679&quot;,&quot;l&quot;:0}\"><!--Zoho writer list char starts--><span class=\"zw-list-char\">7.&nbsp;<\/span><!--Zoho writer list char starts ends-->Skinner Magnet<\/p>\n<p class=\"zw-list zw-paragraph heading0\" data-header=\"0\" data-textformat=\"{&quot;fgc&quot;:&quot;rgb(0, 0, 0)&quot;}\" data-margin-left=\"0.5in\" data-text-indent=\"-0.25in\" data-margin-bottom=\"0pt\" data-hd-info=\"0\" data-list-id=\"14869679\" data-list-info=\"{&quot;id&quot;:&quot;14869679&quot;,&quot;l&quot;:0}\"><!--Zoho writer list char starts--><span class=\"zw-list-char\">8.&nbsp;<\/span><!--Zoho writer list char starts ends-->South High<\/p>\n<p class=\"zw-paragraph heading0\" data-header=\"0\" data-margin-bottom=\"0pt\" data-hd-info=\"0\">Al llegar a cada escuela, las familias conducir\u00e1n hasta all\u00ed para recoger la comida. Un paquete de comida estar\u00e1 disponible por estudiante o ni\u00f1o en el veh\u00edculo. Si no puede traer ni\u00f1os en el veh\u00edculo, el representante debe llevar una identificaci\u00f3n de estudiante, boleta de calificaciones u otra verificaci\u00f3n para cada estudiante.<\/p>\n<p class=\"zw-paragraph heading0\" data-header=\"0\" data-margin-bottom=\"0pt\" data-hd-info=\"0\">\u00abNos preocupamos y estamos aqu\u00ed por nuestros estudiantes\u00bb, dijo la directora de servicios de nutrici\u00f3n Tammy Yarmon. \u00abMe alegra que este apoyo pueda ayudar a los estudiantes a enfocarse en actividades de aprendizaje, lectura y mantenerse activos durante este tiempo\u00bb.<\/p>\n<p>Para obtener una lista de otros sitios de alimentaci\u00f3n comunitaria, visite&nbsp;<a href=\"https:\/\/foodbankheartland.org\/covid-19\/\">https:\/\/foodbankheartland.org\/covid-19\/<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>By Johana Le Flores, activista comunitaria de artes Desde que se pas\u00f3 al aprendizaje a distancia en todos los distritos escolares del \u00e1rea, las Escuelas P\u00fablicas de Omaha (OPS) han trabajado para ayudar y mantener a flote esta vez a sus 53.552 estudiantes. Las principales prioridades son involucrar a los estudiantes y dirigirlos a tener [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3584,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"newspack_ads_suppress_ads":false,"_newspack_byline_active":false,"_newspack_byline":"","newspack_hide_updated_date":false,"newspack_show_updated_date":false,"newspack_content_restriction_is_exempt":false,"newspack_featured_image_position":"","newspack_post_subtitle":"","newspack_article_summary_title":"Overview:","newspack_article_summary":"","footnotes":""},"categories":[46],"tags":[117,50,101],"newspack_spnsrs_tax":[],"coauthors":[1233],"class_list":["post-3583","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-reportaje","tag-comunidades","tag-covid-19","tag-foodbank","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Las Escuelas P\u00fablicas de Omaha contin\u00faan sirviendo a estudiantes y familias - el perico<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/el-perico.com\/es\/las-escuelas-publicas-de-omaha-continuan-sirviendo-a-estudiantes-y-familias\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Las Escuelas P\u00fablicas de Omaha contin\u00faan sirviendo a estudiantes y familias - el perico\" \/>\n<meta property=\"og:description\" content=\"By Johana Le Flores, activista comunitaria de artes Desde que se pas\u00f3 al aprendizaje a distancia en todos los distritos escolares del \u00e1rea, las Escuelas P\u00fablicas de Omaha (OPS) han trabajado para ayudar y mantener a flote esta vez a sus 53.552 estudiantes. Las principales prioridades son involucrar a los estudiantes y dirigirlos a tener [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/el-perico.com\/es\/las-escuelas-publicas-de-omaha-continuan-sirviendo-a-estudiantes-y-familias\/\" \/>\n<meta property=\"og:site_name\" content=\"el perico\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/elpericoomaha\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-29T01:24:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-03-08T23:47:06+00:00\" \/>\n<meta name=\"author\" content=\"El Perico Staff\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"El Perico Staff\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n\t<meta name=\"twitter:label3\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data3\" content=\"El Perico Staff\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/las-escuelas-publicas-de-omaha-continuan-sirviendo-a-estudiantes-y-familias\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/las-escuelas-publicas-de-omaha-continuan-sirviendo-a-estudiantes-y-familias\\\/\"},\"author\":{\"name\":\"El Perico Staff\",\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/#\\\/schema\\\/person\\\/1956e5e63b94d4bd0daf30675bdf4a93\"},\"headline\":\"Las Escuelas P\u00fablicas de Omaha contin\u00faan sirviendo a estudiantes y familias\",\"datePublished\":\"2020-04-29T01:24:05+00:00\",\"dateModified\":\"2022-03-08T23:47:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/las-escuelas-publicas-de-omaha-continuan-sirviendo-a-estudiantes-y-familias\\\/\"},\"wordCount\":640,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/las-escuelas-publicas-de-omaha-continuan-sirviendo-a-estudiantes-y-familias\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"keywords\":[\"comunidades\",\"COVID-19\",\"foodbank\"],\"articleSection\":[\"Reportaje\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/el-perico.com\\\/es\\\/las-escuelas-publicas-de-omaha-continuan-sirviendo-a-estudiantes-y-familias\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/las-escuelas-publicas-de-omaha-continuan-sirviendo-a-estudiantes-y-familias\\\/\",\"url\":\"https:\\\/\\\/el-perico.com\\\/es\\\/las-escuelas-publicas-de-omaha-continuan-sirviendo-a-estudiantes-y-familias\\\/\",\"name\":\"Las Escuelas P\u00fablicas de Omaha contin\u00faan sirviendo a estudiantes y familias - el perico\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/las-escuelas-publicas-de-omaha-continuan-sirviendo-a-estudiantes-y-familias\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/las-escuelas-publicas-de-omaha-continuan-sirviendo-a-estudiantes-y-familias\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2020-04-29T01:24:05+00:00\",\"dateModified\":\"2022-03-08T23:47:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/las-escuelas-publicas-de-omaha-continuan-sirviendo-a-estudiantes-y-familias\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/el-perico.com\\\/es\\\/las-escuelas-publicas-de-omaha-continuan-sirviendo-a-estudiantes-y-familias\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/las-escuelas-publicas-de-omaha-continuan-sirviendo-a-estudiantes-y-familias\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/las-escuelas-publicas-de-omaha-continuan-sirviendo-a-estudiantes-y-familias\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/el-perico.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Las Escuelas P\u00fablicas de Omaha contin\u00faan sirviendo a estudiantes y familias\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/el-perico.com\\\/es\\\/\",\"name\":\"el perico\",\"description\":\"La plataforma original de noticias e informaci\u00f3n para la comunidad hispana de Omaha\",\"publisher\":{\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/el-perico.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/#organization\",\"name\":\"el perico\",\"url\":\"https:\\\/\\\/el-perico.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/el-perico.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/ElPerico-Logo_NPM-1-e1717102187440.png\",\"contentUrl\":\"https:\\\/\\\/el-perico.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/ElPerico-Logo_NPM-1-e1717102187440.png\",\"width\":648,\"height\":216,\"caption\":\"el perico\"},\"image\":{\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/elpericoomaha\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/#\\\/schema\\\/person\\\/1956e5e63b94d4bd0daf30675bdf4a93\",\"name\":\"El Perico Staff\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/701b23c665bfde9fd4d874d31feb4c16bf2ac173b2b0b7224dc39896d4cfc381?s=96&d=mm&r=g80b2efc5844e688a6ffb9340c789e4c4\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/701b23c665bfde9fd4d874d31feb4c16bf2ac173b2b0b7224dc39896d4cfc381?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/701b23c665bfde9fd4d874d31feb4c16bf2ac173b2b0b7224dc39896d4cfc381?s=96&d=mm&r=g\",\"caption\":\"El Perico Staff\"},\"sameAs\":[\"https:\\\/\\\/el-perico.com\"],\"url\":\"https:\\\/\\\/el-perico.com\\\/es\\\/author\\\/af6f1d62_admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Las Escuelas P\u00fablicas de Omaha contin\u00faan sirviendo a estudiantes y familias - el perico","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/el-perico.com\/es\/las-escuelas-publicas-de-omaha-continuan-sirviendo-a-estudiantes-y-familias\/","og_locale":"es_ES","og_type":"article","og_title":"Las Escuelas P\u00fablicas de Omaha contin\u00faan sirviendo a estudiantes y familias - el perico","og_description":"By Johana Le Flores, activista comunitaria de artes Desde que se pas\u00f3 al aprendizaje a distancia en todos los distritos escolares del \u00e1rea, las Escuelas P\u00fablicas de Omaha (OPS) han trabajado para ayudar y mantener a flote esta vez a sus 53.552 estudiantes. Las principales prioridades son involucrar a los estudiantes y dirigirlos a tener [&hellip;]","og_url":"https:\/\/el-perico.com\/es\/las-escuelas-publicas-de-omaha-continuan-sirviendo-a-estudiantes-y-familias\/","og_site_name":"el perico","article_publisher":"https:\/\/www.facebook.com\/elpericoomaha","article_published_time":"2020-04-29T01:24:05+00:00","article_modified_time":"2022-03-08T23:47:06+00:00","author":"El Perico Staff","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"El Perico Staff","Tiempo de lectura":"3 minutos","Written by":"El Perico Staff"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/el-perico.com\/es\/las-escuelas-publicas-de-omaha-continuan-sirviendo-a-estudiantes-y-familias\/#article","isPartOf":{"@id":"https:\/\/el-perico.com\/es\/las-escuelas-publicas-de-omaha-continuan-sirviendo-a-estudiantes-y-familias\/"},"author":{"name":"El Perico Staff","@id":"https:\/\/el-perico.com\/es\/#\/schema\/person\/1956e5e63b94d4bd0daf30675bdf4a93"},"headline":"Las Escuelas P\u00fablicas de Omaha contin\u00faan sirviendo a estudiantes y familias","datePublished":"2020-04-29T01:24:05+00:00","dateModified":"2022-03-08T23:47:06+00:00","mainEntityOfPage":{"@id":"https:\/\/el-perico.com\/es\/las-escuelas-publicas-de-omaha-continuan-sirviendo-a-estudiantes-y-familias\/"},"wordCount":640,"commentCount":0,"publisher":{"@id":"https:\/\/el-perico.com\/es\/#organization"},"image":{"@id":"https:\/\/el-perico.com\/es\/las-escuelas-publicas-de-omaha-continuan-sirviendo-a-estudiantes-y-familias\/#primaryimage"},"thumbnailUrl":"","keywords":["comunidades","COVID-19","foodbank"],"articleSection":["Reportaje"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/el-perico.com\/es\/las-escuelas-publicas-de-omaha-continuan-sirviendo-a-estudiantes-y-familias\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/el-perico.com\/es\/las-escuelas-publicas-de-omaha-continuan-sirviendo-a-estudiantes-y-familias\/","url":"https:\/\/el-perico.com\/es\/las-escuelas-publicas-de-omaha-continuan-sirviendo-a-estudiantes-y-familias\/","name":"Las Escuelas P\u00fablicas de Omaha contin\u00faan sirviendo a estudiantes y familias - el perico","isPartOf":{"@id":"https:\/\/el-perico.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/el-perico.com\/es\/las-escuelas-publicas-de-omaha-continuan-sirviendo-a-estudiantes-y-familias\/#primaryimage"},"image":{"@id":"https:\/\/el-perico.com\/es\/las-escuelas-publicas-de-omaha-continuan-sirviendo-a-estudiantes-y-familias\/#primaryimage"},"thumbnailUrl":"","datePublished":"2020-04-29T01:24:05+00:00","dateModified":"2022-03-08T23:47:06+00:00","breadcrumb":{"@id":"https:\/\/el-perico.com\/es\/las-escuelas-publicas-de-omaha-continuan-sirviendo-a-estudiantes-y-familias\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/el-perico.com\/es\/las-escuelas-publicas-de-omaha-continuan-sirviendo-a-estudiantes-y-familias\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/el-perico.com\/es\/las-escuelas-publicas-de-omaha-continuan-sirviendo-a-estudiantes-y-familias\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/el-perico.com\/es\/las-escuelas-publicas-de-omaha-continuan-sirviendo-a-estudiantes-y-familias\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/el-perico.com\/es\/"},{"@type":"ListItem","position":2,"name":"Las Escuelas P\u00fablicas de Omaha contin\u00faan sirviendo a estudiantes y familias"}]},{"@type":"WebSite","@id":"https:\/\/el-perico.com\/es\/#website","url":"https:\/\/el-perico.com\/es\/","name":"el perico","description":"La plataforma original de noticias e informaci\u00f3n para la comunidad hispana de Omaha","publisher":{"@id":"https:\/\/el-perico.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/el-perico.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/el-perico.com\/es\/#organization","name":"el perico","url":"https:\/\/el-perico.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/el-perico.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/el-perico.com\/wp-content\/uploads\/2024\/05\/ElPerico-Logo_NPM-1-e1717102187440.png","contentUrl":"https:\/\/el-perico.com\/wp-content\/uploads\/2024\/05\/ElPerico-Logo_NPM-1-e1717102187440.png","width":648,"height":216,"caption":"el perico"},"image":{"@id":"https:\/\/el-perico.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/elpericoomaha"]},{"@type":"Person","@id":"https:\/\/el-perico.com\/es\/#\/schema\/person\/1956e5e63b94d4bd0daf30675bdf4a93","name":"El Perico Staff","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/701b23c665bfde9fd4d874d31feb4c16bf2ac173b2b0b7224dc39896d4cfc381?s=96&d=mm&r=g80b2efc5844e688a6ffb9340c789e4c4","url":"https:\/\/secure.gravatar.com\/avatar\/701b23c665bfde9fd4d874d31feb4c16bf2ac173b2b0b7224dc39896d4cfc381?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/701b23c665bfde9fd4d874d31feb4c16bf2ac173b2b0b7224dc39896d4cfc381?s=96&d=mm&r=g","caption":"El Perico Staff"},"sameAs":["https:\/\/el-perico.com"],"url":"https:\/\/el-perico.com\/es\/author\/af6f1d62_admin\/"}]}},"_links":{"self":[{"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/posts\/3583","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/comments?post=3583"}],"version-history":[{"count":1,"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/posts\/3583\/revisions"}],"predecessor-version":[{"id":6160,"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/posts\/3583\/revisions\/6160"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/el-perico.com\/es\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/media?parent=3583"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/categories?post=3583"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/tags?post=3583"},{"taxonomy":"newspack_spnsrs_tax","embeddable":true,"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/newspack_spnsrs_tax?post=3583"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/coauthors?post=3583"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}