{"id":3329,"date":"2020-04-10T12:08:22","date_gmt":"2020-04-10T17:08:22","guid":{"rendered":"https:\/\/el-perico.com\/?p=3329"},"modified":"2022-03-08T23:17:50","modified_gmt":"2022-03-09T04:17:50","slug":"donde-encontrar-despensas-de-comida-para-este-sabado-11-de-abril","status":"publish","type":"post","link":"https:\/\/el-perico.com\/es\/donde-encontrar-despensas-de-comida-para-este-sabado-11-de-abril\/","title":{"rendered":"D\u00f3nde encontrar despensas de comida para este s\u00e1bado 11 de abril en Omaha"},"content":{"rendered":"<figure id=\"attachment_3335\" aria-describedby=\"caption-attachment-3335\" style=\"width: 695px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-3335\" src=\"https:\/\/el-perico.com\/wp-content\/uploads\/2020\/04\/ivytechfoodpantry-300x225.jpeg\" alt=\"\" width=\"695\" height=\"521\"><figcaption id=\"caption-attachment-3335\" class=\"wp-caption-text\"><span style=\"color: #999999;\"><em>Foto referencial.<\/em> <\/span><\/figcaption><\/figure>\n<p>Los trabajos por la repartici\u00f3n de comida contin\u00faan. Aqu\u00ed le mostraremos y recordaremos los d\u00edas en los que puede dirigirse a la despensa m\u00f3vil <a href=\"https:\/\/foodbankheartland.org\/wp-content\/uploads\/2020\/04\/Mobiles_Updated4-7-20.pdf\"><strong>(Food Bank Mobile)<\/strong> <\/a>para encontrar alimentos para usted y su familia. Recuerde que es tiempo de cooperar y si usted considera que tiene suficiente comida para usted y su familia, dele la oportunidad a otros que tambi\u00e9n la necesitan.<\/p>\n<h2>S\u00e1bado 11 de abril<\/h2>\n<figure id=\"attachment_3334\" aria-describedby=\"caption-attachment-3334\" style=\"width: 345px\" class=\"wp-caption alignright\"><a href=\"https:\/\/goo.gl\/maps\/Jmsr9EQoY3b1raBK9\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-3334\" src=\"https:\/\/el-perico.com\/wp-content\/uploads\/2020\/04\/harrison-300x202.jpeg\" alt=\"\" width=\"345\" height=\"232\"><\/a><figcaption id=\"caption-attachment-3334\" class=\"wp-caption-text\"><em><span style=\"color: #999999;\">Toca el mapa para conocer la ubicaci\u00f3n en Google<\/span><\/em><\/figcaption><\/figure>\n<p><strong>Condado de Sarpy:&nbsp;<\/strong><br \/>\nOrganizaci\u00f3n: <em>Messiah Lutheran Church<\/em><br \/>\nHora: <strong><span style=\"color: #ff6600;\">8:15 a.m. a 11:oo a.m. <\/span><\/strong><br \/>\nUbicaci\u00f3n: Harrison&nbsp; Street&nbsp; Baptist Church 8015 Harrison1 St, La Vista, NE 68128.<br \/>\n&nbsp;<br \/>\n<!--more--><\/p>\n<figure id=\"attachment_3336\" aria-describedby=\"caption-attachment-3336\" style=\"width: 340px\" class=\"wp-caption alignright\"><a href=\"https:\/\/goo.gl\/maps\/jcGY3GfC9CnvTmX47\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-3336\" src=\"https:\/\/el-perico.com\/wp-content\/uploads\/2020\/04\/OMAHA1-300x215.jpeg\" alt=\"\" width=\"340\" height=\"244\"><\/a><figcaption id=\"caption-attachment-3336\" class=\"wp-caption-text\"><span style=\"color: #999999;\"><em>Toca para ver el mapa completo<\/em><\/span><\/figcaption><\/figure>\n<p><strong>Condado de Douglas:<\/strong><br \/>\nOrganizaci\u00f3n: <a href=\"https:\/\/heartlandhopemission.org\"><em>Heartland Hope Mission<\/em><\/a><br \/>\nTodo el que necesite alimentos puede retirar comida una vez cada 30 d\u00edas. Las personas mayores de 60 a\u00f1os&nbsp; y personas con discapacidad (mostrando su credencial) podr\u00e1n hacerlo cada 21 d\u00edas.<br \/>\nHora: <strong><span style=\"color: #ff6600;\">9:30 a.m. &#8211; 12:00 m<\/span><\/strong>.<\/p>\n<div id=\"address\">Ubicaci\u00f3n: 2021 U Street, Omaha, NE 68107<\/div>\n<p><!--more--><\/p>\n<div><span style=\"color: #000000;\"><strong>IMPORTANTE: <\/strong><\/span>Esta organizaci\u00f3n podr\u00eda pedirle una credencial con foto que lo identifique y una prueba de otros miembros de la casa que vivan con usted, como el n\u00famero de seguridad social y la fecha de nacimiento. Tambi\u00e9n debe mostrar alguna cuenta o factura de servicio que muestre su direcci\u00f3n exacta (no se necesita si tiene su licencia de conducir de Nebraska o la c\u00e9dula de Nebraska). Tambi\u00e9n debe estar listo para firmar un documento donde diga su ingreso mensual.<\/div>\n<p><!--more--><\/p>\n<div>\n<figure id=\"attachment_3337\" aria-describedby=\"caption-attachment-3337\" style=\"width: 341px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/goo.gl\/maps\/WnaT8eGqGYXRF8oC7\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-3337\" src=\"https:\/\/el-perico.com\/wp-content\/uploads\/2020\/04\/OMAHA-2-300x203.jpg\" alt=\"\" width=\"341\" height=\"230\"><\/a><figcaption id=\"caption-attachment-3337\" class=\"wp-caption-text\"><span style=\"color: #999999;\"><em>Toca para ver el mapa completo<\/em><\/span><\/figcaption><\/figure>\n<p>Organizaci\u00f3n: <a href=\"https:\/\/heartlandhopemission.org\"><em>Heartland Hope Mission<\/em><\/a><br \/>\nHora: <span style=\"color: #ff6600;\"><span style=\"color: #ff6600;\"><strong>10:30 a.m. &#8211; 11:30 a.m.<\/strong><\/span><\/span><br \/>\nUbicaci\u00f3n: Millard pantry (5321 S. 139th Plaza)<\/div>\n<div><\/div>\n<div>Si desea<strong> conocer de otros lugares<\/strong> cerca de su casa puede entrar a <strong><a href=\"https:\/\/www.foodpantries.org\/ci\/ne-omaha\">este enlace<\/a>.<\/strong> Recuerde verificar <strong>el horario de las despensas.&nbsp;<\/strong><\/div>\n<p>&nbsp;<br \/>\n&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los trabajos por la repartici\u00f3n de comida contin\u00faan. Aqu\u00ed le mostraremos y recordaremos los d\u00edas en los que puede dirigirse a la despensa m\u00f3vil (Food Bank Mobile) para encontrar alimentos para usted y su familia. Recuerde que es tiempo de cooperar y si usted considera que tiene suficiente comida para usted y su familia, dele [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3335,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"newspack_ads_suppress_ads":false,"_newspack_byline_active":false,"_newspack_byline":"","newspack_hide_updated_date":false,"newspack_show_updated_date":false,"newspack_content_restriction_is_exempt":false,"newspack_featured_image_position":"","newspack_post_subtitle":"","newspack_article_summary_title":"Overview:","newspack_article_summary":"","footnotes":""},"categories":[46,1],"tags":[],"newspack_spnsrs_tax":[],"coauthors":[1233],"class_list":["post-3329","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-reportaje","category-uncategorized","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>D\u00f3nde encontrar despensas de comida para este s\u00e1bado 11 de abril en Omaha - el perico<\/title>\n<meta name=\"description\" content=\"Los bancos de comidas est\u00e1n abiertos por algunas horas, aqu\u00ed le mostramos algunos que estar\u00e1n disponibles para este s\u00e1bado 11 de abril de 2020\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/el-perico.com\/es\/donde-encontrar-despensas-de-comida-para-este-sabado-11-de-abril\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"D\u00f3nde encontrar despensas de comida para este s\u00e1bado 11 de abril en Omaha - el perico\" \/>\n<meta property=\"og:description\" content=\"Los bancos de comidas est\u00e1n abiertos por algunas horas, aqu\u00ed le mostramos algunos que estar\u00e1n disponibles para este s\u00e1bado 11 de abril de 2020\" \/>\n<meta property=\"og:url\" content=\"https:\/\/el-perico.com\/es\/donde-encontrar-despensas-de-comida-para-este-sabado-11-de-abril\/\" \/>\n<meta property=\"og:site_name\" content=\"el perico\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/elpericoomaha\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-10T17:08:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-03-09T04:17:50+00:00\" \/>\n<meta name=\"author\" content=\"El Perico Staff\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"El Perico Staff\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n\t<meta name=\"twitter:label3\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data3\" content=\"El Perico Staff\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/donde-encontrar-despensas-de-comida-para-este-sabado-11-de-abril\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/donde-encontrar-despensas-de-comida-para-este-sabado-11-de-abril\\\/\"},\"author\":{\"name\":\"El Perico Staff\",\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/#\\\/schema\\\/person\\\/1956e5e63b94d4bd0daf30675bdf4a93\"},\"headline\":\"D\u00f3nde encontrar despensas de comida para este s\u00e1bado 11 de abril en Omaha\",\"datePublished\":\"2020-04-10T17:08:22+00:00\",\"dateModified\":\"2022-03-09T04:17:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/donde-encontrar-despensas-de-comida-para-este-sabado-11-de-abril\\\/\"},\"wordCount\":349,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/donde-encontrar-despensas-de-comida-para-este-sabado-11-de-abril\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"articleSection\":[\"Reportaje\",\"Uncategorized\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/el-perico.com\\\/es\\\/donde-encontrar-despensas-de-comida-para-este-sabado-11-de-abril\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/donde-encontrar-despensas-de-comida-para-este-sabado-11-de-abril\\\/\",\"url\":\"https:\\\/\\\/el-perico.com\\\/es\\\/donde-encontrar-despensas-de-comida-para-este-sabado-11-de-abril\\\/\",\"name\":\"D\u00f3nde encontrar despensas de comida para este s\u00e1bado 11 de abril en Omaha - el perico\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/donde-encontrar-despensas-de-comida-para-este-sabado-11-de-abril\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/donde-encontrar-despensas-de-comida-para-este-sabado-11-de-abril\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2020-04-10T17:08:22+00:00\",\"dateModified\":\"2022-03-09T04:17:50+00:00\",\"description\":\"Los bancos de comidas est\u00e1n abiertos por algunas horas, aqu\u00ed le mostramos algunos que estar\u00e1n disponibles para este s\u00e1bado 11 de abril de 2020\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/donde-encontrar-despensas-de-comida-para-este-sabado-11-de-abril\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/el-perico.com\\\/es\\\/donde-encontrar-despensas-de-comida-para-este-sabado-11-de-abril\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/donde-encontrar-despensas-de-comida-para-este-sabado-11-de-abril\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/donde-encontrar-despensas-de-comida-para-este-sabado-11-de-abril\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/el-perico.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"D\u00f3nde encontrar despensas de comida para este s\u00e1bado 11 de abril en Omaha\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/el-perico.com\\\/es\\\/\",\"name\":\"el perico\",\"description\":\"La plataforma original de noticias e informaci\u00f3n para la comunidad hispana de Omaha\",\"publisher\":{\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/el-perico.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/#organization\",\"name\":\"el perico\",\"url\":\"https:\\\/\\\/el-perico.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/el-perico.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/ElPerico-Logo_NPM-1-e1717102187440.png\",\"contentUrl\":\"https:\\\/\\\/el-perico.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/ElPerico-Logo_NPM-1-e1717102187440.png\",\"width\":648,\"height\":216,\"caption\":\"el perico\"},\"image\":{\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/elpericoomaha\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/#\\\/schema\\\/person\\\/1956e5e63b94d4bd0daf30675bdf4a93\",\"name\":\"El Perico Staff\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/701b23c665bfde9fd4d874d31feb4c16bf2ac173b2b0b7224dc39896d4cfc381?s=96&d=mm&r=g80b2efc5844e688a6ffb9340c789e4c4\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/701b23c665bfde9fd4d874d31feb4c16bf2ac173b2b0b7224dc39896d4cfc381?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/701b23c665bfde9fd4d874d31feb4c16bf2ac173b2b0b7224dc39896d4cfc381?s=96&d=mm&r=g\",\"caption\":\"El Perico Staff\"},\"sameAs\":[\"https:\\\/\\\/el-perico.com\"],\"url\":\"https:\\\/\\\/el-perico.com\\\/es\\\/author\\\/af6f1d62_admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"D\u00f3nde encontrar despensas de comida para este s\u00e1bado 11 de abril en Omaha - el perico","description":"Los bancos de comidas est\u00e1n abiertos por algunas horas, aqu\u00ed le mostramos algunos que estar\u00e1n disponibles para este s\u00e1bado 11 de abril de 2020","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/el-perico.com\/es\/donde-encontrar-despensas-de-comida-para-este-sabado-11-de-abril\/","og_locale":"es_ES","og_type":"article","og_title":"D\u00f3nde encontrar despensas de comida para este s\u00e1bado 11 de abril en Omaha - el perico","og_description":"Los bancos de comidas est\u00e1n abiertos por algunas horas, aqu\u00ed le mostramos algunos que estar\u00e1n disponibles para este s\u00e1bado 11 de abril de 2020","og_url":"https:\/\/el-perico.com\/es\/donde-encontrar-despensas-de-comida-para-este-sabado-11-de-abril\/","og_site_name":"el perico","article_publisher":"https:\/\/www.facebook.com\/elpericoomaha","article_published_time":"2020-04-10T17:08:22+00:00","article_modified_time":"2022-03-09T04:17:50+00:00","author":"El Perico Staff","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"El Perico Staff","Tiempo de lectura":"3 minutos","Written by":"El Perico Staff"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/el-perico.com\/es\/donde-encontrar-despensas-de-comida-para-este-sabado-11-de-abril\/#article","isPartOf":{"@id":"https:\/\/el-perico.com\/es\/donde-encontrar-despensas-de-comida-para-este-sabado-11-de-abril\/"},"author":{"name":"El Perico Staff","@id":"https:\/\/el-perico.com\/es\/#\/schema\/person\/1956e5e63b94d4bd0daf30675bdf4a93"},"headline":"D\u00f3nde encontrar despensas de comida para este s\u00e1bado 11 de abril en Omaha","datePublished":"2020-04-10T17:08:22+00:00","dateModified":"2022-03-09T04:17:50+00:00","mainEntityOfPage":{"@id":"https:\/\/el-perico.com\/es\/donde-encontrar-despensas-de-comida-para-este-sabado-11-de-abril\/"},"wordCount":349,"commentCount":0,"publisher":{"@id":"https:\/\/el-perico.com\/es\/#organization"},"image":{"@id":"https:\/\/el-perico.com\/es\/donde-encontrar-despensas-de-comida-para-este-sabado-11-de-abril\/#primaryimage"},"thumbnailUrl":"","articleSection":["Reportaje","Uncategorized"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/el-perico.com\/es\/donde-encontrar-despensas-de-comida-para-este-sabado-11-de-abril\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/el-perico.com\/es\/donde-encontrar-despensas-de-comida-para-este-sabado-11-de-abril\/","url":"https:\/\/el-perico.com\/es\/donde-encontrar-despensas-de-comida-para-este-sabado-11-de-abril\/","name":"D\u00f3nde encontrar despensas de comida para este s\u00e1bado 11 de abril en Omaha - el perico","isPartOf":{"@id":"https:\/\/el-perico.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/el-perico.com\/es\/donde-encontrar-despensas-de-comida-para-este-sabado-11-de-abril\/#primaryimage"},"image":{"@id":"https:\/\/el-perico.com\/es\/donde-encontrar-despensas-de-comida-para-este-sabado-11-de-abril\/#primaryimage"},"thumbnailUrl":"","datePublished":"2020-04-10T17:08:22+00:00","dateModified":"2022-03-09T04:17:50+00:00","description":"Los bancos de comidas est\u00e1n abiertos por algunas horas, aqu\u00ed le mostramos algunos que estar\u00e1n disponibles para este s\u00e1bado 11 de abril de 2020","breadcrumb":{"@id":"https:\/\/el-perico.com\/es\/donde-encontrar-despensas-de-comida-para-este-sabado-11-de-abril\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/el-perico.com\/es\/donde-encontrar-despensas-de-comida-para-este-sabado-11-de-abril\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/el-perico.com\/es\/donde-encontrar-despensas-de-comida-para-este-sabado-11-de-abril\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/el-perico.com\/es\/donde-encontrar-despensas-de-comida-para-este-sabado-11-de-abril\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/el-perico.com\/es\/"},{"@type":"ListItem","position":2,"name":"D\u00f3nde encontrar despensas de comida para este s\u00e1bado 11 de abril en Omaha"}]},{"@type":"WebSite","@id":"https:\/\/el-perico.com\/es\/#website","url":"https:\/\/el-perico.com\/es\/","name":"el perico","description":"La plataforma original de noticias e informaci\u00f3n para la comunidad hispana de Omaha","publisher":{"@id":"https:\/\/el-perico.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/el-perico.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/el-perico.com\/es\/#organization","name":"el perico","url":"https:\/\/el-perico.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/el-perico.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/el-perico.com\/wp-content\/uploads\/2024\/05\/ElPerico-Logo_NPM-1-e1717102187440.png","contentUrl":"https:\/\/el-perico.com\/wp-content\/uploads\/2024\/05\/ElPerico-Logo_NPM-1-e1717102187440.png","width":648,"height":216,"caption":"el perico"},"image":{"@id":"https:\/\/el-perico.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/elpericoomaha"]},{"@type":"Person","@id":"https:\/\/el-perico.com\/es\/#\/schema\/person\/1956e5e63b94d4bd0daf30675bdf4a93","name":"El Perico Staff","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/701b23c665bfde9fd4d874d31feb4c16bf2ac173b2b0b7224dc39896d4cfc381?s=96&d=mm&r=g80b2efc5844e688a6ffb9340c789e4c4","url":"https:\/\/secure.gravatar.com\/avatar\/701b23c665bfde9fd4d874d31feb4c16bf2ac173b2b0b7224dc39896d4cfc381?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/701b23c665bfde9fd4d874d31feb4c16bf2ac173b2b0b7224dc39896d4cfc381?s=96&d=mm&r=g","caption":"El Perico Staff"},"sameAs":["https:\/\/el-perico.com"],"url":"https:\/\/el-perico.com\/es\/author\/af6f1d62_admin\/"}]}},"_links":{"self":[{"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/posts\/3329","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/comments?post=3329"}],"version-history":[{"count":1,"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/posts\/3329\/revisions"}],"predecessor-version":[{"id":6183,"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/posts\/3329\/revisions\/6183"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/el-perico.com\/es\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/media?parent=3329"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/categories?post=3329"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/tags?post=3329"},{"taxonomy":"newspack_spnsrs_tax","embeddable":true,"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/newspack_spnsrs_tax?post=3329"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/coauthors?post=3329"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}