{"id":3144,"date":"2020-04-02T07:07:28","date_gmt":"2020-04-02T07:07:28","guid":{"rendered":"https:\/\/el-perico.com\/?p=3144"},"modified":"2022-03-16T20:53:00","modified_gmt":"2022-03-17T00:53:00","slug":"cuarentena_covid_ideas_aprender_omaha","status":"publish","type":"post","link":"https:\/\/el-perico.com\/es\/cuarentena_covid_ideas_aprender_omaha\/","title":{"rendered":"\u00a1Hey! tu mente no est\u00e1 en cuarentena &#8211; ideas para aprender algo m\u00e1s."},"content":{"rendered":"<p>Si puedes agregar m\u00e1s ideas, comparte <a href=\"https:\/\/thereader.com\/local-things-to-do-during-quarantine\">aqu\u00ed.<\/a><br \/>\n<strong>1. Hazlo<\/strong>. Mientras algunos espacios f\u00edsicos est\u00e1n cerrados, hay otros que son virtuales y siempre est\u00e1n abiertos de forma gratuita. Aparte de los programas regulares puedes explorar m\u00e1s all\u00e1. Si te gustan los videojuegos o quieres ver sobre qu\u00e9 se tratan alguno, entra a Twitch. Tambi\u00e9n puedes ver un poco de realidad aumentada (Augmented Reality), juegos de dise\u00f1os y no te olvides del Censo. Entra en Do Space para ver la <a href=\"https:\/\/dospace.org\/calendar\/\">programaci\u00f3n<\/a> que tienen con webinars para aprender cosas nuevas, tambi\u00e9n en su <a href=\"https:\/\/www.facebook.com\/DoSpaceOmaha\">p\u00e1ginas de Facebook<\/a>.<br \/>\n<strong>2. Conozca su \u00e1rbol geneal\u00f3gico<\/strong>. La <a href=\"https:\/\/omahalibrary.org\/\">Biblioteca P\u00fablica de Omaha<\/a> (OPL) est\u00e1 abriendo la investigaci\u00f3n de historia familiar (normalmente permitida solo en l\u00ednea) para que los usuarios la utilicen desde su hogar. Debe tener una tarjeta OPL y un PIN para <a href=\"https:\/\/bit.ly\/2x7US7d?fbclid=IwAR1e7HjDofwlw_3cU9lltCCrowHNoz82dWiRdR2W2Mq_jNZ3y71Dx3Asc-I\">comenzar<\/a>. Ancestry Library Edition abrir\u00e1 su mundo a la mayor colecci\u00f3n general de informaci\u00f3n geneal\u00f3gica.<\/p>\n<figure id=\"attachment_3146\" aria-describedby=\"caption-attachment-3146\" style=\"width: 300px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-3146\" src=\"https:\/\/el-perico.com\/wp-content\/uploads\/2020\/04\/yoga-dog-300x300.jpeg\" alt=\"\" width=\"300\" height=\"300\"><figcaption id=\"caption-attachment-3146\" class=\"wp-caption-text\"><span style=\"color: #999999;\"><em>T\u00f3mate un tiempo para depurar tu mente a trav\u00e9s de la meditaci\u00f3n.<\/em><\/span><\/figcaption><\/figure>\n<p><strong>3. \u00bfEstresado(a)? respira\u2026<\/strong> Este es un momento perfecto para comenzar la pr\u00e1ctica la calma y encontrarse consigo mismo. <a href=\"http:\/\/www.thecenterformindfullivingomaha.com\/\">El Centro para la Vida Mental de Omaha<\/a> ubicado en Dundee ofrece clases online de meditaci\u00f3n los lunes, martes y jueves a las 8:15 de la ma\u00f1ana. Hay que tener la aplicaci\u00f3n <a href=\"https:\/\/zoom.us\/\">Zoom<\/a> en tu tel\u00e9fono, tableta o computadora port\u00e1til, y deber\u00e1s hacer click en los enlaces que ofrece. Tambi\u00e9n los centros de yoga como <a href=\"http:\/\/soundmethodyoga.com\/\">Sound Method Yoga<\/a>,&nbsp;<a href=\"https:\/\/www.lotushouseofyoga.com\/\">Lotus House of Yoga&nbsp;<\/a>,<a href=\"https:\/\/www.doyoganow.com\/\">Do Yoga Now,<\/a><a href=\"https:\/\/www.youtube.com\/channel\/UCgK2dl3I9PmQM4qR4_1Kl4g\">One Tree Yoga<\/a>&nbsp;y&nbsp;<a href=\"http:\/\/www.karmayogaomaha.com\/\">Karma Yoga<\/a>&nbsp;tambi\u00e9n ofreces clases virtuales, las puedes encontrar en sus p\u00e1ginas de Facebook. Si hablas <strong>SOLO ESPA\u00d1OL<\/strong> y deseas adentrarse en este mundo, recomendamos los videos del canal de Youtube de <a href=\"https:\/\/www.youtube.com\/channel\/UCb-ODDTys9PeeSyreyh___w\">Malova Elena<\/a> y sus clases de yoga y <a href=\"https:\/\/www.youtube.com\/watch?v=GTERW6tNMy0\">meditaci\u00f3n<\/a> \u00a1int\u00e9ntalo!<br \/>\n<strong>4. Aprenda ingl\u00e9s en l\u00ednea y gratis<\/strong>. Hay diversas p\u00e1ginas y aplicaciones que ofrecen cursos de idiomas por internet. Sin embargo, algunos no te ense\u00f1an c\u00f3mo usar la lengua para comunicarte con los dem\u00e1s, siempre hay unos m\u00e1s efectivos que otro.&nbsp;Consideramos que <a href=\"https:\/\/aprendergratis.es\/cursos-online\/idiomas\/ingles\/\">Aprendegratis.es<\/a> puede ser \u00fatil para principiantes y la<a href=\"https:\/\/www.bbc.co.uk\/learningenglish\/\"> BBC<\/a> ofrece tambi\u00e9n cursos para practicar el idioma en contexto y aprender frases comunes.<\/p>\n<figure id=\"attachment_3147\" aria-describedby=\"caption-attachment-3147\" style=\"width: 372px\" class=\"wp-caption alignright\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-3147\" src=\"https:\/\/el-perico.com\/wp-content\/uploads\/2020\/04\/Fender-Play-learn-guitar-online-300x150.jpeg\" alt=\"\" width=\"372\" height=\"186\"><figcaption id=\"caption-attachment-3147\" class=\"wp-caption-text\"><span style=\"color: #999999;\"><em>Hay much\u00edsimas personas en las redes sociales que est\u00e1n ofreciendo clases online a precios accesibles.<\/em><\/span><\/figcaption><\/figure>\n<p><strong>5. \u00bfVarado en casa con un instrumento musical y sin profesor?<\/strong> Ya muchos profesores de m\u00fasica est\u00e1n ofreciendo clases en l\u00ednea. Si tienes una guitarra puedes entrar a este canal de youtube de <a href=\"https:\/\/www.youtube.com\/watch?v=g6h2ztdqCc8\">kalinchita<\/a>. Si tienes un acorde\u00f3n y quienes practicar, <a href=\"https:\/\/www.youtube.com\/user\/VIRTUOSSOpuntoCOM\">Virtuosso.com<\/a> te puede ayudar a eso, puedes aprender primero a reconocer <a href=\"https:\/\/www.youtube.com\/watch?v=mXFTEnRe1xI&amp;list=PLE9414D96DA0D723D\">los botones de este instrumento.<\/a><br \/>\nTe invitamos a que nos digas si conoces de alguien que est\u00e9 dando clases de m\u00fasica online, seguramente podr\u00e1 conseguir alumnos. D\u00e9janos tu comentario si tienes m\u00e1s sugerencias en esta cuarentena.<br \/>\nPara la versi\u00f3n en ingl\u00e9s visita <a href=\"https:\/\/thereader.com\/news\/covid-19-pandemic-in-omaha\/your-mind-is-not-quarantined-ideas-for-learning-new-things\">The Reader<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si puedes agregar m\u00e1s ideas, comparte aqu\u00ed. 1. Hazlo. Mientras algunos espacios f\u00edsicos est\u00e1n cerrados, hay otros que son virtuales y siempre est\u00e1n abiertos de forma gratuita. Aparte de los programas regulares puedes explorar m\u00e1s all\u00e1. Si te gustan los videojuegos o quieres ver sobre qu\u00e9 se tratan alguno, entra a Twitch. Tambi\u00e9n puedes ver [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3147,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"newspack_ads_suppress_ads":false,"_newspack_byline_active":false,"_newspack_byline":"","newspack_hide_updated_date":false,"newspack_show_updated_date":false,"newspack_content_restriction_is_exempt":false,"newspack_featured_image_position":"","newspack_post_subtitle":"","newspack_article_summary_title":"Overview:","newspack_article_summary":"","footnotes":""},"categories":[42,46],"tags":[],"newspack_spnsrs_tax":[],"coauthors":[1233],"class_list":["post-3144","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura","category-reportaje","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00a1Hey! tu mente no est\u00e1 en cuarentena - ideas para aprender algo m\u00e1s. - el perico<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/el-perico.com\/es\/cuarentena_covid_ideas_aprender_omaha\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00a1Hey! tu mente no est\u00e1 en cuarentena - ideas para aprender algo m\u00e1s. - el perico\" \/>\n<meta property=\"og:description\" content=\"Si puedes agregar m\u00e1s ideas, comparte aqu\u00ed. 1. Hazlo. Mientras algunos espacios f\u00edsicos est\u00e1n cerrados, hay otros que son virtuales y siempre est\u00e1n abiertos de forma gratuita. Aparte de los programas regulares puedes explorar m\u00e1s all\u00e1. Si te gustan los videojuegos o quieres ver sobre qu\u00e9 se tratan alguno, entra a Twitch. Tambi\u00e9n puedes ver [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/el-perico.com\/es\/cuarentena_covid_ideas_aprender_omaha\/\" \/>\n<meta property=\"og:site_name\" content=\"el perico\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/elpericoomaha\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-02T07:07:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-03-17T00:53:00+00:00\" \/>\n<meta name=\"author\" content=\"El Perico Staff\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"El Perico Staff\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n\t<meta name=\"twitter:label3\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data3\" content=\"El Perico Staff\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/cuarentena_covid_ideas_aprender_omaha\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/cuarentena_covid_ideas_aprender_omaha\\\/\"},\"author\":{\"name\":\"El Perico Staff\",\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/#\\\/schema\\\/person\\\/1956e5e63b94d4bd0daf30675bdf4a93\"},\"headline\":\"\u00a1Hey! tu mente no est\u00e1 en cuarentena &#8211; ideas para aprender algo m\u00e1s.\",\"datePublished\":\"2020-04-02T07:07:28+00:00\",\"dateModified\":\"2022-03-17T00:53:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/cuarentena_covid_ideas_aprender_omaha\\\/\"},\"wordCount\":549,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/cuarentena_covid_ideas_aprender_omaha\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"articleSection\":[\"Cultura\",\"Reportaje\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/el-perico.com\\\/es\\\/cuarentena_covid_ideas_aprender_omaha\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/cuarentena_covid_ideas_aprender_omaha\\\/\",\"url\":\"https:\\\/\\\/el-perico.com\\\/es\\\/cuarentena_covid_ideas_aprender_omaha\\\/\",\"name\":\"\u00a1Hey! tu mente no est\u00e1 en cuarentena - ideas para aprender algo m\u00e1s. - el perico\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/cuarentena_covid_ideas_aprender_omaha\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/cuarentena_covid_ideas_aprender_omaha\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2020-04-02T07:07:28+00:00\",\"dateModified\":\"2022-03-17T00:53:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/cuarentena_covid_ideas_aprender_omaha\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/el-perico.com\\\/es\\\/cuarentena_covid_ideas_aprender_omaha\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/cuarentena_covid_ideas_aprender_omaha\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/cuarentena_covid_ideas_aprender_omaha\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/el-perico.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00a1Hey! tu mente no est\u00e1 en cuarentena &#8211; ideas para aprender algo m\u00e1s.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/el-perico.com\\\/es\\\/\",\"name\":\"el perico\",\"description\":\"La plataforma original de noticias e informaci\u00f3n para la comunidad hispana de Omaha\",\"publisher\":{\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/el-perico.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/#organization\",\"name\":\"el perico\",\"url\":\"https:\\\/\\\/el-perico.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/el-perico.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/ElPerico-Logo_NPM-1-e1717102187440.png\",\"contentUrl\":\"https:\\\/\\\/el-perico.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/ElPerico-Logo_NPM-1-e1717102187440.png\",\"width\":648,\"height\":216,\"caption\":\"el perico\"},\"image\":{\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/elpericoomaha\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/#\\\/schema\\\/person\\\/1956e5e63b94d4bd0daf30675bdf4a93\",\"name\":\"El Perico Staff\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/701b23c665bfde9fd4d874d31feb4c16bf2ac173b2b0b7224dc39896d4cfc381?s=96&d=mm&r=g80b2efc5844e688a6ffb9340c789e4c4\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/701b23c665bfde9fd4d874d31feb4c16bf2ac173b2b0b7224dc39896d4cfc381?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/701b23c665bfde9fd4d874d31feb4c16bf2ac173b2b0b7224dc39896d4cfc381?s=96&d=mm&r=g\",\"caption\":\"El Perico Staff\"},\"sameAs\":[\"https:\\\/\\\/el-perico.com\"],\"url\":\"https:\\\/\\\/el-perico.com\\\/es\\\/author\\\/af6f1d62_admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00a1Hey! tu mente no est\u00e1 en cuarentena - ideas para aprender algo m\u00e1s. - el perico","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/el-perico.com\/es\/cuarentena_covid_ideas_aprender_omaha\/","og_locale":"es_ES","og_type":"article","og_title":"\u00a1Hey! tu mente no est\u00e1 en cuarentena - ideas para aprender algo m\u00e1s. - el perico","og_description":"Si puedes agregar m\u00e1s ideas, comparte aqu\u00ed. 1. Hazlo. Mientras algunos espacios f\u00edsicos est\u00e1n cerrados, hay otros que son virtuales y siempre est\u00e1n abiertos de forma gratuita. Aparte de los programas regulares puedes explorar m\u00e1s all\u00e1. Si te gustan los videojuegos o quieres ver sobre qu\u00e9 se tratan alguno, entra a Twitch. Tambi\u00e9n puedes ver [&hellip;]","og_url":"https:\/\/el-perico.com\/es\/cuarentena_covid_ideas_aprender_omaha\/","og_site_name":"el perico","article_publisher":"https:\/\/www.facebook.com\/elpericoomaha","article_published_time":"2020-04-02T07:07:28+00:00","article_modified_time":"2022-03-17T00:53:00+00:00","author":"El Perico Staff","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"El Perico Staff","Tiempo de lectura":"3 minutos","Written by":"El Perico Staff"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/el-perico.com\/es\/cuarentena_covid_ideas_aprender_omaha\/#article","isPartOf":{"@id":"https:\/\/el-perico.com\/es\/cuarentena_covid_ideas_aprender_omaha\/"},"author":{"name":"El Perico Staff","@id":"https:\/\/el-perico.com\/es\/#\/schema\/person\/1956e5e63b94d4bd0daf30675bdf4a93"},"headline":"\u00a1Hey! tu mente no est\u00e1 en cuarentena &#8211; ideas para aprender algo m\u00e1s.","datePublished":"2020-04-02T07:07:28+00:00","dateModified":"2022-03-17T00:53:00+00:00","mainEntityOfPage":{"@id":"https:\/\/el-perico.com\/es\/cuarentena_covid_ideas_aprender_omaha\/"},"wordCount":549,"commentCount":0,"publisher":{"@id":"https:\/\/el-perico.com\/es\/#organization"},"image":{"@id":"https:\/\/el-perico.com\/es\/cuarentena_covid_ideas_aprender_omaha\/#primaryimage"},"thumbnailUrl":"","articleSection":["Cultura","Reportaje"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/el-perico.com\/es\/cuarentena_covid_ideas_aprender_omaha\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/el-perico.com\/es\/cuarentena_covid_ideas_aprender_omaha\/","url":"https:\/\/el-perico.com\/es\/cuarentena_covid_ideas_aprender_omaha\/","name":"\u00a1Hey! tu mente no est\u00e1 en cuarentena - ideas para aprender algo m\u00e1s. - el perico","isPartOf":{"@id":"https:\/\/el-perico.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/el-perico.com\/es\/cuarentena_covid_ideas_aprender_omaha\/#primaryimage"},"image":{"@id":"https:\/\/el-perico.com\/es\/cuarentena_covid_ideas_aprender_omaha\/#primaryimage"},"thumbnailUrl":"","datePublished":"2020-04-02T07:07:28+00:00","dateModified":"2022-03-17T00:53:00+00:00","breadcrumb":{"@id":"https:\/\/el-perico.com\/es\/cuarentena_covid_ideas_aprender_omaha\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/el-perico.com\/es\/cuarentena_covid_ideas_aprender_omaha\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/el-perico.com\/es\/cuarentena_covid_ideas_aprender_omaha\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/el-perico.com\/es\/cuarentena_covid_ideas_aprender_omaha\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/el-perico.com\/es\/"},{"@type":"ListItem","position":2,"name":"\u00a1Hey! tu mente no est\u00e1 en cuarentena &#8211; ideas para aprender algo m\u00e1s."}]},{"@type":"WebSite","@id":"https:\/\/el-perico.com\/es\/#website","url":"https:\/\/el-perico.com\/es\/","name":"el perico","description":"La plataforma original de noticias e informaci\u00f3n para la comunidad hispana de Omaha","publisher":{"@id":"https:\/\/el-perico.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/el-perico.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/el-perico.com\/es\/#organization","name":"el perico","url":"https:\/\/el-perico.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/el-perico.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/el-perico.com\/wp-content\/uploads\/2024\/05\/ElPerico-Logo_NPM-1-e1717102187440.png","contentUrl":"https:\/\/el-perico.com\/wp-content\/uploads\/2024\/05\/ElPerico-Logo_NPM-1-e1717102187440.png","width":648,"height":216,"caption":"el perico"},"image":{"@id":"https:\/\/el-perico.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/elpericoomaha"]},{"@type":"Person","@id":"https:\/\/el-perico.com\/es\/#\/schema\/person\/1956e5e63b94d4bd0daf30675bdf4a93","name":"El Perico Staff","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/701b23c665bfde9fd4d874d31feb4c16bf2ac173b2b0b7224dc39896d4cfc381?s=96&d=mm&r=g80b2efc5844e688a6ffb9340c789e4c4","url":"https:\/\/secure.gravatar.com\/avatar\/701b23c665bfde9fd4d874d31feb4c16bf2ac173b2b0b7224dc39896d4cfc381?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/701b23c665bfde9fd4d874d31feb4c16bf2ac173b2b0b7224dc39896d4cfc381?s=96&d=mm&r=g","caption":"El Perico Staff"},"sameAs":["https:\/\/el-perico.com"],"url":"https:\/\/el-perico.com\/es\/author\/af6f1d62_admin\/"}]}},"_links":{"self":[{"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/posts\/3144","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/comments?post=3144"}],"version-history":[{"count":1,"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/posts\/3144\/revisions"}],"predecessor-version":[{"id":6370,"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/posts\/3144\/revisions\/6370"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/el-perico.com\/es\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/media?parent=3144"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/categories?post=3144"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/tags?post=3144"},{"taxonomy":"newspack_spnsrs_tax","embeddable":true,"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/newspack_spnsrs_tax?post=3144"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/coauthors?post=3144"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}