{"id":216,"date":"2016-10-13T20:43:29","date_gmt":"2016-10-13T20:43:29","guid":{"rendered":"http:\/\/el-perico.hdnweb.com\/?p=216"},"modified":"2016-10-13T20:43:29","modified_gmt":"2016-10-13T20:43:29","slug":"espanol-daca-habra-alivio-en-tiempos-de-incertidumbre","status":"publish","type":"post","link":"https:\/\/el-perico.com\/es\/espanol-daca-habra-alivio-en-tiempos-de-incertidumbre\/","title":{"rendered":"DACA \u00bfHabr\u00e1 Alivio en Tiempos de Incertidumbre?"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-213 aligncenter\" src=\"http:\/\/el-perico.hdnweb.com\/wp-content\/uploads\/sites\/3\/2016\/10\/Statue.of_.Liberty.original.9862-300x169.jpg\" alt=\"statue-of-liberty-original-9862\" width=\"467\" height=\"263\" \/><br \/>\n&nbsp;<br \/>\nLa renovaci\u00f3n de DACA de Leticia Urrutia se acerca en octubre, un mes antes de las elecciones presidenciales.<br \/>\n\u00abMe dec\u00eda, &#8216;\u00bfQu\u00e9 voy a hacer?'\u00bb dijo la nativa de M\u00e9xico de 23 a\u00f1os de edad en una mesa redonda de medios en San Francisco.<br \/>\nUrrutia tiene Acci\u00f3n Diferida para los Llegados en la Infancia (DACA por sus siglas en ingl\u00e9s), una protecci\u00f3n contra la deportaci\u00f3n durante dos a\u00f1os que es renovable y es para inmigrantes no documentados que vinieron a los EEUU de ni\u00f1os.<br \/>\nPromulgado en 2012, el programa DACA original sigue vigente y no se ve afectado por la decisi\u00f3n dividida 4 a 4 por la Corte Suprema del mes pasado.<br \/>\nPero la cuesti\u00f3n de si se ha de renovar el per\u00edodo de DACA antes de las elecciones est\u00e1 relacionada con una mayor preocupaci\u00f3n &#8212; la de no saber qui\u00e9n ser\u00e1 el pr\u00f3ximo presidente de los EEUU y si el nuevo presidente elegir\u00eda terminar el programa. (Si el nuevo presidente no hace nada, el programa seguir\u00e1 en efecto.)<br \/>\nAlgunos inmigrantes estar\u00e1n preocupados por exponerse a mayor riesgo si se presentan.<br \/>\n\u00abNo hay pruebas de esto\u00bb, dijo Sally Kinoshita, directora adjunta de Immigrant Legal Resource Center, y agreg\u00f3 que no ser\u00eda factible ni pol\u00edtica ni econ\u00f3micamente dado el n\u00famero de personas que ya la han solicitado. \u00abHan habido numerosos programas parecidos, y no hay pruebas de que el gobierno persiga a uno.\u00bb<br \/>\nA\u00fan as\u00ed, la cuesti\u00f3n agobia a muchos inmigrantes en medio de una temporada electoral que ha visto un aumento en la ret\u00f3rica anti-inmigrante.<br \/>\n\u00abCuando lo dicen los oficiales p\u00fablicos, los dem\u00e1s piensan que est\u00e1 permitido unirse a esta expresi\u00f3n de odio,\u00bb dijo Amanda Alvarado Ford, abogada de inmigraci\u00f3n en La Raza Centro Legal.<br \/>\n\u00abTodos los que se preocupan por reformar la inmigraci\u00f3n est\u00e1 mirando de cerca nuestras elecciones en noviembre\u00bb, dijo Kinoshita.<br \/>\nEl pr\u00f3ximo presidente nombrar\u00e1 al noveno juez de la Corte Suprema de los EUA, que se ha estancado sobre inmigraci\u00f3n y varios otros casos desde la muerte del juez Antonin Scalia este a\u00f1o.<br \/>\nMientras tanto, los defensores de derechos de los inmigrantes est\u00e1n animando a sus comunidades a protegerse solicitando DACA y buscando proveedores cualificados de servicios legales para ver si tambi\u00e9n cumplen los requisitos de otros programas.<br \/>\nPara Urrutia, recibir DACA le ha cambiado la vida.<br \/>\nGracias a DACA, tiene protecci\u00f3n temporal contra la deportaci\u00f3n y acceso a un permiso de trabajo y un n\u00famero de seguro social. Ha podido conseguir un trabajo y ahora est\u00e1 estudiando Ciencias Pol\u00edticas.<br \/>\nUrrutia es una de m\u00e1s de 800,000 personas que han solicitado DACA desde que fue promulgada por el Presidente Obama en 2012.<br \/>\nMuchos m\u00e1s cumplen los requisitos para DACA pero no la han solicitado. El Migration Policy Institute calcula que un total de 1.7 millones de personas en el pa\u00eds podr\u00edan beneficiarse de DACA incluyendo unas 400,000 personas que ser\u00edan elegibles si se matricularan para estudiar y as\u00ed cumplir los requisitos de educaci\u00f3n.<br \/>\nPero una vista de cerca a los n\u00fameros muestran una varianza dram\u00e1tica por nacionalidad. Seg\u00fan el Migration Policy Institute, m\u00e1s del 90 por ciento de los mexicanos elegibles y m\u00e1s del 66 por ciento de los centroamericanos elegibles han solicitado DACA.<br \/>\nEl \u00edndice de solicitudes es considerablemente inferior para las comunidades asi\u00e1tico-americanas. El 24 por ciento de los filipinos elegibles, el 21 por ciento de los indios elegibles y el 17 por ciento de los surcoreanos elegibles han solicitado DACA. El porcentaje de chino americanos que han solicitado DACA es tan bajo que no lleg\u00f3 a la lista de los primeros 20 pa\u00edses de solicitantes de DACA.<br \/>\nEn una reuni\u00f3n con periodistas, los defensores de los derechos de inmigrantes animaron a los que cumplen los requisitos a que soliciten DACA, sobre todo en las comunidades asi\u00e1tico-americanas.<br \/>\n\u00abIndudablemente vemos un aumento en llamadas telef\u00f3nicas cuando vemos reportajes en los medios,\u00bb dijo Annette Wong, directora de programas para Chinese for Affirmative Action.<br \/>\nPara animar a m\u00e1s personas a tener acceso a los beneficios de DACA, la Oficina de Participaci\u00f3n C\u00edvica y Asuntos de Inmigrantes de San Francisco ha lanzado un nuevo programa de ayudas econ\u00f3micas mediante sus socios sin fines de lucro. El programa cubre una parte o el total de la tasa de $465 y est\u00e1 disponible para los inmigrantes que soliciten DACA u otros servicios relacionados con la inmigraci\u00f3n.<br \/>\nLos l\u00edderes de derechos de los inmigrantes tambi\u00e9n est\u00e1n trabajando en disipar algunos mitos comunes acerca del programa.<br \/>\n\u00abNo, no tienes que tener buenas calificaciones,\u00bb para solicitar DACA, dijo Amanda Alvarado Ford de La Raza Centro Legal. Mientras que algunos piensan que DACA solo es para universitarios o los estudiantes con las mejores calificaciones, la verdad es que recibir un GED (Certificado de Equivalencia de Estudios Secundarios) te puede hacer elegible.<br \/>\nAl recordar c\u00f3mo DACA ha cambiado su vida, Urrutia dice que piensa solicitar la renovaci\u00f3n en octubre.<br \/>\nDice que quiere renovar DACA porque est\u00e1 \u00abplaneando por adelantado.\u00bb Piensa hacer estudios graduados de psicolog\u00eda y quiere poder trabajar en su campo &#8211; algo que es dif\u00edcil hacer sin un permiso de trabajo.<br \/>\n\u00abVoy a volver a solicitarla\u00bb, dijo, \u00abporque todas las oportunidades que DACA me ha dado han sido los mejores momentos de mi vida.\u00bb<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; La renovaci\u00f3n de DACA de Leticia Urrutia se acerca en octubre, un mes antes de las elecciones presidenciales. \u00abMe dec\u00eda, &#8216;\u00bfQu\u00e9 voy a hacer?&#8217;\u00bb dijo la nativa de M\u00e9xico de 23 a\u00f1os de edad en una mesa redonda de medios en San Francisco. Urrutia tiene Acci\u00f3n Diferida para los Llegados en la Infancia (DACA [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":213,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"newspack_ads_suppress_ads":false,"_newspack_byline_active":false,"_newspack_byline":"","newspack_hide_updated_date":false,"newspack_show_updated_date":false,"newspack_content_restriction_is_exempt":false,"newspack_featured_image_position":"","newspack_post_subtitle":"","newspack_article_summary_title":"Overview:","newspack_article_summary":"","footnotes":""},"categories":[1],"tags":[],"newspack_spnsrs_tax":[],"coauthors":[],"class_list":["post-216","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>DACA \u00bfHabr\u00e1 Alivio en Tiempos de Incertidumbre? - el perico<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/el-perico.com\/es\/espanol-daca-habra-alivio-en-tiempos-de-incertidumbre\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DACA \u00bfHabr\u00e1 Alivio en Tiempos de Incertidumbre? - el perico\" \/>\n<meta property=\"og:description\" content=\"&nbsp; La renovaci\u00f3n de DACA de Leticia Urrutia se acerca en octubre, un mes antes de las elecciones presidenciales. \u00abMe dec\u00eda, &#8216;\u00bfQu\u00e9 voy a hacer?&#039;\u00bb dijo la nativa de M\u00e9xico de 23 a\u00f1os de edad en una mesa redonda de medios en San Francisco. Urrutia tiene Acci\u00f3n Diferida para los Llegados en la Infancia (DACA [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/el-perico.com\/es\/espanol-daca-habra-alivio-en-tiempos-de-incertidumbre\/\" \/>\n<meta property=\"og:site_name\" content=\"el perico\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/elpericoomaha\" \/>\n<meta property=\"article:published_time\" content=\"2016-10-13T20:43:29+00:00\" \/>\n<meta name=\"author\" content=\"El Perico Staff\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"El Perico Staff\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n\t<meta name=\"twitter:label3\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data3\" content=\"El Perico Staff\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/espanol-daca-habra-alivio-en-tiempos-de-incertidumbre\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/espanol-daca-habra-alivio-en-tiempos-de-incertidumbre\\\/\"},\"author\":{\"name\":\"El Perico Staff\",\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/#\\\/schema\\\/person\\\/1956e5e63b94d4bd0daf30675bdf4a93\"},\"headline\":\"DACA \u00bfHabr\u00e1 Alivio en Tiempos de Incertidumbre?\",\"datePublished\":\"2016-10-13T20:43:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/espanol-daca-habra-alivio-en-tiempos-de-incertidumbre\\\/\"},\"wordCount\":920,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/espanol-daca-habra-alivio-en-tiempos-de-incertidumbre\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"articleSection\":[\"Uncategorized\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/el-perico.com\\\/es\\\/espanol-daca-habra-alivio-en-tiempos-de-incertidumbre\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/espanol-daca-habra-alivio-en-tiempos-de-incertidumbre\\\/\",\"url\":\"https:\\\/\\\/el-perico.com\\\/es\\\/espanol-daca-habra-alivio-en-tiempos-de-incertidumbre\\\/\",\"name\":\"DACA \u00bfHabr\u00e1 Alivio en Tiempos de Incertidumbre? - el perico\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/espanol-daca-habra-alivio-en-tiempos-de-incertidumbre\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/espanol-daca-habra-alivio-en-tiempos-de-incertidumbre\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2016-10-13T20:43:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/espanol-daca-habra-alivio-en-tiempos-de-incertidumbre\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/el-perico.com\\\/es\\\/espanol-daca-habra-alivio-en-tiempos-de-incertidumbre\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/espanol-daca-habra-alivio-en-tiempos-de-incertidumbre\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/espanol-daca-habra-alivio-en-tiempos-de-incertidumbre\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/el-perico.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"DACA \u00bfHabr\u00e1 Alivio en Tiempos de Incertidumbre?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/el-perico.com\\\/es\\\/\",\"name\":\"el perico\",\"description\":\"La plataforma original de noticias e informaci\u00f3n para la comunidad hispana de Omaha\",\"publisher\":{\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/el-perico.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/#organization\",\"name\":\"el perico\",\"url\":\"https:\\\/\\\/el-perico.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/el-perico.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/ElPerico-Logo_NPM-1-e1717102187440.png\",\"contentUrl\":\"https:\\\/\\\/el-perico.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/ElPerico-Logo_NPM-1-e1717102187440.png\",\"width\":648,\"height\":216,\"caption\":\"el perico\"},\"image\":{\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/elpericoomaha\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/#\\\/schema\\\/person\\\/1956e5e63b94d4bd0daf30675bdf4a93\",\"name\":\"El Perico Staff\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/701b23c665bfde9fd4d874d31feb4c16bf2ac173b2b0b7224dc39896d4cfc381?s=96&d=mm&r=g80b2efc5844e688a6ffb9340c789e4c4\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/701b23c665bfde9fd4d874d31feb4c16bf2ac173b2b0b7224dc39896d4cfc381?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/701b23c665bfde9fd4d874d31feb4c16bf2ac173b2b0b7224dc39896d4cfc381?s=96&d=mm&r=g\",\"caption\":\"El Perico Staff\"},\"sameAs\":[\"https:\\\/\\\/el-perico.com\"],\"url\":\"https:\\\/\\\/el-perico.com\\\/es\\\/author\\\/af6f1d62_admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"DACA \u00bfHabr\u00e1 Alivio en Tiempos de Incertidumbre? - el perico","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/el-perico.com\/es\/espanol-daca-habra-alivio-en-tiempos-de-incertidumbre\/","og_locale":"es_ES","og_type":"article","og_title":"DACA \u00bfHabr\u00e1 Alivio en Tiempos de Incertidumbre? - el perico","og_description":"&nbsp; La renovaci\u00f3n de DACA de Leticia Urrutia se acerca en octubre, un mes antes de las elecciones presidenciales. \u00abMe dec\u00eda, &#8216;\u00bfQu\u00e9 voy a hacer?'\u00bb dijo la nativa de M\u00e9xico de 23 a\u00f1os de edad en una mesa redonda de medios en San Francisco. Urrutia tiene Acci\u00f3n Diferida para los Llegados en la Infancia (DACA [&hellip;]","og_url":"https:\/\/el-perico.com\/es\/espanol-daca-habra-alivio-en-tiempos-de-incertidumbre\/","og_site_name":"el perico","article_publisher":"https:\/\/www.facebook.com\/elpericoomaha","article_published_time":"2016-10-13T20:43:29+00:00","author":"El Perico Staff","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"El Perico Staff","Tiempo de lectura":"5 minutos","Written by":"El Perico Staff"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/el-perico.com\/es\/espanol-daca-habra-alivio-en-tiempos-de-incertidumbre\/#article","isPartOf":{"@id":"https:\/\/el-perico.com\/es\/espanol-daca-habra-alivio-en-tiempos-de-incertidumbre\/"},"author":{"name":"El Perico Staff","@id":"https:\/\/el-perico.com\/es\/#\/schema\/person\/1956e5e63b94d4bd0daf30675bdf4a93"},"headline":"DACA \u00bfHabr\u00e1 Alivio en Tiempos de Incertidumbre?","datePublished":"2016-10-13T20:43:29+00:00","mainEntityOfPage":{"@id":"https:\/\/el-perico.com\/es\/espanol-daca-habra-alivio-en-tiempos-de-incertidumbre\/"},"wordCount":920,"commentCount":0,"publisher":{"@id":"https:\/\/el-perico.com\/es\/#organization"},"image":{"@id":"https:\/\/el-perico.com\/es\/espanol-daca-habra-alivio-en-tiempos-de-incertidumbre\/#primaryimage"},"thumbnailUrl":"","articleSection":["Uncategorized"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/el-perico.com\/es\/espanol-daca-habra-alivio-en-tiempos-de-incertidumbre\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/el-perico.com\/es\/espanol-daca-habra-alivio-en-tiempos-de-incertidumbre\/","url":"https:\/\/el-perico.com\/es\/espanol-daca-habra-alivio-en-tiempos-de-incertidumbre\/","name":"DACA \u00bfHabr\u00e1 Alivio en Tiempos de Incertidumbre? - el perico","isPartOf":{"@id":"https:\/\/el-perico.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/el-perico.com\/es\/espanol-daca-habra-alivio-en-tiempos-de-incertidumbre\/#primaryimage"},"image":{"@id":"https:\/\/el-perico.com\/es\/espanol-daca-habra-alivio-en-tiempos-de-incertidumbre\/#primaryimage"},"thumbnailUrl":"","datePublished":"2016-10-13T20:43:29+00:00","breadcrumb":{"@id":"https:\/\/el-perico.com\/es\/espanol-daca-habra-alivio-en-tiempos-de-incertidumbre\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/el-perico.com\/es\/espanol-daca-habra-alivio-en-tiempos-de-incertidumbre\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/el-perico.com\/es\/espanol-daca-habra-alivio-en-tiempos-de-incertidumbre\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/el-perico.com\/es\/espanol-daca-habra-alivio-en-tiempos-de-incertidumbre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/el-perico.com\/es\/"},{"@type":"ListItem","position":2,"name":"DACA \u00bfHabr\u00e1 Alivio en Tiempos de Incertidumbre?"}]},{"@type":"WebSite","@id":"https:\/\/el-perico.com\/es\/#website","url":"https:\/\/el-perico.com\/es\/","name":"el perico","description":"La plataforma original de noticias e informaci\u00f3n para la comunidad hispana de Omaha","publisher":{"@id":"https:\/\/el-perico.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/el-perico.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/el-perico.com\/es\/#organization","name":"el perico","url":"https:\/\/el-perico.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/el-perico.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/el-perico.com\/wp-content\/uploads\/2024\/05\/ElPerico-Logo_NPM-1-e1717102187440.png","contentUrl":"https:\/\/el-perico.com\/wp-content\/uploads\/2024\/05\/ElPerico-Logo_NPM-1-e1717102187440.png","width":648,"height":216,"caption":"el perico"},"image":{"@id":"https:\/\/el-perico.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/elpericoomaha"]},{"@type":"Person","@id":"https:\/\/el-perico.com\/es\/#\/schema\/person\/1956e5e63b94d4bd0daf30675bdf4a93","name":"El Perico Staff","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/701b23c665bfde9fd4d874d31feb4c16bf2ac173b2b0b7224dc39896d4cfc381?s=96&d=mm&r=g80b2efc5844e688a6ffb9340c789e4c4","url":"https:\/\/secure.gravatar.com\/avatar\/701b23c665bfde9fd4d874d31feb4c16bf2ac173b2b0b7224dc39896d4cfc381?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/701b23c665bfde9fd4d874d31feb4c16bf2ac173b2b0b7224dc39896d4cfc381?s=96&d=mm&r=g","caption":"El Perico Staff"},"sameAs":["https:\/\/el-perico.com"],"url":"https:\/\/el-perico.com\/es\/author\/af6f1d62_admin\/"}]}},"_links":{"self":[{"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/posts\/216","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/comments?post=216"}],"version-history":[{"count":0,"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/posts\/216\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/el-perico.com\/es\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/media?parent=216"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/categories?post=216"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/tags?post=216"},{"taxonomy":"newspack_spnsrs_tax","embeddable":true,"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/newspack_spnsrs_tax?post=216"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/coauthors?post=216"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}