{"id":1950,"date":"2019-03-14T14:17:10","date_gmt":"2019-03-14T14:17:10","guid":{"rendered":"https:\/\/el-perico.kaageg0-liquidwebsites.com\/?p=1950"},"modified":"2019-03-14T14:17:10","modified_gmt":"2019-03-14T14:17:10","slug":"14m-podrian-perder-cobertura-bajo-la-propuesta-republicana-de-salud","status":"publish","type":"post","link":"https:\/\/el-perico.com\/es\/14m-podrian-perder-cobertura-bajo-la-propuesta-republicana-de-salud\/","title":{"rendered":"14M PODRI\u0301AN PERDER COBERTURA BAJO LA PROPUESTA REPUBLICANA DE SALUD"},"content":{"rendered":"<p>Un ana\u0301lisis no partidario publicado el 13 de marzo proyecto\u0301 que 14 millones de personas podri\u0301an perder cobertura el an\u0303o que entra bajo la propuesta de la Ca\u0301mara para desmantelar el programa de cuidado de la salud del ex presidente Obama.<br \/>\nLas estimaciones de la Oficina de Presupuesto del Congreso del pasado lunes sen\u0303alaron que el nu\u0301mero de los que no estari\u0301an cubiertos podri\u0301a crecer a 24 millones para el 2026.<br \/>\nLas proyecciones dieron cabida a los oponentes quienes previnieron que las medidas podri\u0301an hacer a un lado de los planes de seguro me\u0301dico a millones de electores. La mayori\u0301a de las cri\u0301ticas vinieron de pate de los demo\u0301cratas y de republicanos de los estados que se han beneficiado con la ley de Obama y de muchas ramas de la industria del cuidado de la salud.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un ana\u0301lisis no partidario publicado el 13 de marzo proyecto\u0301 que 14 millones de personas podri\u0301an perder cobertura el an\u0303o que entra bajo la propuesta de la Ca\u0301mara para desmantelar el programa de cuidado de la salud del ex presidente Obama. Las estimaciones de la Oficina de Presupuesto del Congreso del pasado lunes sen\u0303alaron que [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"newspack_ads_suppress_ads":false,"_newspack_byline_active":false,"_newspack_byline":"","newspack_hide_updated_date":false,"newspack_show_updated_date":false,"newspack_content_restriction_is_exempt":false,"newspack_featured_image_position":"","newspack_post_subtitle":"","newspack_article_summary_title":"Overview:","newspack_article_summary":"","footnotes":""},"categories":[45],"tags":[],"newspack_spnsrs_tax":[],"coauthors":[],"class_list":["post-1950","post","type-post","status-publish","format-standard","hentry","category-salud","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>14M PODRI\u0301AN PERDER COBERTURA BAJO LA PROPUESTA REPUBLICANA DE SALUD - el perico<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/el-perico.com\/es\/14m-podrian-perder-cobertura-bajo-la-propuesta-republicana-de-salud\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"14M PODRI\u0301AN PERDER COBERTURA BAJO LA PROPUESTA REPUBLICANA DE SALUD - el perico\" \/>\n<meta property=\"og:description\" content=\"Un ana\u0301lisis no partidario publicado el 13 de marzo proyecto\u0301 que 14 millones de personas podri\u0301an perder cobertura el an\u0303o que entra bajo la propuesta de la Ca\u0301mara para desmantelar el programa de cuidado de la salud del ex presidente Obama. Las estimaciones de la Oficina de Presupuesto del Congreso del pasado lunes sen\u0303alaron que [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/el-perico.com\/es\/14m-podrian-perder-cobertura-bajo-la-propuesta-republicana-de-salud\/\" \/>\n<meta property=\"og:site_name\" content=\"el perico\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/elpericoomaha\" \/>\n<meta property=\"article:published_time\" content=\"2019-03-14T14:17:10+00:00\" \/>\n<meta name=\"author\" content=\"El Perico Staff\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"El Perico Staff\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n\t<meta name=\"twitter:label3\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data3\" content=\"El Perico Staff\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/14m-podrian-perder-cobertura-bajo-la-propuesta-republicana-de-salud\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/14m-podrian-perder-cobertura-bajo-la-propuesta-republicana-de-salud\\\/\"},\"author\":{\"name\":\"El Perico Staff\",\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/#\\\/schema\\\/person\\\/1956e5e63b94d4bd0daf30675bdf4a93\"},\"headline\":\"14M PODRI\u0301AN PERDER COBERTURA BAJO LA PROPUESTA REPUBLICANA DE SALUD\",\"datePublished\":\"2019-03-14T14:17:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/14m-podrian-perder-cobertura-bajo-la-propuesta-republicana-de-salud\\\/\"},\"wordCount\":156,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/#organization\"},\"articleSection\":[\"Salud\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/el-perico.com\\\/es\\\/14m-podrian-perder-cobertura-bajo-la-propuesta-republicana-de-salud\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/14m-podrian-perder-cobertura-bajo-la-propuesta-republicana-de-salud\\\/\",\"url\":\"https:\\\/\\\/el-perico.com\\\/es\\\/14m-podrian-perder-cobertura-bajo-la-propuesta-republicana-de-salud\\\/\",\"name\":\"14M PODRI\u0301AN PERDER COBERTURA BAJO LA PROPUESTA REPUBLICANA DE SALUD - el perico\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/#website\"},\"datePublished\":\"2019-03-14T14:17:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/14m-podrian-perder-cobertura-bajo-la-propuesta-republicana-de-salud\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/el-perico.com\\\/es\\\/14m-podrian-perder-cobertura-bajo-la-propuesta-republicana-de-salud\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/14m-podrian-perder-cobertura-bajo-la-propuesta-republicana-de-salud\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/el-perico.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"14M PODRI\u0301AN PERDER COBERTURA BAJO LA PROPUESTA REPUBLICANA DE SALUD\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/el-perico.com\\\/es\\\/\",\"name\":\"el perico\",\"description\":\"La plataforma original de noticias e informaci\u00f3n para la comunidad hispana de Omaha\",\"publisher\":{\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/el-perico.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/#organization\",\"name\":\"el perico\",\"url\":\"https:\\\/\\\/el-perico.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/el-perico.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/ElPerico-Logo_NPM-1-e1717102187440.png\",\"contentUrl\":\"https:\\\/\\\/el-perico.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/ElPerico-Logo_NPM-1-e1717102187440.png\",\"width\":648,\"height\":216,\"caption\":\"el perico\"},\"image\":{\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/elpericoomaha\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/el-perico.com\\\/es\\\/#\\\/schema\\\/person\\\/1956e5e63b94d4bd0daf30675bdf4a93\",\"name\":\"El Perico Staff\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/701b23c665bfde9fd4d874d31feb4c16bf2ac173b2b0b7224dc39896d4cfc381?s=96&d=mm&r=g80b2efc5844e688a6ffb9340c789e4c4\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/701b23c665bfde9fd4d874d31feb4c16bf2ac173b2b0b7224dc39896d4cfc381?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/701b23c665bfde9fd4d874d31feb4c16bf2ac173b2b0b7224dc39896d4cfc381?s=96&d=mm&r=g\",\"caption\":\"El Perico Staff\"},\"sameAs\":[\"https:\\\/\\\/el-perico.com\"],\"url\":\"https:\\\/\\\/el-perico.com\\\/es\\\/author\\\/af6f1d62_admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"14M PODRI\u0301AN PERDER COBERTURA BAJO LA PROPUESTA REPUBLICANA DE SALUD - el perico","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/el-perico.com\/es\/14m-podrian-perder-cobertura-bajo-la-propuesta-republicana-de-salud\/","og_locale":"es_ES","og_type":"article","og_title":"14M PODRI\u0301AN PERDER COBERTURA BAJO LA PROPUESTA REPUBLICANA DE SALUD - el perico","og_description":"Un ana\u0301lisis no partidario publicado el 13 de marzo proyecto\u0301 que 14 millones de personas podri\u0301an perder cobertura el an\u0303o que entra bajo la propuesta de la Ca\u0301mara para desmantelar el programa de cuidado de la salud del ex presidente Obama. Las estimaciones de la Oficina de Presupuesto del Congreso del pasado lunes sen\u0303alaron que [&hellip;]","og_url":"https:\/\/el-perico.com\/es\/14m-podrian-perder-cobertura-bajo-la-propuesta-republicana-de-salud\/","og_site_name":"el perico","article_publisher":"https:\/\/www.facebook.com\/elpericoomaha","article_published_time":"2019-03-14T14:17:10+00:00","author":"El Perico Staff","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"El Perico Staff","Tiempo de lectura":"1 minuto","Written by":"El Perico Staff"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/el-perico.com\/es\/14m-podrian-perder-cobertura-bajo-la-propuesta-republicana-de-salud\/#article","isPartOf":{"@id":"https:\/\/el-perico.com\/es\/14m-podrian-perder-cobertura-bajo-la-propuesta-republicana-de-salud\/"},"author":{"name":"El Perico Staff","@id":"https:\/\/el-perico.com\/es\/#\/schema\/person\/1956e5e63b94d4bd0daf30675bdf4a93"},"headline":"14M PODRI\u0301AN PERDER COBERTURA BAJO LA PROPUESTA REPUBLICANA DE SALUD","datePublished":"2019-03-14T14:17:10+00:00","mainEntityOfPage":{"@id":"https:\/\/el-perico.com\/es\/14m-podrian-perder-cobertura-bajo-la-propuesta-republicana-de-salud\/"},"wordCount":156,"commentCount":0,"publisher":{"@id":"https:\/\/el-perico.com\/es\/#organization"},"articleSection":["Salud"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/el-perico.com\/es\/14m-podrian-perder-cobertura-bajo-la-propuesta-republicana-de-salud\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/el-perico.com\/es\/14m-podrian-perder-cobertura-bajo-la-propuesta-republicana-de-salud\/","url":"https:\/\/el-perico.com\/es\/14m-podrian-perder-cobertura-bajo-la-propuesta-republicana-de-salud\/","name":"14M PODRI\u0301AN PERDER COBERTURA BAJO LA PROPUESTA REPUBLICANA DE SALUD - el perico","isPartOf":{"@id":"https:\/\/el-perico.com\/es\/#website"},"datePublished":"2019-03-14T14:17:10+00:00","breadcrumb":{"@id":"https:\/\/el-perico.com\/es\/14m-podrian-perder-cobertura-bajo-la-propuesta-republicana-de-salud\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/el-perico.com\/es\/14m-podrian-perder-cobertura-bajo-la-propuesta-republicana-de-salud\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/el-perico.com\/es\/14m-podrian-perder-cobertura-bajo-la-propuesta-republicana-de-salud\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/el-perico.com\/es\/"},{"@type":"ListItem","position":2,"name":"14M PODRI\u0301AN PERDER COBERTURA BAJO LA PROPUESTA REPUBLICANA DE SALUD"}]},{"@type":"WebSite","@id":"https:\/\/el-perico.com\/es\/#website","url":"https:\/\/el-perico.com\/es\/","name":"el perico","description":"La plataforma original de noticias e informaci\u00f3n para la comunidad hispana de Omaha","publisher":{"@id":"https:\/\/el-perico.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/el-perico.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/el-perico.com\/es\/#organization","name":"el perico","url":"https:\/\/el-perico.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/el-perico.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/el-perico.com\/wp-content\/uploads\/2024\/05\/ElPerico-Logo_NPM-1-e1717102187440.png","contentUrl":"https:\/\/el-perico.com\/wp-content\/uploads\/2024\/05\/ElPerico-Logo_NPM-1-e1717102187440.png","width":648,"height":216,"caption":"el perico"},"image":{"@id":"https:\/\/el-perico.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/elpericoomaha"]},{"@type":"Person","@id":"https:\/\/el-perico.com\/es\/#\/schema\/person\/1956e5e63b94d4bd0daf30675bdf4a93","name":"El Perico Staff","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/701b23c665bfde9fd4d874d31feb4c16bf2ac173b2b0b7224dc39896d4cfc381?s=96&d=mm&r=g80b2efc5844e688a6ffb9340c789e4c4","url":"https:\/\/secure.gravatar.com\/avatar\/701b23c665bfde9fd4d874d31feb4c16bf2ac173b2b0b7224dc39896d4cfc381?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/701b23c665bfde9fd4d874d31feb4c16bf2ac173b2b0b7224dc39896d4cfc381?s=96&d=mm&r=g","caption":"El Perico Staff"},"sameAs":["https:\/\/el-perico.com"],"url":"https:\/\/el-perico.com\/es\/author\/af6f1d62_admin\/"}]}},"_links":{"self":[{"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/posts\/1950","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/comments?post=1950"}],"version-history":[{"count":0,"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/posts\/1950\/revisions"}],"wp:attachment":[{"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/media?parent=1950"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/categories?post=1950"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/tags?post=1950"},{"taxonomy":"newspack_spnsrs_tax","embeddable":true,"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/newspack_spnsrs_tax?post=1950"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/el-perico.com\/es\/wp-json\/wp\/v2\/coauthors?post=1950"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}